{"id":102765,"date":"2024-11-30T21:23:14","date_gmt":"2024-11-30T20:23:14","guid":{"rendered":"https:\/\/news.acropolis.org\/?p=102765"},"modified":"2024-11-30T21:23:14","modified_gmt":"2024-11-30T20:23:14","slug":"una-calle-para-todos-dia-del-aparcamiento-leipzig-alemania","status":"publish","type":"post","link":"https:\/\/news.acropolis.org\/es\/2024\/una-calle-para-todos-dia-del-aparcamiento-leipzig-alemania\/","title":{"rendered":"Una calle para todos. D\u00eda del aparcamiento (Leipzig, Alemania)"},"content":{"rendered":"<p><a href=\"https:\/\/news.acropolis.org\/2024\/a-street-for-everyone-parking-day-leipzig-germany\/unbenannt-jpg_compressed\/\" rel=\"attachment wp-att-102737\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-102737\" src=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/11\/Unbenannt.JPG_compressed.jpeg\" alt=\"Parking Day Leipzig\" width=\"500\" height=\"492\" srcset=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/11\/Unbenannt.JPG_compressed.jpeg 868w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/11\/Unbenannt.JPG_compressed-300x295.jpeg 300w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/11\/Unbenannt.JPG_compressed-768x756.jpeg 768w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/11\/Unbenannt.JPG_compressed-730x718.jpeg 730w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/11\/Unbenannt.JPG_compressed-435x428.jpeg 435w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/11\/Unbenannt.JPG_compressed-24x24.jpeg 24w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/11\/Unbenannt.JPG_compressed-48x48.jpeg 48w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a>Los coches aparcados en las calles forman parte de nuestro paisaje urbano habitual, pero para una ciudad sana del futuro necesitamos espacio para los encuentros, para la naturaleza y lugares para jugar. Como parte de una iniciativa vecinal, los miembros de la Escuela NA de Leipzig ocuparon cinco plazas de aparcamiento para probar ideas alternativas en este espacio vital; con un tablero de ajedrez, un sof\u00e1 y un \u00e1rbol de la virtud, para utilizarlo como un lugar de encuentro y de conversaciones filos\u00f3ficas, para proponer soluciones para esta \u00e9poca de cambio y para pensar juntos c\u00f3mo se puede lograr un equilibrio justo entre todos los usuarios de la v\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los coches aparcados en las calles forman parte de nuestro paisaje urbano habitual, pero para una ciudad sana del futuro necesitamos espacio para los encuentros, para la naturaleza y lugares [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":102739,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[233,170,5013,187],"class_list":["post-102765","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actividades_culturales","tag-conservacion-medioambiental","tag-filosofia-2","tag-leipzig-es","tag-nueva-acropolis","clearfix"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Una calle para todos. D\u00eda del aparcamiento (Leipzig, Alemania) - Noticias de Nueva Acr\u00f3polis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/news.acropolis.org\/es\/2024\/una-calle-para-todos-dia-del-aparcamiento-leipzig-alemania\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Una calle para todos. D\u00eda del aparcamiento (Leipzig, Alemania) - Noticias de Nueva Acr\u00f3polis\" \/>\n<meta name=\"twitter:description\" content=\"Los coches aparcados en las calles forman parte de nuestro paisaje urbano habitual, pero para una ciudad sana del futuro necesitamos espacio para los encuentros, para la naturaleza y lugares [&hellip;]\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/11\/Unbenannt.JPG_compressed.jpeg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alemania\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/una-calle-para-todos-dia-del-aparcamiento-leipzig-alemania\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/una-calle-para-todos-dia-del-aparcamiento-leipzig-alemania\\\/\"},\"author\":{\"name\":\"Germany\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/4cb7cee6446382e733e5cc1ad36d9e58\"},\"headline\":\"Una calle para todos. D\u00eda del aparcamiento (Leipzig, Alemania)\",\"datePublished\":\"2024-11-30T20:23:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/una-calle-para-todos-dia-del-aparcamiento-leipzig-alemania\\\/\"},\"wordCount\":122,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/una-calle-para-todos-dia-del-aparcamiento-leipzig-alemania\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Unbenannt.JPG_compressed.jpeg\",\"keywords\":[\"Conservaci\u00f3n medioambiental\",\"filosof\u00eda\",\"Leipzig\",\"nueva acr\u00f3polis\"],\"articleSection\":[\"Actividades Culturales\"],\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/una-calle-para-todos-dia-del-aparcamiento-leipzig-alemania\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/una-calle-para-todos-dia-del-aparcamiento-leipzig-alemania\\\/\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/una-calle-para-todos-dia-del-aparcamiento-leipzig-alemania\\\/\",\"name\":\"Una calle para todos. D\u00eda del aparcamiento (Leipzig, Alemania) - Noticias de Nueva Acr\u00f3polis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/una-calle-para-todos-dia-del-aparcamiento-leipzig-alemania\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/una-calle-para-todos-dia-del-aparcamiento-leipzig-alemania\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Unbenannt.JPG_compressed.jpeg\",\"datePublished\":\"2024-11-30T20:23:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/4cb7cee6446382e733e5cc1ad36d9e58\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/una-calle-para-todos-dia-del-aparcamiento-leipzig-alemania\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/una-calle-para-todos-dia-del-aparcamiento-leipzig-alemania\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/una-calle-para-todos-dia-del-aparcamiento-leipzig-alemania\\\/#primaryimage\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Unbenannt.JPG_compressed.jpeg\",\"contentUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Unbenannt.JPG_compressed.jpeg\",\"width\":868,\"height\":854,\"caption\":\"Parking Day Leipzig\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/una-calle-para-todos-dia-del-aparcamiento-leipzig-alemania\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una calle para todos. D\u00eda del aparcamiento (Leipzig, Alemania)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/\",\"name\":\"Noticias de Nueva Acr\u00f3polis\",\"description\":\"Actividades de la Organizaci\u00f3n Internacional Nueva Acr\u00f3polis\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/4cb7cee6446382e733e5cc1ad36d9e58\",\"name\":\"Germany\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/DEU.png\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/DEU.png\",\"contentUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/DEU.png\",\"caption\":\"Germany\"},\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/author\\\/ionad\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una calle para todos. D\u00eda del aparcamiento (Leipzig, Alemania) - Noticias de Nueva Acr\u00f3polis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/news.acropolis.org\/es\/2024\/una-calle-para-todos-dia-del-aparcamiento-leipzig-alemania\/","twitter_card":"summary_large_image","twitter_title":"Una calle para todos. D\u00eda del aparcamiento (Leipzig, Alemania) - Noticias de Nueva Acr\u00f3polis","twitter_description":"Los coches aparcados en las calles forman parte de nuestro paisaje urbano habitual, pero para una ciudad sana del futuro necesitamos espacio para los encuentros, para la naturaleza y lugares [&hellip;]","twitter_image":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/11\/Unbenannt.JPG_compressed.jpeg","twitter_misc":{"Escrito por":"Alemania","Tiempo de lectura":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/news.acropolis.org\/es\/2024\/una-calle-para-todos-dia-del-aparcamiento-leipzig-alemania\/#article","isPartOf":{"@id":"https:\/\/news.acropolis.org\/es\/2024\/una-calle-para-todos-dia-del-aparcamiento-leipzig-alemania\/"},"author":{"name":"Germany","@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/4cb7cee6446382e733e5cc1ad36d9e58"},"headline":"Una calle para todos. D\u00eda del aparcamiento (Leipzig, Alemania)","datePublished":"2024-11-30T20:23:14+00:00","mainEntityOfPage":{"@id":"https:\/\/news.acropolis.org\/es\/2024\/una-calle-para-todos-dia-del-aparcamiento-leipzig-alemania\/"},"wordCount":122,"commentCount":0,"image":{"@id":"https:\/\/news.acropolis.org\/es\/2024\/una-calle-para-todos-dia-del-aparcamiento-leipzig-alemania\/#primaryimage"},"thumbnailUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/11\/Unbenannt.JPG_compressed.jpeg","keywords":["Conservaci\u00f3n medioambiental","filosof\u00eda","Leipzig","nueva acr\u00f3polis"],"articleSection":["Actividades Culturales"],"inLanguage":"es-ES","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/news.acropolis.org\/es\/2024\/una-calle-para-todos-dia-del-aparcamiento-leipzig-alemania\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/news.acropolis.org\/es\/2024\/una-calle-para-todos-dia-del-aparcamiento-leipzig-alemania\/","url":"https:\/\/news.acropolis.org\/es\/2024\/una-calle-para-todos-dia-del-aparcamiento-leipzig-alemania\/","name":"Una calle para todos. D\u00eda del aparcamiento (Leipzig, Alemania) - Noticias de Nueva Acr\u00f3polis","isPartOf":{"@id":"https:\/\/news.acropolis.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/news.acropolis.org\/es\/2024\/una-calle-para-todos-dia-del-aparcamiento-leipzig-alemania\/#primaryimage"},"image":{"@id":"https:\/\/news.acropolis.org\/es\/2024\/una-calle-para-todos-dia-del-aparcamiento-leipzig-alemania\/#primaryimage"},"thumbnailUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/11\/Unbenannt.JPG_compressed.jpeg","datePublished":"2024-11-30T20:23:14+00:00","author":{"@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/4cb7cee6446382e733e5cc1ad36d9e58"},"breadcrumb":{"@id":"https:\/\/news.acropolis.org\/es\/2024\/una-calle-para-todos-dia-del-aparcamiento-leipzig-alemania\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/news.acropolis.org\/es\/2024\/una-calle-para-todos-dia-del-aparcamiento-leipzig-alemania\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/news.acropolis.org\/es\/2024\/una-calle-para-todos-dia-del-aparcamiento-leipzig-alemania\/#primaryimage","url":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/11\/Unbenannt.JPG_compressed.jpeg","contentUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/11\/Unbenannt.JPG_compressed.jpeg","width":868,"height":854,"caption":"Parking Day Leipzig"},{"@type":"BreadcrumbList","@id":"https:\/\/news.acropolis.org\/es\/2024\/una-calle-para-todos-dia-del-aparcamiento-leipzig-alemania\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/news.acropolis.org\/es\/"},{"@type":"ListItem","position":2,"name":"Una calle para todos. D\u00eda del aparcamiento (Leipzig, Alemania)"}]},{"@type":"WebSite","@id":"https:\/\/news.acropolis.org\/es\/#website","url":"https:\/\/news.acropolis.org\/es\/","name":"Noticias de Nueva Acr\u00f3polis","description":"Actividades de la Organizaci\u00f3n Internacional Nueva Acr\u00f3polis","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/news.acropolis.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/4cb7cee6446382e733e5cc1ad36d9e58","name":"Germany","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/DEU.png","url":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/DEU.png","contentUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/DEU.png","caption":"Germany"},"url":"https:\/\/news.acropolis.org\/es\/author\/ionad\/"}]}},"_links":{"self":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/102765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/comments?post=102765"}],"version-history":[{"count":2,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/102765\/revisions"}],"predecessor-version":[{"id":102767,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/102765\/revisions\/102767"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/media\/102739"}],"wp:attachment":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/media?parent=102765"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/categories?post=102765"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/tags?post=102765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}