{"id":111212,"date":"2025-05-31T10:42:04","date_gmt":"2025-05-31T08:42:04","guid":{"rendered":"https:\/\/news.acropolis.org\/?p=111212"},"modified":"2025-05-30T10:43:59","modified_gmt":"2025-05-30T08:43:59","slug":"viaje-al-corazon-de-la-prehistoria-en-cantabria-bilbao-espana","status":"publish","type":"post","link":"https:\/\/news.acropolis.org\/es\/2025\/viaje-al-corazon-de-la-prehistoria-en-cantabria-bilbao-espana\/","title":{"rendered":"Viaje al coraz\u00f3n de la prehistoria en Cantabria (Bilbao, Espa\u00f1a)"},"content":{"rendered":"<p><a href=\"https:\/\/noticias.nueva-acropolis.es\/?attachment_id=32377\" rel=\"attachment wp-att-32377\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-32377\" src=\"https:\/\/noticias.nueva-acropolis.es\/wp-content\/uploads\/2025\/05\/cantabria1.jpg\" alt=\"\" width=\"475\" height=\"444\" \/><\/a>Socios de la Escuela de Filosof\u00eda de<strong> Nueva Acr\u00f3polis\u00a0 Bilbao<\/strong> y amantes de la arqueolog\u00eda y de la prehistoria realizaron una salida cultural a tres destacados sitios del patrimonio c\u00e1ntabro: la <strong>Cueva de Las Monedas<\/strong>, la<strong> Cueva del Castillo<\/strong> y el <strong>Museo de Prehistoria y Arqueolog\u00eda de Santander<\/strong>. Esta excursi\u00f3n tuvo como objetivo acercarse al arte rupestre paleol\u00edtico y a los modos de vida de nuestros antepasados m\u00e1s remotos.<\/p>\n<p>La jornada comenz\u00f3 con la visita a las cuevas del Monte Castillo, en <strong>Puente Viesgo<\/strong>, un conjunto declarado Patrimonio Mundial por la UNESCO. En primer lugar, los asistentes accedieron a la Cueva de Las Monedas, la m\u00e1s moderna del conjunto en cuanto a cronolog\u00eda, que alberga impresionantes formaciones geol\u00f3gicas y pinturas datadas en torno a los 12.000 a\u00f1os de antig\u00fcedad.<\/p>\n<p>A continuaci\u00f3n, la visita continu\u00f3 en la cercana Cueva del Castillo, una de las m\u00e1s antiguas del mundo, con evidencias de arte rupestre de hasta 40.000 a\u00f1os de antig\u00fcedad. Los participantes recorrieron sus galer\u00edas repletas con pinturas de manos, signos abstractos y figuras de animales, entendiendo la trascendencia cultural y espiritual que estas manifestaciones ten\u00edan para los primeros habitantes de la regi\u00f3n.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-32380 alignright\" src=\"https:\/\/noticias.nueva-acropolis.es\/wp-content\/uploads\/2025\/05\/cantabria-2.1-300x192.jpg\" alt=\"\" width=\"300\" height=\"192\" \/><\/p>\n<p>Por la tarde, el grupo se traslad\u00f3 a Santander para visitar el Museo de Prehistoria y Arqueolog\u00eda de Cantabria (MUPAC), donde pudieron profundizar en el conocimiento de las cuevas visitadas. La exposici\u00f3n permanente permiti\u00f3 contemplar herramientas y restos\u00a0 procedentes de yacimientos de toda Cantabria.<\/p>\n<p>Esta actividad dej\u00f3 impronta en todos los participantes, al brindarles la posibilidad de viajar en el tiempo y conectar con las huellas antiguas de la humanidad. Fue mucho m\u00e1s que una visita cultural: fue un encuentro \u00edntimo con nuestras ra\u00edces, con el misterio y la belleza de los or\u00edgenes humanos que Cantabria guarda con tanto af\u00e1n.<\/p>\n<p><a href=\"https:\/\/noticias.nueva-acropolis.es\/?attachment_id=32381\" rel=\"attachment wp-att-32381\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-32381 aligncenter\" src=\"https:\/\/noticias.nueva-acropolis.es\/wp-content\/uploads\/2025\/05\/cantabria-3.1.jpg\" alt=\"\" width=\"841\" height=\"534\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Socios de la Escuela de Filosof\u00eda de Nueva Acr\u00f3polis\u00a0 Bilbao y amantes de la arqueolog\u00eda y de la prehistoria realizaron una salida cultural a tres destacados sitios del patrimonio c\u00e1ntabro: [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":111213,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[47],"tags":[],"class_list":["post-111212","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actividades_educativas","clearfix"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Viaje al coraz\u00f3n de la prehistoria en Cantabria (Bilbao, Espa\u00f1a) - Noticias de Nueva Acr\u00f3polis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/news.acropolis.org\/es\/2025\/viaje-al-corazon-de-la-prehistoria-en-cantabria-bilbao-espana\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Viaje al coraz\u00f3n de la prehistoria en Cantabria (Bilbao, Espa\u00f1a) - Noticias de Nueva Acr\u00f3polis\" \/>\n<meta name=\"twitter:description\" content=\"Socios de la Escuela de Filosof\u00eda de Nueva Acr\u00f3polis\u00a0 Bilbao y amantes de la arqueolog\u00eda y de la prehistoria realizaron una salida cultural a tres destacados sitios del patrimonio c\u00e1ntabro: [&hellip;]\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/05\/cantabria-3.1.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Espa\u00f1a\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/viaje-al-corazon-de-la-prehistoria-en-cantabria-bilbao-espana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/viaje-al-corazon-de-la-prehistoria-en-cantabria-bilbao-espana\\\/\"},\"author\":{\"name\":\"Spain\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/ced850172dfe4e556569b56610e2183e\"},\"headline\":\"Viaje al coraz\u00f3n de la prehistoria en Cantabria (Bilbao, Espa\u00f1a)\",\"datePublished\":\"2025-05-31T08:42:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/viaje-al-corazon-de-la-prehistoria-en-cantabria-bilbao-espana\\\/\"},\"wordCount\":327,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/viaje-al-corazon-de-la-prehistoria-en-cantabria-bilbao-espana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cantabria-3.1.jpg\",\"articleSection\":[\"Actividades Educativas\"],\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/viaje-al-corazon-de-la-prehistoria-en-cantabria-bilbao-espana\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/viaje-al-corazon-de-la-prehistoria-en-cantabria-bilbao-espana\\\/\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/viaje-al-corazon-de-la-prehistoria-en-cantabria-bilbao-espana\\\/\",\"name\":\"Viaje al coraz\u00f3n de la prehistoria en Cantabria (Bilbao, Espa\u00f1a) - Noticias de Nueva Acr\u00f3polis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/viaje-al-corazon-de-la-prehistoria-en-cantabria-bilbao-espana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/viaje-al-corazon-de-la-prehistoria-en-cantabria-bilbao-espana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cantabria-3.1.jpg\",\"datePublished\":\"2025-05-31T08:42:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/ced850172dfe4e556569b56610e2183e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/viaje-al-corazon-de-la-prehistoria-en-cantabria-bilbao-espana\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/viaje-al-corazon-de-la-prehistoria-en-cantabria-bilbao-espana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/viaje-al-corazon-de-la-prehistoria-en-cantabria-bilbao-espana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cantabria-3.1.jpg\",\"contentUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cantabria-3.1.jpg\",\"width\":841,\"height\":534},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/viaje-al-corazon-de-la-prehistoria-en-cantabria-bilbao-espana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Viaje al coraz\u00f3n de la prehistoria en Cantabria (Bilbao, Espa\u00f1a)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/\",\"name\":\"Noticias de Nueva Acr\u00f3polis\",\"description\":\"Actividades de la Organizaci\u00f3n Internacional Nueva Acr\u00f3polis\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/ced850172dfe4e556569b56610e2183e\",\"name\":\"Spain\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/ESP.png\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/ESP.png\",\"contentUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/ESP.png\",\"caption\":\"Spain\"},\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/author\\\/oinaes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Viaje al coraz\u00f3n de la prehistoria en Cantabria (Bilbao, Espa\u00f1a) - Noticias de Nueva Acr\u00f3polis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/news.acropolis.org\/es\/2025\/viaje-al-corazon-de-la-prehistoria-en-cantabria-bilbao-espana\/","twitter_card":"summary_large_image","twitter_title":"Viaje al coraz\u00f3n de la prehistoria en Cantabria (Bilbao, Espa\u00f1a) - Noticias de Nueva Acr\u00f3polis","twitter_description":"Socios de la Escuela de Filosof\u00eda de Nueva Acr\u00f3polis\u00a0 Bilbao y amantes de la arqueolog\u00eda y de la prehistoria realizaron una salida cultural a tres destacados sitios del patrimonio c\u00e1ntabro: [&hellip;]","twitter_image":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/05\/cantabria-3.1.jpg","twitter_misc":{"Escrito por":"Espa\u00f1a","Tiempo de lectura":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/news.acropolis.org\/es\/2025\/viaje-al-corazon-de-la-prehistoria-en-cantabria-bilbao-espana\/#article","isPartOf":{"@id":"https:\/\/news.acropolis.org\/es\/2025\/viaje-al-corazon-de-la-prehistoria-en-cantabria-bilbao-espana\/"},"author":{"name":"Spain","@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/ced850172dfe4e556569b56610e2183e"},"headline":"Viaje al coraz\u00f3n de la prehistoria en Cantabria (Bilbao, Espa\u00f1a)","datePublished":"2025-05-31T08:42:04+00:00","mainEntityOfPage":{"@id":"https:\/\/news.acropolis.org\/es\/2025\/viaje-al-corazon-de-la-prehistoria-en-cantabria-bilbao-espana\/"},"wordCount":327,"commentCount":0,"image":{"@id":"https:\/\/news.acropolis.org\/es\/2025\/viaje-al-corazon-de-la-prehistoria-en-cantabria-bilbao-espana\/#primaryimage"},"thumbnailUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/05\/cantabria-3.1.jpg","articleSection":["Actividades Educativas"],"inLanguage":"es-ES","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/news.acropolis.org\/es\/2025\/viaje-al-corazon-de-la-prehistoria-en-cantabria-bilbao-espana\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/news.acropolis.org\/es\/2025\/viaje-al-corazon-de-la-prehistoria-en-cantabria-bilbao-espana\/","url":"https:\/\/news.acropolis.org\/es\/2025\/viaje-al-corazon-de-la-prehistoria-en-cantabria-bilbao-espana\/","name":"Viaje al coraz\u00f3n de la prehistoria en Cantabria (Bilbao, Espa\u00f1a) - Noticias de Nueva Acr\u00f3polis","isPartOf":{"@id":"https:\/\/news.acropolis.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/news.acropolis.org\/es\/2025\/viaje-al-corazon-de-la-prehistoria-en-cantabria-bilbao-espana\/#primaryimage"},"image":{"@id":"https:\/\/news.acropolis.org\/es\/2025\/viaje-al-corazon-de-la-prehistoria-en-cantabria-bilbao-espana\/#primaryimage"},"thumbnailUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/05\/cantabria-3.1.jpg","datePublished":"2025-05-31T08:42:04+00:00","author":{"@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/ced850172dfe4e556569b56610e2183e"},"breadcrumb":{"@id":"https:\/\/news.acropolis.org\/es\/2025\/viaje-al-corazon-de-la-prehistoria-en-cantabria-bilbao-espana\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/news.acropolis.org\/es\/2025\/viaje-al-corazon-de-la-prehistoria-en-cantabria-bilbao-espana\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/news.acropolis.org\/es\/2025\/viaje-al-corazon-de-la-prehistoria-en-cantabria-bilbao-espana\/#primaryimage","url":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/05\/cantabria-3.1.jpg","contentUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/05\/cantabria-3.1.jpg","width":841,"height":534},{"@type":"BreadcrumbList","@id":"https:\/\/news.acropolis.org\/es\/2025\/viaje-al-corazon-de-la-prehistoria-en-cantabria-bilbao-espana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/news.acropolis.org\/es\/"},{"@type":"ListItem","position":2,"name":"Viaje al coraz\u00f3n de la prehistoria en Cantabria (Bilbao, Espa\u00f1a)"}]},{"@type":"WebSite","@id":"https:\/\/news.acropolis.org\/es\/#website","url":"https:\/\/news.acropolis.org\/es\/","name":"Noticias de Nueva Acr\u00f3polis","description":"Actividades de la Organizaci\u00f3n Internacional Nueva Acr\u00f3polis","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/news.acropolis.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/ced850172dfe4e556569b56610e2183e","name":"Spain","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/ESP.png","url":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/ESP.png","contentUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/ESP.png","caption":"Spain"},"url":"https:\/\/news.acropolis.org\/es\/author\/oinaes\/"}]}},"_links":{"self":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/111212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/comments?post=111212"}],"version-history":[{"count":1,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/111212\/revisions"}],"predecessor-version":[{"id":111216,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/111212\/revisions\/111216"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/media\/111213"}],"wp:attachment":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/media?parent=111212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/categories?post=111212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/tags?post=111212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}