{"id":112558,"date":"2025-07-09T08:57:01","date_gmt":"2025-07-09T06:57:01","guid":{"rendered":"https:\/\/news.acropolis.org\/?p=112558"},"modified":"2025-07-09T08:57:01","modified_gmt":"2025-07-09T06:57:01","slug":"celebracion-del-solsticio-de-verano-cali-colombia","status":"publish","type":"post","link":"https:\/\/news.acropolis.org\/es\/2025\/celebracion-del-solsticio-de-verano-cali-colombia\/","title":{"rendered":"Celebraci\u00f3n del solsticio de verano (Cali, Colombia)"},"content":{"rendered":"<p><a href=\"https:\/\/news.acropolis.org\/es\/solsticio-de-verano-cali-colombia-2\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-112561 size-full\" src=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/07\/Solsticio-de-verano-Cali-Colombia.jpg\" alt=\"\" width=\"533\" height=\"800\" srcset=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/07\/Solsticio-de-verano-Cali-Colombia.jpg 533w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/07\/Solsticio-de-verano-Cali-Colombia-200x300.jpg 200w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/07\/Solsticio-de-verano-Cali-Colombia-435x653.jpg 435w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" \/><\/a>Un grupo de j\u00f3venes se reunieron en el parque ecol\u00f3gico de Pance con el prop\u00f3sito de iniciar un ciclo de renovaci\u00f3n celebrando la Vida.\u00a0 En contacto con la naturaleza y la madre tierra, unidos compartieron este d\u00eda especial.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un grupo de j\u00f3venes se reunieron en el parque ecol\u00f3gico de Pance con el prop\u00f3sito de iniciar un ciclo de renovaci\u00f3n celebrando la Vida.\u00a0 En contacto con la naturaleza y [&hellip;]<\/p>\n","protected":false},"author":45,"featured_media":112559,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[],"class_list":["post-112558","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actividades_culturales","clearfix"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Celebraci\u00f3n del solsticio de verano (Cali, Colombia) - Noticias de Nueva Acr\u00f3polis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/news.acropolis.org\/es\/2025\/celebracion-del-solsticio-de-verano-cali-colombia\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Celebraci\u00f3n del solsticio de verano (Cali, Colombia) - Noticias de Nueva Acr\u00f3polis\" \/>\n<meta name=\"twitter:description\" content=\"Un grupo de j\u00f3venes se reunieron en el parque ecol\u00f3gico de Pance con el prop\u00f3sito de iniciar un ciclo de renovaci\u00f3n celebrando la Vida.\u00a0 En contacto con la naturaleza y [&hellip;]\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/07\/Solsticio-de-verano-Cali-Colombia.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Colombia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/celebracion-del-solsticio-de-verano-cali-colombia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/celebracion-del-solsticio-de-verano-cali-colombia\\\/\"},\"author\":{\"name\":\"Colombia\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/34a71b82a591a112f5fef5f84e884328\"},\"headline\":\"Celebraci\u00f3n del solsticio de verano (Cali, Colombia)\",\"datePublished\":\"2025-07-09T06:57:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/celebracion-del-solsticio-de-verano-cali-colombia\\\/\"},\"wordCount\":51,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/celebracion-del-solsticio-de-verano-cali-colombia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Solsticio-de-verano-Cali-Colombia.jpg\",\"articleSection\":[\"Actividades Culturales\"],\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/celebracion-del-solsticio-de-verano-cali-colombia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/celebracion-del-solsticio-de-verano-cali-colombia\\\/\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/celebracion-del-solsticio-de-verano-cali-colombia\\\/\",\"name\":\"Celebraci\u00f3n del solsticio de verano (Cali, Colombia) - Noticias de Nueva Acr\u00f3polis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/celebracion-del-solsticio-de-verano-cali-colombia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/celebracion-del-solsticio-de-verano-cali-colombia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Solsticio-de-verano-Cali-Colombia.jpg\",\"datePublished\":\"2025-07-09T06:57:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/34a71b82a591a112f5fef5f84e884328\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/celebracion-del-solsticio-de-verano-cali-colombia\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/celebracion-del-solsticio-de-verano-cali-colombia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/celebracion-del-solsticio-de-verano-cali-colombia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Solsticio-de-verano-Cali-Colombia.jpg\",\"contentUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Solsticio-de-verano-Cali-Colombia.jpg\",\"width\":533,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/celebracion-del-solsticio-de-verano-cali-colombia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Celebraci\u00f3n del solsticio de verano (Cali, Colombia)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/\",\"name\":\"Noticias de Nueva Acr\u00f3polis\",\"description\":\"Actividades de la Organizaci\u00f3n Internacional Nueva Acr\u00f3polis\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/34a71b82a591a112f5fef5f84e884328\",\"name\":\"Colombia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/COL.png\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/COL.png\",\"contentUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/COL.png\",\"caption\":\"Colombia\"},\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/author\\\/oinacol\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Celebraci\u00f3n del solsticio de verano (Cali, Colombia) - Noticias de Nueva Acr\u00f3polis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/news.acropolis.org\/es\/2025\/celebracion-del-solsticio-de-verano-cali-colombia\/","twitter_card":"summary_large_image","twitter_title":"Celebraci\u00f3n del solsticio de verano (Cali, Colombia) - Noticias de Nueva Acr\u00f3polis","twitter_description":"Un grupo de j\u00f3venes se reunieron en el parque ecol\u00f3gico de Pance con el prop\u00f3sito de iniciar un ciclo de renovaci\u00f3n celebrando la Vida.\u00a0 En contacto con la naturaleza y [&hellip;]","twitter_image":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/07\/Solsticio-de-verano-Cali-Colombia.jpg","twitter_misc":{"Escrito por":"Colombia","Tiempo de lectura":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/news.acropolis.org\/es\/2025\/celebracion-del-solsticio-de-verano-cali-colombia\/#article","isPartOf":{"@id":"https:\/\/news.acropolis.org\/es\/2025\/celebracion-del-solsticio-de-verano-cali-colombia\/"},"author":{"name":"Colombia","@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/34a71b82a591a112f5fef5f84e884328"},"headline":"Celebraci\u00f3n del solsticio de verano (Cali, Colombia)","datePublished":"2025-07-09T06:57:01+00:00","mainEntityOfPage":{"@id":"https:\/\/news.acropolis.org\/es\/2025\/celebracion-del-solsticio-de-verano-cali-colombia\/"},"wordCount":51,"commentCount":0,"image":{"@id":"https:\/\/news.acropolis.org\/es\/2025\/celebracion-del-solsticio-de-verano-cali-colombia\/#primaryimage"},"thumbnailUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/07\/Solsticio-de-verano-Cali-Colombia.jpg","articleSection":["Actividades Culturales"],"inLanguage":"es-ES","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/news.acropolis.org\/es\/2025\/celebracion-del-solsticio-de-verano-cali-colombia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/news.acropolis.org\/es\/2025\/celebracion-del-solsticio-de-verano-cali-colombia\/","url":"https:\/\/news.acropolis.org\/es\/2025\/celebracion-del-solsticio-de-verano-cali-colombia\/","name":"Celebraci\u00f3n del solsticio de verano (Cali, Colombia) - Noticias de Nueva Acr\u00f3polis","isPartOf":{"@id":"https:\/\/news.acropolis.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/news.acropolis.org\/es\/2025\/celebracion-del-solsticio-de-verano-cali-colombia\/#primaryimage"},"image":{"@id":"https:\/\/news.acropolis.org\/es\/2025\/celebracion-del-solsticio-de-verano-cali-colombia\/#primaryimage"},"thumbnailUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/07\/Solsticio-de-verano-Cali-Colombia.jpg","datePublished":"2025-07-09T06:57:01+00:00","author":{"@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/34a71b82a591a112f5fef5f84e884328"},"breadcrumb":{"@id":"https:\/\/news.acropolis.org\/es\/2025\/celebracion-del-solsticio-de-verano-cali-colombia\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/news.acropolis.org\/es\/2025\/celebracion-del-solsticio-de-verano-cali-colombia\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/news.acropolis.org\/es\/2025\/celebracion-del-solsticio-de-verano-cali-colombia\/#primaryimage","url":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/07\/Solsticio-de-verano-Cali-Colombia.jpg","contentUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/07\/Solsticio-de-verano-Cali-Colombia.jpg","width":533,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/news.acropolis.org\/es\/2025\/celebracion-del-solsticio-de-verano-cali-colombia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/news.acropolis.org\/es\/"},{"@type":"ListItem","position":2,"name":"Celebraci\u00f3n del solsticio de verano (Cali, Colombia)"}]},{"@type":"WebSite","@id":"https:\/\/news.acropolis.org\/es\/#website","url":"https:\/\/news.acropolis.org\/es\/","name":"Noticias de Nueva Acr\u00f3polis","description":"Actividades de la Organizaci\u00f3n Internacional Nueva Acr\u00f3polis","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/news.acropolis.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/34a71b82a591a112f5fef5f84e884328","name":"Colombia","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/COL.png","url":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/COL.png","contentUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/COL.png","caption":"Colombia"},"url":"https:\/\/news.acropolis.org\/es\/author\/oinacol\/"}]}},"_links":{"self":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/112558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/comments?post=112558"}],"version-history":[{"count":3,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/112558\/revisions"}],"predecessor-version":[{"id":112629,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/112558\/revisions\/112629"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/media\/112559"}],"wp:attachment":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/media?parent=112558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/categories?post=112558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/tags?post=112558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}