{"id":115114,"date":"2025-11-16T07:22:14","date_gmt":"2025-11-16T06:22:14","guid":{"rendered":"https:\/\/news.acropolis.org\/?p=115114"},"modified":"2025-11-16T07:22:14","modified_gmt":"2025-11-16T06:22:14","slug":"tertulia-filosofica-el-libro-de-los-muertos-un-mapa-para-la-eternidad-panama","status":"publish","type":"post","link":"https:\/\/news.acropolis.org\/es\/2025\/tertulia-filosofica-el-libro-de-los-muertos-un-mapa-para-la-eternidad-panama\/","title":{"rendered":"Tertulia filos\u00f3fica &#8220;El libro de los muertos: Un mapa para la eternidad&#8221; (Panam\u00e1)"},"content":{"rendered":"<p data-start=\"0\" data-end=\"627\">La m\u00e1s reciente Tertulia Filos\u00f3fica se adentr\u00f3 en uno de los textos m\u00e1s enigm\u00e1ticos y trascendentales del antiguo Egipto: <em data-start=\"126\" data-end=\"151\">El Libro de los Muertos<\/em>, los asistentes exploraron los significados ocultos de esta obra que, lejos de ser un simple manual funerario, se presenta como una gu\u00eda espiritual para el alma en su traves\u00eda hacia el m\u00e1s all\u00e1. Entre s\u00edmbolos, mitos y ense\u00f1anzas, se revel\u00f3 la profundidad de un texto que, a pesar de sus miles de a\u00f1os de antig\u00fcedad, contin\u00faa inspirando preguntas esenciales sobre la vida, la muerte y la trascendencia.<\/p>\n<p data-start=\"629\" data-end=\"1213\" data-is-last-node=\"\" data-is-only-node=\"\">La tertulia destac\u00f3 adem\u00e1s que su verdadero nombre, <em data-start=\"681\" data-end=\"713\">\u201cEl Libro de la Oculta Morada\u201d<\/em>, aporta una nueva dimensi\u00f3n de comprensi\u00f3n. No se trata \u00fanicamente de un camino hacia la eternidad, sino de un mapa interior que invita al ser humano a reflexionar sobre su propia existencia.<\/p>\n<p data-start=\"629\" data-end=\"1213\" data-is-last-node=\"\" data-is-only-node=\"\">La conversaci\u00f3n se convirti\u00f3 en un espacio de di\u00e1logo e introspecci\u00f3n, donde cada participante pudo acercarse a la sabidur\u00eda ancestral egipcia y reconocer c\u00f3mo su mensaje resuena en la actualidad, record\u00e1ndonos que la filosof\u00eda no solo habita en los libros, sino tambi\u00e9n en la b\u00fasqueda constante de sentido.<\/p>\n<p data-start=\"629\" data-end=\"1213\" data-is-last-node=\"\" data-is-only-node=\"\"><a href=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/09\/IMG_4187.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-115115 size-large\" src=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/09\/IMG_4187-1024x768.jpg\" alt=\"\" width=\"1024\" height=\"768\" srcset=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/09\/IMG_4187-1024x768.jpg 1024w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/09\/IMG_4187-300x225.jpg 300w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/09\/IMG_4187-768x576.jpg 768w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/09\/IMG_4187-730x548.jpg 730w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/09\/IMG_4187-435x326.jpg 435w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/09\/IMG_4187-80x60.jpg 80w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/09\/IMG_4187.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a> <a href=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/09\/IMG_4181.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-115118 size-large\" src=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/09\/IMG_4181-1024x768.jpg\" alt=\"\" width=\"1024\" height=\"768\" srcset=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/09\/IMG_4181-1024x768.jpg 1024w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/09\/IMG_4181-300x225.jpg 300w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/09\/IMG_4181-768x576.jpg 768w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/09\/IMG_4181-730x548.jpg 730w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/09\/IMG_4181-435x326.jpg 435w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/09\/IMG_4181-80x60.jpg 80w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/09\/IMG_4181.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La m\u00e1s reciente Tertulia Filos\u00f3fica se adentr\u00f3 en uno de los textos m\u00e1s enigm\u00e1ticos y trascendentales del antiguo Egipto: El Libro de los Muertos, los asistentes exploraron los significados ocultos [&hellip;]<\/p>\n","protected":false},"author":50,"featured_media":115115,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[51],"tags":[],"class_list":["post-115114","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-promocion_filosofia","clearfix"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tertulia filos\u00f3fica &quot;El libro de los muertos: Un mapa para la eternidad&quot; (Panam\u00e1) - Noticias de Nueva Acr\u00f3polis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/news.acropolis.org\/es\/2025\/tertulia-filosofica-el-libro-de-los-muertos-un-mapa-para-la-eternidad-panama\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Tertulia filos\u00f3fica &quot;El libro de los muertos: Un mapa para la eternidad&quot; (Panam\u00e1) - Noticias de Nueva Acr\u00f3polis\" \/>\n<meta name=\"twitter:description\" content=\"La m\u00e1s reciente Tertulia Filos\u00f3fica se adentr\u00f3 en uno de los textos m\u00e1s enigm\u00e1ticos y trascendentales del antiguo Egipto: El Libro de los Muertos, los asistentes exploraron los significados ocultos [&hellip;]\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Panam\u00e1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/tertulia-filosofica-el-libro-de-los-muertos-un-mapa-para-la-eternidad-panama\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/tertulia-filosofica-el-libro-de-los-muertos-un-mapa-para-la-eternidad-panama\\\/\"},\"author\":{\"name\":\"Panama\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/44fe880a2a861ee0d2bcaef437ac0fa7\"},\"headline\":\"Tertulia filos\u00f3fica &#8220;El libro de los muertos: Un mapa para la eternidad&#8221; (Panam\u00e1)\",\"datePublished\":\"2025-11-16T06:22:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/tertulia-filosofica-el-libro-de-los-muertos-un-mapa-para-la-eternidad-panama\\\/\"},\"wordCount\":223,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/tertulia-filosofica-el-libro-de-los-muertos-un-mapa-para-la-eternidad-panama\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/IMG_4187.jpg\",\"articleSection\":[\"Promoci\u00f3n de la Filosof\u00eda\"],\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/tertulia-filosofica-el-libro-de-los-muertos-un-mapa-para-la-eternidad-panama\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/tertulia-filosofica-el-libro-de-los-muertos-un-mapa-para-la-eternidad-panama\\\/\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/tertulia-filosofica-el-libro-de-los-muertos-un-mapa-para-la-eternidad-panama\\\/\",\"name\":\"Tertulia filos\u00f3fica \\\"El libro de los muertos: Un mapa para la eternidad\\\" (Panam\u00e1) - Noticias de Nueva Acr\u00f3polis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/tertulia-filosofica-el-libro-de-los-muertos-un-mapa-para-la-eternidad-panama\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/tertulia-filosofica-el-libro-de-los-muertos-un-mapa-para-la-eternidad-panama\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/IMG_4187.jpg\",\"datePublished\":\"2025-11-16T06:22:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/44fe880a2a861ee0d2bcaef437ac0fa7\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/tertulia-filosofica-el-libro-de-los-muertos-un-mapa-para-la-eternidad-panama\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/tertulia-filosofica-el-libro-de-los-muertos-un-mapa-para-la-eternidad-panama\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/tertulia-filosofica-el-libro-de-los-muertos-un-mapa-para-la-eternidad-panama\\\/#primaryimage\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/IMG_4187.jpg\",\"contentUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/IMG_4187.jpg\",\"width\":1280,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/tertulia-filosofica-el-libro-de-los-muertos-un-mapa-para-la-eternidad-panama\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tertulia filos\u00f3fica &#8220;El libro de los muertos: Un mapa para la eternidad&#8221; (Panam\u00e1)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/\",\"name\":\"Noticias de Nueva Acr\u00f3polis\",\"description\":\"Actividades de la Organizaci\u00f3n Internacional Nueva Acr\u00f3polis\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/44fe880a2a861ee0d2bcaef437ac0fa7\",\"name\":\"Panama\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/PAN.png\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/PAN.png\",\"contentUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/PAN.png\",\"caption\":\"Panama\"},\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/author\\\/oinapan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tertulia filos\u00f3fica \"El libro de los muertos: Un mapa para la eternidad\" (Panam\u00e1) - Noticias de Nueva Acr\u00f3polis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/news.acropolis.org\/es\/2025\/tertulia-filosofica-el-libro-de-los-muertos-un-mapa-para-la-eternidad-panama\/","twitter_card":"summary_large_image","twitter_title":"Tertulia filos\u00f3fica \"El libro de los muertos: Un mapa para la eternidad\" (Panam\u00e1) - Noticias de Nueva Acr\u00f3polis","twitter_description":"La m\u00e1s reciente Tertulia Filos\u00f3fica se adentr\u00f3 en uno de los textos m\u00e1s enigm\u00e1ticos y trascendentales del antiguo Egipto: El Libro de los Muertos, los asistentes exploraron los significados ocultos [&hellip;]","twitter_misc":{"Escrito por":"Panam\u00e1","Tiempo de lectura":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/news.acropolis.org\/es\/2025\/tertulia-filosofica-el-libro-de-los-muertos-un-mapa-para-la-eternidad-panama\/#article","isPartOf":{"@id":"https:\/\/news.acropolis.org\/es\/2025\/tertulia-filosofica-el-libro-de-los-muertos-un-mapa-para-la-eternidad-panama\/"},"author":{"name":"Panama","@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/44fe880a2a861ee0d2bcaef437ac0fa7"},"headline":"Tertulia filos\u00f3fica &#8220;El libro de los muertos: Un mapa para la eternidad&#8221; (Panam\u00e1)","datePublished":"2025-11-16T06:22:14+00:00","mainEntityOfPage":{"@id":"https:\/\/news.acropolis.org\/es\/2025\/tertulia-filosofica-el-libro-de-los-muertos-un-mapa-para-la-eternidad-panama\/"},"wordCount":223,"commentCount":0,"image":{"@id":"https:\/\/news.acropolis.org\/es\/2025\/tertulia-filosofica-el-libro-de-los-muertos-un-mapa-para-la-eternidad-panama\/#primaryimage"},"thumbnailUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/09\/IMG_4187.jpg","articleSection":["Promoci\u00f3n de la Filosof\u00eda"],"inLanguage":"es-ES","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/news.acropolis.org\/es\/2025\/tertulia-filosofica-el-libro-de-los-muertos-un-mapa-para-la-eternidad-panama\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/news.acropolis.org\/es\/2025\/tertulia-filosofica-el-libro-de-los-muertos-un-mapa-para-la-eternidad-panama\/","url":"https:\/\/news.acropolis.org\/es\/2025\/tertulia-filosofica-el-libro-de-los-muertos-un-mapa-para-la-eternidad-panama\/","name":"Tertulia filos\u00f3fica \"El libro de los muertos: Un mapa para la eternidad\" (Panam\u00e1) - Noticias de Nueva Acr\u00f3polis","isPartOf":{"@id":"https:\/\/news.acropolis.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/news.acropolis.org\/es\/2025\/tertulia-filosofica-el-libro-de-los-muertos-un-mapa-para-la-eternidad-panama\/#primaryimage"},"image":{"@id":"https:\/\/news.acropolis.org\/es\/2025\/tertulia-filosofica-el-libro-de-los-muertos-un-mapa-para-la-eternidad-panama\/#primaryimage"},"thumbnailUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/09\/IMG_4187.jpg","datePublished":"2025-11-16T06:22:14+00:00","author":{"@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/44fe880a2a861ee0d2bcaef437ac0fa7"},"breadcrumb":{"@id":"https:\/\/news.acropolis.org\/es\/2025\/tertulia-filosofica-el-libro-de-los-muertos-un-mapa-para-la-eternidad-panama\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/news.acropolis.org\/es\/2025\/tertulia-filosofica-el-libro-de-los-muertos-un-mapa-para-la-eternidad-panama\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/news.acropolis.org\/es\/2025\/tertulia-filosofica-el-libro-de-los-muertos-un-mapa-para-la-eternidad-panama\/#primaryimage","url":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/09\/IMG_4187.jpg","contentUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/09\/IMG_4187.jpg","width":1280,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/news.acropolis.org\/es\/2025\/tertulia-filosofica-el-libro-de-los-muertos-un-mapa-para-la-eternidad-panama\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/news.acropolis.org\/es\/"},{"@type":"ListItem","position":2,"name":"Tertulia filos\u00f3fica &#8220;El libro de los muertos: Un mapa para la eternidad&#8221; (Panam\u00e1)"}]},{"@type":"WebSite","@id":"https:\/\/news.acropolis.org\/es\/#website","url":"https:\/\/news.acropolis.org\/es\/","name":"Noticias de Nueva Acr\u00f3polis","description":"Actividades de la Organizaci\u00f3n Internacional Nueva Acr\u00f3polis","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/news.acropolis.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/44fe880a2a861ee0d2bcaef437ac0fa7","name":"Panama","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/PAN.png","url":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/PAN.png","contentUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/PAN.png","caption":"Panama"},"url":"https:\/\/news.acropolis.org\/es\/author\/oinapan\/"}]}},"_links":{"self":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/115114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/users\/50"}],"replies":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/comments?post=115114"}],"version-history":[{"count":4,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/115114\/revisions"}],"predecessor-version":[{"id":119471,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/115114\/revisions\/119471"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/media\/115115"}],"wp:attachment":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/media?parent=115114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/categories?post=115114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/tags?post=115114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}