{"id":118812,"date":"2025-11-05T11:26:04","date_gmt":"2025-11-05T10:26:04","guid":{"rendered":"https:\/\/news.acropolis.org\/?p=118812"},"modified":"2025-11-11T09:42:15","modified_gmt":"2025-11-11T08:42:15","slug":"nueva-acropolis-en-salzburgo-austria","status":"publish","type":"post","link":"https:\/\/news.acropolis.org\/es\/2025\/nueva-acropolis-en-salzburgo-austria\/","title":{"rendered":"Nueva Acr\u00f3polis en Salzburgo (Austria)"},"content":{"rendered":"<p><strong>Reapertura tras la reubicaci\u00f3n<\/strong><\/p>\n<p>Alrededor de 100 invitados, junto con representantes de la pol\u00edtica, la cultura y la educaci\u00f3n, se reunieron para celebrar la inauguraci\u00f3n de este nuevo espacio dedicado al pensamiento filos\u00f3fico, la actividad creativa y la interacci\u00f3n humana.<\/p>\n<p>Entre los invitados de honor se encontraban el teniente de alcalde Mag. Kay-Michael Dankl, el Dr. Hannes Weinelt, director de Nueva Acr\u00f3polis Austria, y Mag. Gabi Burgstaller, exgobernadora de Salzburgo.<\/p>\n<p>En su discurso, el Sr. Dankl destac\u00f3 la importancia de estos lugares en la actualidad: plataformas donde las personas pueden conversar, reflexionar, escuchar y construir el futuro juntas.<\/p>\n<p>Uno de los momentos m\u00e1s destacados de la velada fueron las sesiones de di\u00e1logo filos\u00f3fico: conversaciones breves y animadas, preguntas sorprendentes, muchas risas y encuentros genuinos. Esto demostr\u00f3 lo din\u00e1mica y accesible que puede ser la filosof\u00eda cuando uno simplemente se anima a explorarla.<\/p>\n<p>El cantante y pianista Fernando Araujo nos emocion\u00f3 profundamente, enriqueciendo la velada de una manera especial con su m\u00fasica e invit\u00e1ndonos a reflexionar, so\u00f1ar y conectar con la naturaleza.<\/p>\n<p>La nueva escuela se centra en una \u00abfilosof\u00eda para todos\u00bb, inspirada en el esp\u00edritu de Salzburgo y abierta a quienes buscan mayor profundidad, significado y conexi\u00f3n en sus vidas.<\/p>\n<p>Nuestra visi\u00f3n: no solo pensar en filosof\u00eda, sino vivirla.<\/p>\n<p>Filosofar juntos, ser creativos y actuar para construir un mundo m\u00e1s consciente, m\u00e1s humano y m\u00e1s habitable, paso a paso.<\/p>\n<p>Porque la filosof\u00eda comienza precisamente cuando nos preguntamos: \u00a0\u00bfC\u00f3mo quiero vivir?<\/p>\n<p><a href=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/11\/2510_NAS-EoeffnungsfestGBZ_5829.jpg_compressed-002.jpg\"><br \/>\n<\/a><a href=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/11\/2510_NAS-EoeffnungsfestGBZ_5894.jpg_compressed-002.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-118767\" src=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/11\/2510_NAS-EoeffnungsfestGBZ_5894.jpg_compressed-002-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/11\/2510_NAS-EoeffnungsfestGBZ_5894.jpg_compressed-002-300x200.jpg 300w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/11\/2510_NAS-EoeffnungsfestGBZ_5894.jpg_compressed-002-1024x683.jpg 1024w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/11\/2510_NAS-EoeffnungsfestGBZ_5894.jpg_compressed-002-768x512.jpg 768w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/11\/2510_NAS-EoeffnungsfestGBZ_5894.jpg_compressed-002-1536x1024.jpg 1536w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/11\/2510_NAS-EoeffnungsfestGBZ_5894.jpg_compressed-002-730x487.jpg 730w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/11\/2510_NAS-EoeffnungsfestGBZ_5894.jpg_compressed-002-435x290.jpg 435w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/11\/2510_NAS-EoeffnungsfestGBZ_5894.jpg_compressed-002.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/11\/2510_NAS-EoeffnungsfestGBZ_6018.jpg_compressed-002.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-118770\" src=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/11\/2510_NAS-EoeffnungsfestGBZ_6018.jpg_compressed-002-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/11\/2510_NAS-EoeffnungsfestGBZ_6018.jpg_compressed-002-300x200.jpg 300w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/11\/2510_NAS-EoeffnungsfestGBZ_6018.jpg_compressed-002-1024x683.jpg 1024w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/11\/2510_NAS-EoeffnungsfestGBZ_6018.jpg_compressed-002-768x512.jpg 768w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/11\/2510_NAS-EoeffnungsfestGBZ_6018.jpg_compressed-002-1536x1024.jpg 1536w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/11\/2510_NAS-EoeffnungsfestGBZ_6018.jpg_compressed-002-730x487.jpg 730w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/11\/2510_NAS-EoeffnungsfestGBZ_6018.jpg_compressed-002-435x290.jpg 435w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/11\/2510_NAS-EoeffnungsfestGBZ_6018.jpg_compressed-002.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/11\/2510_NAS-EoeffnungsfestGBZ_6240.jpg_compressed-002.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-118773\" src=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/11\/2510_NAS-EoeffnungsfestGBZ_6240.jpg_compressed-002-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/11\/2510_NAS-EoeffnungsfestGBZ_6240.jpg_compressed-002-300x200.jpg 300w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/11\/2510_NAS-EoeffnungsfestGBZ_6240.jpg_compressed-002-1024x683.jpg 1024w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/11\/2510_NAS-EoeffnungsfestGBZ_6240.jpg_compressed-002-768x512.jpg 768w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/11\/2510_NAS-EoeffnungsfestGBZ_6240.jpg_compressed-002-1536x1024.jpg 1536w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/11\/2510_NAS-EoeffnungsfestGBZ_6240.jpg_compressed-002-730x487.jpg 730w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/11\/2510_NAS-EoeffnungsfestGBZ_6240.jpg_compressed-002-435x290.jpg 435w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/11\/2510_NAS-EoeffnungsfestGBZ_6240.jpg_compressed-002.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/11\/2510_NAS-Eroeffnungsfest-iphoneIMG_2621.jpg_compressed-002.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-118776\" src=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/11\/2510_NAS-Eroeffnungsfest-iphoneIMG_2621.jpg_compressed-002-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/11\/2510_NAS-Eroeffnungsfest-iphoneIMG_2621.jpg_compressed-002-300x169.jpg 300w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/11\/2510_NAS-Eroeffnungsfest-iphoneIMG_2621.jpg_compressed-002-1024x576.jpg 1024w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/11\/2510_NAS-Eroeffnungsfest-iphoneIMG_2621.jpg_compressed-002-768x432.jpg 768w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/11\/2510_NAS-Eroeffnungsfest-iphoneIMG_2621.jpg_compressed-002-1536x864.jpg 1536w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/11\/2510_NAS-Eroeffnungsfest-iphoneIMG_2621.jpg_compressed-002-2048x1152.jpg 2048w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/11\/2510_NAS-Eroeffnungsfest-iphoneIMG_2621.jpg_compressed-002-730x411.jpg 730w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/11\/2510_NAS-Eroeffnungsfest-iphoneIMG_2621.jpg_compressed-002-435x245.jpg 435w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Reapertura tras la reubicaci\u00f3n Alrededor de 100 invitados, junto con representantes de la pol\u00edtica, la cultura y la educaci\u00f3n, se reunieron para celebrar la inauguraci\u00f3n de este nuevo espacio dedicado [&hellip;]<\/p>\n","protected":false},"author":31,"featured_media":118766,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[51],"tags":[],"class_list":["post-118812","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-promocion_filosofia","clearfix"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nueva Acr\u00f3polis en Salzburgo (Austria) - Noticias de Nueva Acr\u00f3polis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/news.acropolis.org\/es\/2025\/nueva-acropolis-en-salzburgo-austria\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Nueva Acr\u00f3polis en Salzburgo (Austria) - Noticias de Nueva Acr\u00f3polis\" \/>\n<meta name=\"twitter:description\" content=\"Reapertura tras la reubicaci\u00f3n Alrededor de 100 invitados, junto con representantes de la pol\u00edtica, la cultura y la educaci\u00f3n, se reunieron para celebrar la inauguraci\u00f3n de este nuevo espacio dedicado [&hellip;]\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/11\/2510_NAS-EoeffnungsfestGBZ_5829.jpg_compressed-002.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Austria\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/nueva-acropolis-en-salzburgo-austria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/nueva-acropolis-en-salzburgo-austria\\\/\"},\"author\":{\"name\":\"Austria\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/425f59cca8fecb7d750a02985da925d4\"},\"headline\":\"Nueva Acr\u00f3polis en Salzburgo (Austria)\",\"datePublished\":\"2025-11-05T10:26:04+00:00\",\"dateModified\":\"2025-11-11T08:42:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/nueva-acropolis-en-salzburgo-austria\\\/\"},\"wordCount\":270,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/nueva-acropolis-en-salzburgo-austria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/2510_NAS-EoeffnungsfestGBZ_5829.jpg_compressed-002.jpg\",\"articleSection\":[\"Promoci\u00f3n de la Filosof\u00eda\"],\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/nueva-acropolis-en-salzburgo-austria\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/nueva-acropolis-en-salzburgo-austria\\\/\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/nueva-acropolis-en-salzburgo-austria\\\/\",\"name\":\"Nueva Acr\u00f3polis en Salzburgo (Austria) - Noticias de Nueva Acr\u00f3polis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/nueva-acropolis-en-salzburgo-austria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/nueva-acropolis-en-salzburgo-austria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/2510_NAS-EoeffnungsfestGBZ_5829.jpg_compressed-002.jpg\",\"datePublished\":\"2025-11-05T10:26:04+00:00\",\"dateModified\":\"2025-11-11T08:42:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/425f59cca8fecb7d750a02985da925d4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/nueva-acropolis-en-salzburgo-austria\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/nueva-acropolis-en-salzburgo-austria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/nueva-acropolis-en-salzburgo-austria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/2510_NAS-EoeffnungsfestGBZ_5829.jpg_compressed-002.jpg\",\"contentUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/2510_NAS-EoeffnungsfestGBZ_5829.jpg_compressed-002.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/nueva-acropolis-en-salzburgo-austria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nueva Acr\u00f3polis en Salzburgo (Austria)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/\",\"name\":\"Noticias de Nueva Acr\u00f3polis\",\"description\":\"Actividades de la Organizaci\u00f3n Internacional Nueva Acr\u00f3polis\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/425f59cca8fecb7d750a02985da925d4\",\"name\":\"Austria\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/AUT.png\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/AUT.png\",\"contentUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/AUT.png\",\"caption\":\"Austria\"},\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/author\\\/oinaaut\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nueva Acr\u00f3polis en Salzburgo (Austria) - Noticias de Nueva Acr\u00f3polis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/news.acropolis.org\/es\/2025\/nueva-acropolis-en-salzburgo-austria\/","twitter_card":"summary_large_image","twitter_title":"Nueva Acr\u00f3polis en Salzburgo (Austria) - Noticias de Nueva Acr\u00f3polis","twitter_description":"Reapertura tras la reubicaci\u00f3n Alrededor de 100 invitados, junto con representantes de la pol\u00edtica, la cultura y la educaci\u00f3n, se reunieron para celebrar la inauguraci\u00f3n de este nuevo espacio dedicado [&hellip;]","twitter_image":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/11\/2510_NAS-EoeffnungsfestGBZ_5829.jpg_compressed-002.jpg","twitter_misc":{"Escrito por":"Austria","Tiempo de lectura":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/news.acropolis.org\/es\/2025\/nueva-acropolis-en-salzburgo-austria\/#article","isPartOf":{"@id":"https:\/\/news.acropolis.org\/es\/2025\/nueva-acropolis-en-salzburgo-austria\/"},"author":{"name":"Austria","@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/425f59cca8fecb7d750a02985da925d4"},"headline":"Nueva Acr\u00f3polis en Salzburgo (Austria)","datePublished":"2025-11-05T10:26:04+00:00","dateModified":"2025-11-11T08:42:15+00:00","mainEntityOfPage":{"@id":"https:\/\/news.acropolis.org\/es\/2025\/nueva-acropolis-en-salzburgo-austria\/"},"wordCount":270,"commentCount":0,"image":{"@id":"https:\/\/news.acropolis.org\/es\/2025\/nueva-acropolis-en-salzburgo-austria\/#primaryimage"},"thumbnailUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/11\/2510_NAS-EoeffnungsfestGBZ_5829.jpg_compressed-002.jpg","articleSection":["Promoci\u00f3n de la Filosof\u00eda"],"inLanguage":"es-ES","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/news.acropolis.org\/es\/2025\/nueva-acropolis-en-salzburgo-austria\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/news.acropolis.org\/es\/2025\/nueva-acropolis-en-salzburgo-austria\/","url":"https:\/\/news.acropolis.org\/es\/2025\/nueva-acropolis-en-salzburgo-austria\/","name":"Nueva Acr\u00f3polis en Salzburgo (Austria) - Noticias de Nueva Acr\u00f3polis","isPartOf":{"@id":"https:\/\/news.acropolis.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/news.acropolis.org\/es\/2025\/nueva-acropolis-en-salzburgo-austria\/#primaryimage"},"image":{"@id":"https:\/\/news.acropolis.org\/es\/2025\/nueva-acropolis-en-salzburgo-austria\/#primaryimage"},"thumbnailUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/11\/2510_NAS-EoeffnungsfestGBZ_5829.jpg_compressed-002.jpg","datePublished":"2025-11-05T10:26:04+00:00","dateModified":"2025-11-11T08:42:15+00:00","author":{"@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/425f59cca8fecb7d750a02985da925d4"},"breadcrumb":{"@id":"https:\/\/news.acropolis.org\/es\/2025\/nueva-acropolis-en-salzburgo-austria\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/news.acropolis.org\/es\/2025\/nueva-acropolis-en-salzburgo-austria\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/news.acropolis.org\/es\/2025\/nueva-acropolis-en-salzburgo-austria\/#primaryimage","url":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/11\/2510_NAS-EoeffnungsfestGBZ_5829.jpg_compressed-002.jpg","contentUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/11\/2510_NAS-EoeffnungsfestGBZ_5829.jpg_compressed-002.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/news.acropolis.org\/es\/2025\/nueva-acropolis-en-salzburgo-austria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/news.acropolis.org\/es\/"},{"@type":"ListItem","position":2,"name":"Nueva Acr\u00f3polis en Salzburgo (Austria)"}]},{"@type":"WebSite","@id":"https:\/\/news.acropolis.org\/es\/#website","url":"https:\/\/news.acropolis.org\/es\/","name":"Noticias de Nueva Acr\u00f3polis","description":"Actividades de la Organizaci\u00f3n Internacional Nueva Acr\u00f3polis","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/news.acropolis.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/425f59cca8fecb7d750a02985da925d4","name":"Austria","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/AUT.png","url":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/AUT.png","contentUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/AUT.png","caption":"Austria"},"url":"https:\/\/news.acropolis.org\/es\/author\/oinaaut\/"}]}},"_links":{"self":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/118812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/comments?post=118812"}],"version-history":[{"count":3,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/118812\/revisions"}],"predecessor-version":[{"id":119203,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/118812\/revisions\/119203"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/media\/118766"}],"wp:attachment":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/media?parent=118812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/categories?post=118812"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/tags?post=118812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}