{"id":120898,"date":"2025-12-28T10:16:32","date_gmt":"2025-12-28T09:16:32","guid":{"rendered":"https:\/\/news.acropolis.org\/?p=120898"},"modified":"2025-12-28T11:20:34","modified_gmt":"2025-12-28T10:20:34","slug":"encuentro-con-la-historia-cali-colombia","status":"publish","type":"post","link":"https:\/\/news.acropolis.org\/es\/2025\/encuentro-con-la-historia-cali-colombia\/","title":{"rendered":"&#8220;Encuentro con la Historia (Cali, Colombia)"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><a href=\"https:\/\/news.acropolis.org\/es\/2025\/encuentro-con-la-historia-cali-colombia\/encuentro-con-la-historia-2025-213x300\/\" rel=\"attachment wp-att-122706\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-122706\" src=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/12\/encuentro-con-la-historia-2025-213x300-1.png\" alt=\"\" width=\"213\" height=\"300\" \/><\/a>Puesta en escena de \u201cEl encuentro con la Historia\u201d, un espacio para aprender y recordar personajes importantes de diferentes culturas y civilizaciones. Todos los participantes de la Escuela de Filosof\u00eda, con gran entusiasmo, representaron a una Hipatia, Confucio, el mito de Bachue, juicio Osiriano, entre otros. Una velada espectacular de concurrida asistencia.<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Puesta en escena de \u201cEl encuentro con la Historia\u201d, un espacio para aprender y recordar personajes importantes de diferentes culturas y civilizaciones. Todos los participantes de la Escuela de Filosof\u00eda, [&hellip;]<\/p>\n","protected":false},"author":45,"featured_media":120862,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49],"tags":[],"class_list":["post-120898","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artisticas_artesanales","clearfix"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Encuentro con la Historia (Cali, Colombia) - Noticias de Nueva Acr\u00f3polis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/news.acropolis.org\/es\/2025\/encuentro-con-la-historia-cali-colombia\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"&quot;Encuentro con la Historia (Cali, Colombia) - Noticias de Nueva Acr\u00f3polis\" \/>\n<meta name=\"twitter:description\" content=\"Puesta en escena de \u201cEl encuentro con la Historia\u201d, un espacio para aprender y recordar personajes importantes de diferentes culturas y civilizaciones. Todos los participantes de la Escuela de Filosof\u00eda, [&hellip;]\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/12\/encuentro-con-la-historia-2025.png\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Colombia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/encuentro-con-la-historia-cali-colombia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/encuentro-con-la-historia-cali-colombia\\\/\"},\"author\":{\"name\":\"Colombia\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/34a71b82a591a112f5fef5f84e884328\"},\"headline\":\"&#8220;Encuentro con la Historia (Cali, Colombia)\",\"datePublished\":\"2025-12-28T09:16:32+00:00\",\"dateModified\":\"2025-12-28T10:20:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/encuentro-con-la-historia-cali-colombia\\\/\"},\"wordCount\":59,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/encuentro-con-la-historia-cali-colombia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/encuentro-con-la-historia-2025.png\",\"articleSection\":[\"Actividades Art\u00edsticas y Artesanales\"],\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/encuentro-con-la-historia-cali-colombia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/encuentro-con-la-historia-cali-colombia\\\/\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/encuentro-con-la-historia-cali-colombia\\\/\",\"name\":\"\\\"Encuentro con la Historia (Cali, Colombia) - Noticias de Nueva Acr\u00f3polis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/encuentro-con-la-historia-cali-colombia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/encuentro-con-la-historia-cali-colombia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/encuentro-con-la-historia-2025.png\",\"datePublished\":\"2025-12-28T09:16:32+00:00\",\"dateModified\":\"2025-12-28T10:20:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/34a71b82a591a112f5fef5f84e884328\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/encuentro-con-la-historia-cali-colombia\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/encuentro-con-la-historia-cali-colombia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/encuentro-con-la-historia-cali-colombia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/encuentro-con-la-historia-2025.png\",\"contentUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/encuentro-con-la-historia-2025.png\",\"width\":238,\"height\":336},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2025\\\/encuentro-con-la-historia-cali-colombia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Encuentro con la Historia (Cali, Colombia)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/\",\"name\":\"Noticias de Nueva Acr\u00f3polis\",\"description\":\"Actividades de la Organizaci\u00f3n Internacional Nueva Acr\u00f3polis\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/34a71b82a591a112f5fef5f84e884328\",\"name\":\"Colombia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/COL.png\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/COL.png\",\"contentUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/COL.png\",\"caption\":\"Colombia\"},\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/author\\\/oinacol\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Encuentro con la Historia (Cali, Colombia) - Noticias de Nueva Acr\u00f3polis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/news.acropolis.org\/es\/2025\/encuentro-con-la-historia-cali-colombia\/","twitter_card":"summary_large_image","twitter_title":"\"Encuentro con la Historia (Cali, Colombia) - Noticias de Nueva Acr\u00f3polis","twitter_description":"Puesta en escena de \u201cEl encuentro con la Historia\u201d, un espacio para aprender y recordar personajes importantes de diferentes culturas y civilizaciones. Todos los participantes de la Escuela de Filosof\u00eda, [&hellip;]","twitter_image":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/12\/encuentro-con-la-historia-2025.png","twitter_misc":{"Escrito por":"Colombia","Tiempo de lectura":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/news.acropolis.org\/es\/2025\/encuentro-con-la-historia-cali-colombia\/#article","isPartOf":{"@id":"https:\/\/news.acropolis.org\/es\/2025\/encuentro-con-la-historia-cali-colombia\/"},"author":{"name":"Colombia","@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/34a71b82a591a112f5fef5f84e884328"},"headline":"&#8220;Encuentro con la Historia (Cali, Colombia)","datePublished":"2025-12-28T09:16:32+00:00","dateModified":"2025-12-28T10:20:34+00:00","mainEntityOfPage":{"@id":"https:\/\/news.acropolis.org\/es\/2025\/encuentro-con-la-historia-cali-colombia\/"},"wordCount":59,"commentCount":0,"image":{"@id":"https:\/\/news.acropolis.org\/es\/2025\/encuentro-con-la-historia-cali-colombia\/#primaryimage"},"thumbnailUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/12\/encuentro-con-la-historia-2025.png","articleSection":["Actividades Art\u00edsticas y Artesanales"],"inLanguage":"es-ES","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/news.acropolis.org\/es\/2025\/encuentro-con-la-historia-cali-colombia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/news.acropolis.org\/es\/2025\/encuentro-con-la-historia-cali-colombia\/","url":"https:\/\/news.acropolis.org\/es\/2025\/encuentro-con-la-historia-cali-colombia\/","name":"\"Encuentro con la Historia (Cali, Colombia) - Noticias de Nueva Acr\u00f3polis","isPartOf":{"@id":"https:\/\/news.acropolis.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/news.acropolis.org\/es\/2025\/encuentro-con-la-historia-cali-colombia\/#primaryimage"},"image":{"@id":"https:\/\/news.acropolis.org\/es\/2025\/encuentro-con-la-historia-cali-colombia\/#primaryimage"},"thumbnailUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/12\/encuentro-con-la-historia-2025.png","datePublished":"2025-12-28T09:16:32+00:00","dateModified":"2025-12-28T10:20:34+00:00","author":{"@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/34a71b82a591a112f5fef5f84e884328"},"breadcrumb":{"@id":"https:\/\/news.acropolis.org\/es\/2025\/encuentro-con-la-historia-cali-colombia\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/news.acropolis.org\/es\/2025\/encuentro-con-la-historia-cali-colombia\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/news.acropolis.org\/es\/2025\/encuentro-con-la-historia-cali-colombia\/#primaryimage","url":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/12\/encuentro-con-la-historia-2025.png","contentUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2025\/12\/encuentro-con-la-historia-2025.png","width":238,"height":336},{"@type":"BreadcrumbList","@id":"https:\/\/news.acropolis.org\/es\/2025\/encuentro-con-la-historia-cali-colombia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/news.acropolis.org\/es\/"},{"@type":"ListItem","position":2,"name":"&#8220;Encuentro con la Historia (Cali, Colombia)"}]},{"@type":"WebSite","@id":"https:\/\/news.acropolis.org\/es\/#website","url":"https:\/\/news.acropolis.org\/es\/","name":"Noticias de Nueva Acr\u00f3polis","description":"Actividades de la Organizaci\u00f3n Internacional Nueva Acr\u00f3polis","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/news.acropolis.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/34a71b82a591a112f5fef5f84e884328","name":"Colombia","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/COL.png","url":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/COL.png","contentUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/COL.png","caption":"Colombia"},"url":"https:\/\/news.acropolis.org\/es\/author\/oinacol\/"}]}},"_links":{"self":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/120898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/comments?post=120898"}],"version-history":[{"count":5,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/120898\/revisions"}],"predecessor-version":[{"id":122711,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/120898\/revisions\/122711"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/media\/120862"}],"wp:attachment":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/media?parent=120898"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/categories?post=120898"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/tags?post=120898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}