{"id":125950,"date":"2026-03-13T11:30:31","date_gmt":"2026-03-13T10:30:31","guid":{"rendered":"https:\/\/news.acropolis.org\/?p=125950"},"modified":"2026-03-13T11:30:31","modified_gmt":"2026-03-13T10:30:31","slug":"c-g-jung-psicologia-desde-el-alma-seminario-de-fin-de-semana-bratislava-eslovaquia","status":"publish","type":"post","link":"https:\/\/news.acropolis.org\/es\/2026\/c-g-jung-psicologia-desde-el-alma-seminario-de-fin-de-semana-bratislava-eslovaquia\/","title":{"rendered":"C.G. Jung, psicolog\u00eda desde el alma. Seminario de fin de semana (Bratislava, Eslovaquia)"},"content":{"rendered":"<p>Durante un seminario de fin de semana, los participantes exploraron el mundo de la psique desde la perspectiva de Carl Gustav Jung. Este m\u00e9dico y psicoterapeuta suizo aport\u00f3 nuevos enfoques, conceptos y m\u00e9todos a la psicolog\u00eda que a\u00fan se utilizan en la pr\u00e1ctica. Fue el primero en utilizar t\u00e9rminos como introvertido y extrovertido, o el t\u00e9rmino &#8220;persona&#8221; para referirse a la m\u00e1scara tras la que se esconde nuestro yo esencial. A trav\u00e9s de historias de su vida y su extensa obra, podemos percibir el mensaje que nos dej\u00f3: una persona puede moldear su personalidad a lo largo de su vida, iluminar sus sombras internas y desarrollarse conscientemente.<\/p>\n<p><a href=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2026\/03\/IMG_0050.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-125908\" src=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2026\/03\/IMG_0050.jpg\" alt=\"\" width=\"705\" height=\"529\" srcset=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2026\/03\/IMG_0050.jpg 705w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2026\/03\/IMG_0050-300x225.jpg 300w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2026\/03\/IMG_0050-435x326.jpg 435w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2026\/03\/IMG_0050-80x60.jpg 80w\" sizes=\"auto, (max-width: 705px) 100vw, 705px\" \/><\/a><a href=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2026\/03\/IMG_0070.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-125911\" src=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2026\/03\/IMG_0070.jpg\" alt=\"\" width=\"604\" height=\"453\" srcset=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2026\/03\/IMG_0070.jpg 604w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2026\/03\/IMG_0070-300x225.jpg 300w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2026\/03\/IMG_0070-435x326.jpg 435w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2026\/03\/IMG_0070-80x60.jpg 80w\" sizes=\"auto, (max-width: 604px) 100vw, 604px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante un seminario de fin de semana, los participantes exploraron el mundo de la psique desde la perspectiva de Carl Gustav Jung. Este m\u00e9dico y psicoterapeuta suizo aport\u00f3 nuevos enfoques, [&hellip;]<\/p>\n","protected":false},"author":36,"featured_media":125910,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[47],"tags":[],"class_list":["post-125950","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actividades_educativas","clearfix"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C.G. Jung, psicolog\u00eda desde el alma. Seminario de fin de semana (Bratislava, Eslovaquia) - Noticias de Nueva Acr\u00f3polis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/news.acropolis.org\/es\/2026\/c-g-jung-psicologia-desde-el-alma-seminario-de-fin-de-semana-bratislava-eslovaquia\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"C.G. Jung, psicolog\u00eda desde el alma. Seminario de fin de semana (Bratislava, Eslovaquia) - Noticias de Nueva Acr\u00f3polis\" \/>\n<meta name=\"twitter:description\" content=\"Durante un seminario de fin de semana, los participantes exploraron el mundo de la psique desde la perspectiva de Carl Gustav Jung. Este m\u00e9dico y psicoterapeuta suizo aport\u00f3 nuevos enfoques, [&hellip;]\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2026\/03\/IMG_0050.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eslovaquia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2026\\\/c-g-jung-psicologia-desde-el-alma-seminario-de-fin-de-semana-bratislava-eslovaquia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2026\\\/c-g-jung-psicologia-desde-el-alma-seminario-de-fin-de-semana-bratislava-eslovaquia\\\/\"},\"author\":{\"name\":\"Slovakia\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/1a1f5a206a7bb7a0c85e469ae9463b6d\"},\"headline\":\"C.G. Jung, psicolog\u00eda desde el alma. Seminario de fin de semana (Bratislava, Eslovaquia)\",\"datePublished\":\"2026-03-13T10:30:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2026\\\/c-g-jung-psicologia-desde-el-alma-seminario-de-fin-de-semana-bratislava-eslovaquia\\\/\"},\"wordCount\":131,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2026\\\/c-g-jung-psicologia-desde-el-alma-seminario-de-fin-de-semana-bratislava-eslovaquia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/IMG_0050.jpg\",\"articleSection\":[\"Actividades Educativas\"],\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2026\\\/c-g-jung-psicologia-desde-el-alma-seminario-de-fin-de-semana-bratislava-eslovaquia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2026\\\/c-g-jung-psicologia-desde-el-alma-seminario-de-fin-de-semana-bratislava-eslovaquia\\\/\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2026\\\/c-g-jung-psicologia-desde-el-alma-seminario-de-fin-de-semana-bratislava-eslovaquia\\\/\",\"name\":\"C.G. Jung, psicolog\u00eda desde el alma. Seminario de fin de semana (Bratislava, Eslovaquia) - Noticias de Nueva Acr\u00f3polis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2026\\\/c-g-jung-psicologia-desde-el-alma-seminario-de-fin-de-semana-bratislava-eslovaquia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2026\\\/c-g-jung-psicologia-desde-el-alma-seminario-de-fin-de-semana-bratislava-eslovaquia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/IMG_0050.jpg\",\"datePublished\":\"2026-03-13T10:30:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/1a1f5a206a7bb7a0c85e469ae9463b6d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2026\\\/c-g-jung-psicologia-desde-el-alma-seminario-de-fin-de-semana-bratislava-eslovaquia\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2026\\\/c-g-jung-psicologia-desde-el-alma-seminario-de-fin-de-semana-bratislava-eslovaquia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2026\\\/c-g-jung-psicologia-desde-el-alma-seminario-de-fin-de-semana-bratislava-eslovaquia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/IMG_0050.jpg\",\"contentUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/IMG_0050.jpg\",\"width\":705,\"height\":529},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2026\\\/c-g-jung-psicologia-desde-el-alma-seminario-de-fin-de-semana-bratislava-eslovaquia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C.G. Jung, psicolog\u00eda desde el alma. Seminario de fin de semana (Bratislava, Eslovaquia)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/\",\"name\":\"Noticias de Nueva Acr\u00f3polis\",\"description\":\"Actividades de la Organizaci\u00f3n Internacional Nueva Acr\u00f3polis\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/1a1f5a206a7bb7a0c85e469ae9463b6d\",\"name\":\"Slovakia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/SVK.png\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/SVK.png\",\"contentUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/SVK.png\",\"caption\":\"Slovakia\"},\"sameAs\":[\"http:\\\/\\\/www.akropolis.sk\"],\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/author\\\/oinaesk\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C.G. Jung, psicolog\u00eda desde el alma. Seminario de fin de semana (Bratislava, Eslovaquia) - Noticias de Nueva Acr\u00f3polis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/news.acropolis.org\/es\/2026\/c-g-jung-psicologia-desde-el-alma-seminario-de-fin-de-semana-bratislava-eslovaquia\/","twitter_card":"summary_large_image","twitter_title":"C.G. Jung, psicolog\u00eda desde el alma. Seminario de fin de semana (Bratislava, Eslovaquia) - Noticias de Nueva Acr\u00f3polis","twitter_description":"Durante un seminario de fin de semana, los participantes exploraron el mundo de la psique desde la perspectiva de Carl Gustav Jung. Este m\u00e9dico y psicoterapeuta suizo aport\u00f3 nuevos enfoques, [&hellip;]","twitter_image":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2026\/03\/IMG_0050.jpg","twitter_misc":{"Escrito por":"Eslovaquia","Tiempo de lectura":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/news.acropolis.org\/es\/2026\/c-g-jung-psicologia-desde-el-alma-seminario-de-fin-de-semana-bratislava-eslovaquia\/#article","isPartOf":{"@id":"https:\/\/news.acropolis.org\/es\/2026\/c-g-jung-psicologia-desde-el-alma-seminario-de-fin-de-semana-bratislava-eslovaquia\/"},"author":{"name":"Slovakia","@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/1a1f5a206a7bb7a0c85e469ae9463b6d"},"headline":"C.G. Jung, psicolog\u00eda desde el alma. Seminario de fin de semana (Bratislava, Eslovaquia)","datePublished":"2026-03-13T10:30:31+00:00","mainEntityOfPage":{"@id":"https:\/\/news.acropolis.org\/es\/2026\/c-g-jung-psicologia-desde-el-alma-seminario-de-fin-de-semana-bratislava-eslovaquia\/"},"wordCount":131,"commentCount":0,"image":{"@id":"https:\/\/news.acropolis.org\/es\/2026\/c-g-jung-psicologia-desde-el-alma-seminario-de-fin-de-semana-bratislava-eslovaquia\/#primaryimage"},"thumbnailUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2026\/03\/IMG_0050.jpg","articleSection":["Actividades Educativas"],"inLanguage":"es-ES","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/news.acropolis.org\/es\/2026\/c-g-jung-psicologia-desde-el-alma-seminario-de-fin-de-semana-bratislava-eslovaquia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/news.acropolis.org\/es\/2026\/c-g-jung-psicologia-desde-el-alma-seminario-de-fin-de-semana-bratislava-eslovaquia\/","url":"https:\/\/news.acropolis.org\/es\/2026\/c-g-jung-psicologia-desde-el-alma-seminario-de-fin-de-semana-bratislava-eslovaquia\/","name":"C.G. Jung, psicolog\u00eda desde el alma. Seminario de fin de semana (Bratislava, Eslovaquia) - Noticias de Nueva Acr\u00f3polis","isPartOf":{"@id":"https:\/\/news.acropolis.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/news.acropolis.org\/es\/2026\/c-g-jung-psicologia-desde-el-alma-seminario-de-fin-de-semana-bratislava-eslovaquia\/#primaryimage"},"image":{"@id":"https:\/\/news.acropolis.org\/es\/2026\/c-g-jung-psicologia-desde-el-alma-seminario-de-fin-de-semana-bratislava-eslovaquia\/#primaryimage"},"thumbnailUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2026\/03\/IMG_0050.jpg","datePublished":"2026-03-13T10:30:31+00:00","author":{"@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/1a1f5a206a7bb7a0c85e469ae9463b6d"},"breadcrumb":{"@id":"https:\/\/news.acropolis.org\/es\/2026\/c-g-jung-psicologia-desde-el-alma-seminario-de-fin-de-semana-bratislava-eslovaquia\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/news.acropolis.org\/es\/2026\/c-g-jung-psicologia-desde-el-alma-seminario-de-fin-de-semana-bratislava-eslovaquia\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/news.acropolis.org\/es\/2026\/c-g-jung-psicologia-desde-el-alma-seminario-de-fin-de-semana-bratislava-eslovaquia\/#primaryimage","url":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2026\/03\/IMG_0050.jpg","contentUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2026\/03\/IMG_0050.jpg","width":705,"height":529},{"@type":"BreadcrumbList","@id":"https:\/\/news.acropolis.org\/es\/2026\/c-g-jung-psicologia-desde-el-alma-seminario-de-fin-de-semana-bratislava-eslovaquia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/news.acropolis.org\/es\/"},{"@type":"ListItem","position":2,"name":"C.G. Jung, psicolog\u00eda desde el alma. Seminario de fin de semana (Bratislava, Eslovaquia)"}]},{"@type":"WebSite","@id":"https:\/\/news.acropolis.org\/es\/#website","url":"https:\/\/news.acropolis.org\/es\/","name":"Noticias de Nueva Acr\u00f3polis","description":"Actividades de la Organizaci\u00f3n Internacional Nueva Acr\u00f3polis","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/news.acropolis.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/1a1f5a206a7bb7a0c85e469ae9463b6d","name":"Slovakia","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/SVK.png","url":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/SVK.png","contentUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/SVK.png","caption":"Slovakia"},"sameAs":["http:\/\/www.akropolis.sk"],"url":"https:\/\/news.acropolis.org\/es\/author\/oinaesk\/"}]}},"_links":{"self":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/125950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/comments?post=125950"}],"version-history":[{"count":1,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/125950\/revisions"}],"predecessor-version":[{"id":125951,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/125950\/revisions\/125951"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/media\/125910"}],"wp:attachment":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/media?parent=125950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/categories?post=125950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/tags?post=125950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}