{"id":58444,"date":"2021-04-03T21:57:19","date_gmt":"2021-04-03T19:57:19","guid":{"rendered":"https:\/\/news.acropolis.org\/2021\/los-caballeros-de-la-mesa-redonda-que-hay-detras-de-la-leyenda-rusia\/"},"modified":"2021-04-03T21:57:19","modified_gmt":"2021-04-03T19:57:19","slug":"los-caballeros-de-la-mesa-redonda-que-hay-detras-de-la-leyenda-rusia","status":"publish","type":"post","link":"https:\/\/news.acropolis.org\/es\/2021\/los-caballeros-de-la-mesa-redonda-que-hay-detras-de-la-leyenda-rusia\/","title":{"rendered":"&#8220;Los Caballeros de la Mesa Redonda, \u00bfQu\u00e9 hay detr\u00e1s de la leyenda?&#8221; (Rusia)"},"content":{"rendered":"<p>Europa siglo 12 dC. Durante varios siglos, sobre las ruinas del Imperio Romano, muchos peque\u00f1os estados est\u00e1n constantemente enfrentados entre s\u00ed. Robos, guerras, epidemias de las que mueren pueblos enteros. Tanto la cultura como las ciencias est\u00e1n en declive. Se olvidan muchos conocimientos sobre la estructura del mundo y del hombre. La gente lucha por sobrevivir.<\/p>\n<p>Y as\u00ed, en medio de la violencia y el olvido, surgen leyendas de nobles caballeros. Pasan todo el tiempo vagando y solo una vez al a\u00f1o se re\u00fanen en el Castillo de Camelot para contar sus aventuras y confirmar el derecho a sentarse en la Mesa Redonda. Cada historia atrae y fascina porque tiene un significado y un mensaje m\u00e1s profundos.<\/p>\n<p>Junto al p\u00fablico asistente, se analizaron algunos s\u00edmbolos y acciones de las leyendas desde un punto de vista especial: el interior del hombre y su propio camino. Con tal enfoque, resulta que todos los h\u00e9roes y dragones, el sabio Merl\u00edn y el rey son parte de nosotros. Por ejemplo, la Dama de la Edad Media era considerada un s\u00edmbolo del alma humana. Es interesante que la aparici\u00f3n de la Dama presagiara la haza\u00f1a de cada caballero. Otro ejemplo es que lograr una victoria requer\u00eda no solo fuerza y \u200b\u200bhabilidad para blandir un arma sino tambi\u00e9n alguna cualidad interior como compasi\u00f3n,\u00a0 etc.<\/p>\n<p>Despu\u00e9s del coloquio con los participantes, todos juntos bailaron una pieza medieval lenta para sentirse un poco como esos caballeros y damas.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/acropolis.org.ru\/img\/site\/image\/newsnum1399\/__2021-02-22__12-14-22.png\" alt=\"\u0420\u044b\u0446\u0430\u0440\u0438 \u041a\u0440\u0443\u0433\u043b\u043e\u0433\u043e \u0441\u0442\u043e\u043b\u0430. \u0427\u0442\u043e \u0445\u0440\u0430\u043d\u0438\u0442 \u043b\u0435\u0433\u0435\u043d\u0434\u0430?\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Europa siglo 12 dC. Durante varios siglos, sobre las ruinas del Imperio Romano, muchos peque\u00f1os estados est\u00e1n constantemente enfrentados entre s\u00ed. Robos, guerras, epidemias de las que mueren pueblos enteros. [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":58442,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[3454],"class_list":["post-58444","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actividades_culturales","tag-central-russia-es-4","clearfix"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Los Caballeros de la Mesa Redonda, \u00bfQu\u00e9 hay detr\u00e1s de la leyenda?&quot; (Rusia) - Noticias de Nueva Acr\u00f3polis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/news.acropolis.org\/es\/2021\/los-caballeros-de-la-mesa-redonda-que-hay-detras-de-la-leyenda-rusia\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"&quot;Los Caballeros de la Mesa Redonda, \u00bfQu\u00e9 hay detr\u00e1s de la leyenda?&quot; (Rusia) - Noticias de Nueva Acr\u00f3polis\" \/>\n<meta name=\"twitter:description\" content=\"Europa siglo 12 dC. Durante varios siglos, sobre las ruinas del Imperio Romano, muchos peque\u00f1os estados est\u00e1n constantemente enfrentados entre s\u00ed. Robos, guerras, epidemias de las que mueren pueblos enteros. [&hellip;]\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2021\/03\/russia.png\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rusia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2021\\\/los-caballeros-de-la-mesa-redonda-que-hay-detras-de-la-leyenda-rusia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2021\\\/los-caballeros-de-la-mesa-redonda-que-hay-detras-de-la-leyenda-rusia\\\/\"},\"author\":{\"name\":\"Russia\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/74e7c6f6312ead9b4e09301d7290e1b6\"},\"headline\":\"&#8220;Los Caballeros de la Mesa Redonda, \u00bfQu\u00e9 hay detr\u00e1s de la leyenda?&#8221; (Rusia)\",\"datePublished\":\"2021-04-03T19:57:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2021\\\/los-caballeros-de-la-mesa-redonda-que-hay-detras-de-la-leyenda-rusia\\\/\"},\"wordCount\":270,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2021\\\/los-caballeros-de-la-mesa-redonda-que-hay-detras-de-la-leyenda-rusia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/russia.png\",\"keywords\":[\"Central Russia\"],\"articleSection\":[\"Actividades Culturales\"],\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2021\\\/los-caballeros-de-la-mesa-redonda-que-hay-detras-de-la-leyenda-rusia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2021\\\/los-caballeros-de-la-mesa-redonda-que-hay-detras-de-la-leyenda-rusia\\\/\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2021\\\/los-caballeros-de-la-mesa-redonda-que-hay-detras-de-la-leyenda-rusia\\\/\",\"name\":\"\\\"Los Caballeros de la Mesa Redonda, \u00bfQu\u00e9 hay detr\u00e1s de la leyenda?\\\" (Rusia) - Noticias de Nueva Acr\u00f3polis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2021\\\/los-caballeros-de-la-mesa-redonda-que-hay-detras-de-la-leyenda-rusia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2021\\\/los-caballeros-de-la-mesa-redonda-que-hay-detras-de-la-leyenda-rusia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/russia.png\",\"datePublished\":\"2021-04-03T19:57:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/74e7c6f6312ead9b4e09301d7290e1b6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2021\\\/los-caballeros-de-la-mesa-redonda-que-hay-detras-de-la-leyenda-rusia\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2021\\\/los-caballeros-de-la-mesa-redonda-que-hay-detras-de-la-leyenda-rusia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2021\\\/los-caballeros-de-la-mesa-redonda-que-hay-detras-de-la-leyenda-rusia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/russia.png\",\"contentUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/russia.png\",\"width\":425,\"height\":322},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2021\\\/los-caballeros-de-la-mesa-redonda-que-hay-detras-de-la-leyenda-rusia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Los Caballeros de la Mesa Redonda, \u00bfQu\u00e9 hay detr\u00e1s de la leyenda?&#8221; (Rusia)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/\",\"name\":\"Noticias de Nueva Acr\u00f3polis\",\"description\":\"Actividades de la Organizaci\u00f3n Internacional Nueva Acr\u00f3polis\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/74e7c6f6312ead9b4e09301d7290e1b6\",\"name\":\"Russia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/RUS.png\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/RUS.png\",\"contentUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/RUS.png\",\"caption\":\"Russia\"},\"sameAs\":[\"https:\\\/\\\/acropolis.org.ru\\\/\"],\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/author\\\/oinarus\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Los Caballeros de la Mesa Redonda, \u00bfQu\u00e9 hay detr\u00e1s de la leyenda?\" (Rusia) - Noticias de Nueva Acr\u00f3polis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/news.acropolis.org\/es\/2021\/los-caballeros-de-la-mesa-redonda-que-hay-detras-de-la-leyenda-rusia\/","twitter_card":"summary_large_image","twitter_title":"\"Los Caballeros de la Mesa Redonda, \u00bfQu\u00e9 hay detr\u00e1s de la leyenda?\" (Rusia) - Noticias de Nueva Acr\u00f3polis","twitter_description":"Europa siglo 12 dC. Durante varios siglos, sobre las ruinas del Imperio Romano, muchos peque\u00f1os estados est\u00e1n constantemente enfrentados entre s\u00ed. Robos, guerras, epidemias de las que mueren pueblos enteros. [&hellip;]","twitter_image":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2021\/03\/russia.png","twitter_misc":{"Escrito por":"Rusia","Tiempo de lectura":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/news.acropolis.org\/es\/2021\/los-caballeros-de-la-mesa-redonda-que-hay-detras-de-la-leyenda-rusia\/#article","isPartOf":{"@id":"https:\/\/news.acropolis.org\/es\/2021\/los-caballeros-de-la-mesa-redonda-que-hay-detras-de-la-leyenda-rusia\/"},"author":{"name":"Russia","@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/74e7c6f6312ead9b4e09301d7290e1b6"},"headline":"&#8220;Los Caballeros de la Mesa Redonda, \u00bfQu\u00e9 hay detr\u00e1s de la leyenda?&#8221; (Rusia)","datePublished":"2021-04-03T19:57:19+00:00","mainEntityOfPage":{"@id":"https:\/\/news.acropolis.org\/es\/2021\/los-caballeros-de-la-mesa-redonda-que-hay-detras-de-la-leyenda-rusia\/"},"wordCount":270,"commentCount":0,"image":{"@id":"https:\/\/news.acropolis.org\/es\/2021\/los-caballeros-de-la-mesa-redonda-que-hay-detras-de-la-leyenda-rusia\/#primaryimage"},"thumbnailUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2021\/03\/russia.png","keywords":["Central Russia"],"articleSection":["Actividades Culturales"],"inLanguage":"es-ES","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/news.acropolis.org\/es\/2021\/los-caballeros-de-la-mesa-redonda-que-hay-detras-de-la-leyenda-rusia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/news.acropolis.org\/es\/2021\/los-caballeros-de-la-mesa-redonda-que-hay-detras-de-la-leyenda-rusia\/","url":"https:\/\/news.acropolis.org\/es\/2021\/los-caballeros-de-la-mesa-redonda-que-hay-detras-de-la-leyenda-rusia\/","name":"\"Los Caballeros de la Mesa Redonda, \u00bfQu\u00e9 hay detr\u00e1s de la leyenda?\" (Rusia) - Noticias de Nueva Acr\u00f3polis","isPartOf":{"@id":"https:\/\/news.acropolis.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/news.acropolis.org\/es\/2021\/los-caballeros-de-la-mesa-redonda-que-hay-detras-de-la-leyenda-rusia\/#primaryimage"},"image":{"@id":"https:\/\/news.acropolis.org\/es\/2021\/los-caballeros-de-la-mesa-redonda-que-hay-detras-de-la-leyenda-rusia\/#primaryimage"},"thumbnailUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2021\/03\/russia.png","datePublished":"2021-04-03T19:57:19+00:00","author":{"@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/74e7c6f6312ead9b4e09301d7290e1b6"},"breadcrumb":{"@id":"https:\/\/news.acropolis.org\/es\/2021\/los-caballeros-de-la-mesa-redonda-que-hay-detras-de-la-leyenda-rusia\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/news.acropolis.org\/es\/2021\/los-caballeros-de-la-mesa-redonda-que-hay-detras-de-la-leyenda-rusia\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/news.acropolis.org\/es\/2021\/los-caballeros-de-la-mesa-redonda-que-hay-detras-de-la-leyenda-rusia\/#primaryimage","url":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2021\/03\/russia.png","contentUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2021\/03\/russia.png","width":425,"height":322},{"@type":"BreadcrumbList","@id":"https:\/\/news.acropolis.org\/es\/2021\/los-caballeros-de-la-mesa-redonda-que-hay-detras-de-la-leyenda-rusia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/news.acropolis.org\/es\/"},{"@type":"ListItem","position":2,"name":"&#8220;Los Caballeros de la Mesa Redonda, \u00bfQu\u00e9 hay detr\u00e1s de la leyenda?&#8221; (Rusia)"}]},{"@type":"WebSite","@id":"https:\/\/news.acropolis.org\/es\/#website","url":"https:\/\/news.acropolis.org\/es\/","name":"Noticias de Nueva Acr\u00f3polis","description":"Actividades de la Organizaci\u00f3n Internacional Nueva Acr\u00f3polis","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/news.acropolis.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/74e7c6f6312ead9b4e09301d7290e1b6","name":"Russia","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/RUS.png","url":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/RUS.png","contentUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/RUS.png","caption":"Russia"},"sameAs":["https:\/\/acropolis.org.ru\/"],"url":"https:\/\/news.acropolis.org\/es\/author\/oinarus\/"}]}},"_links":{"self":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/58444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/comments?post=58444"}],"version-history":[{"count":0,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/58444\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/media\/58442"}],"wp:attachment":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/media?parent=58444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/categories?post=58444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/tags?post=58444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}