{"id":6503,"date":"2013-11-27T19:19:31","date_gmt":"2013-11-27T18:19:31","guid":{"rendered":"https:\/\/news.acropolis.org\/?p=6503"},"modified":"2014-01-04T09:32:08","modified_gmt":"2014-01-04T08:32:08","slug":"2400-anos-de-la-fundacion-de-la-academia-de-platon-santos-brasil","status":"publish","type":"post","link":"https:\/\/news.acropolis.org\/es\/2013\/2400-anos-de-la-fundacion-de-la-academia-de-platon-santos-brasil\/","title":{"rendered":"2400 a\u00f1os de la fundaci\u00f3n de la Academia de Plat\u00f3n (Santos, Brasil)"},"content":{"rendered":"<p><a href=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2013\/11\/Plat\u00e3o01.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-6505\" alt=\"Plat\u00e3o01\" src=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2013\/11\/Plat\u00e3o01-300x163.jpg\" width=\"270\" height=\"147\" srcset=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2013\/11\/Plat\u00e3o01-300x163.jpg 300w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2013\/11\/Plat\u00e3o01.jpg 1000w\" sizes=\"auto, (max-width: 270px) 100vw, 270px\" \/><\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-6509 alignright\" alt=\"Plat\u00e3o05\" src=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2013\/11\/Plat\u00e3o05-300x200.jpg\" width=\"240\" height=\"160\" srcset=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2013\/11\/Plat\u00e3o05-300x200.jpg 300w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2013\/11\/Plat\u00e3o05.jpg 1000w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/><\/p>\n<p><a style=\"font-size: 13px; line-height: 19px;\" href=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2013\/11\/Plat\u00e3o04.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-6508\" alt=\"Plat\u00e3o04\" src=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2013\/11\/Plat\u00e3o04-300x137.jpg\" width=\"270\" height=\"123\" srcset=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2013\/11\/Plat\u00e3o04-300x137.jpg 300w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2013\/11\/Plat\u00e3o04.jpg 1000w\" sizes=\"auto, (max-width: 270px) 100vw, 270px\" \/><\/a><\/p>\n<p>Nueva Acr\u00f3polis en Brasil promueve varios actos para conmemorar los 2400 a\u00f1os de la fundaci\u00f3n de la Academia de Plat\u00f3n. Conferencias, grupos de lectura de los mitos plat\u00f3nicos y debates sobre algunos fragmentos de sus obras literarias, as\u00ed\u00a0como el intercambio justo de libros fueron algunas de las actividades del programa en el que los ni\u00f1os tuvieron su especial participaci\u00f3n. En las conferencias se abord\u00f3 el legado de la Academia\u00a0plat\u00f3nica y su influencia en el pensamiento actual sobre todo para la civilizaci\u00f3n occidental. Los c\u00edrculos de lectura trataron de compartir los mitos desarrollados en sus obras a trav\u00e9s de la interpretaci\u00f3n literaria seguida de un debate con los asistentes y la representaci\u00f3n del Mito de la caverna por el teatro de sombras. El objetivo de esta iniciativa fue mostrar c\u00f3mo el pensamiento plat\u00f3nico\u00a0ha inspirado muchas corrientes hist\u00f3ricas y numerosas directrices innovadoras y creativas.<\/p>\n<p><a href=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2013\/11\/Plat\u00e3o03.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-6507 alignright\" alt=\"Plat\u00e3o03\" src=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2013\/11\/Plat\u00e3o03-300x187.jpg\" width=\"240\" height=\"150\" srcset=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2013\/11\/Plat\u00e3o03-300x187.jpg 300w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2013\/11\/Plat\u00e3o03.jpg 1000w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nueva Acr\u00f3polis en Brasil promueve varios actos para conmemorar los 2400 a\u00f1os de la fundaci\u00f3n de la Academia de Plat\u00f3n. Conferencias, grupos de lectura de los mitos plat\u00f3nicos y debates [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":6505,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[51],"tags":[],"class_list":["post-6503","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-promocion_filosofia","clearfix"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>2400 a\u00f1os de la fundaci\u00f3n de la Academia de Plat\u00f3n (Santos, Brasil) - Noticias de Nueva Acr\u00f3polis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/news.acropolis.org\/es\/2013\/2400-anos-de-la-fundacion-de-la-academia-de-platon-santos-brasil\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"2400 a\u00f1os de la fundaci\u00f3n de la Academia de Plat\u00f3n (Santos, Brasil) - Noticias de Nueva Acr\u00f3polis\" \/>\n<meta name=\"twitter:description\" content=\"Nueva Acr\u00f3polis en Brasil promueve varios actos para conmemorar los 2400 a\u00f1os de la fundaci\u00f3n de la Academia de Plat\u00f3n. Conferencias, grupos de lectura de los mitos plat\u00f3nicos y debates [&hellip;]\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2013\/11\/Plat\u00e3o01.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Brasil\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2013\\\/2400-anos-de-la-fundacion-de-la-academia-de-platon-santos-brasil\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2013\\\/2400-anos-de-la-fundacion-de-la-academia-de-platon-santos-brasil\\\/\"},\"author\":{\"name\":\"Brazil\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/7ebe516505cf9031162552b6f779c7b1\"},\"headline\":\"2400 a\u00f1os de la fundaci\u00f3n de la Academia de Plat\u00f3n (Santos, Brasil)\",\"datePublished\":\"2013-11-27T18:19:31+00:00\",\"dateModified\":\"2014-01-04T08:32:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2013\\\/2400-anos-de-la-fundacion-de-la-academia-de-platon-santos-brasil\\\/\"},\"wordCount\":175,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2013\\\/2400-anos-de-la-fundacion-de-la-academia-de-platon-santos-brasil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/Plat\u00e3o01.jpg\",\"articleSection\":[\"Promoci\u00f3n de la Filosof\u00eda\"],\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2013\\\/2400-anos-de-la-fundacion-de-la-academia-de-platon-santos-brasil\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2013\\\/2400-anos-de-la-fundacion-de-la-academia-de-platon-santos-brasil\\\/\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2013\\\/2400-anos-de-la-fundacion-de-la-academia-de-platon-santos-brasil\\\/\",\"name\":\"2400 a\u00f1os de la fundaci\u00f3n de la Academia de Plat\u00f3n (Santos, Brasil) - Noticias de Nueva Acr\u00f3polis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2013\\\/2400-anos-de-la-fundacion-de-la-academia-de-platon-santos-brasil\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2013\\\/2400-anos-de-la-fundacion-de-la-academia-de-platon-santos-brasil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/Plat\u00e3o01.jpg\",\"datePublished\":\"2013-11-27T18:19:31+00:00\",\"dateModified\":\"2014-01-04T08:32:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/7ebe516505cf9031162552b6f779c7b1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2013\\\/2400-anos-de-la-fundacion-de-la-academia-de-platon-santos-brasil\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2013\\\/2400-anos-de-la-fundacion-de-la-academia-de-platon-santos-brasil\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2013\\\/2400-anos-de-la-fundacion-de-la-academia-de-platon-santos-brasil\\\/#primaryimage\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/Plat\u00e3o01.jpg\",\"contentUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/Plat\u00e3o01.jpg\",\"width\":1000,\"height\":546},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2013\\\/2400-anos-de-la-fundacion-de-la-academia-de-platon-santos-brasil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"2400 a\u00f1os de la fundaci\u00f3n de la Academia de Plat\u00f3n (Santos, Brasil)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/\",\"name\":\"Noticias de Nueva Acr\u00f3polis\",\"description\":\"Actividades de la Organizaci\u00f3n Internacional Nueva Acr\u00f3polis\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/7ebe516505cf9031162552b6f779c7b1\",\"name\":\"Brazil\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/BRA.png\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/BRA.png\",\"contentUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/BRA.png\",\"caption\":\"Brazil\"},\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/author\\\/oinab\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2400 a\u00f1os de la fundaci\u00f3n de la Academia de Plat\u00f3n (Santos, Brasil) - Noticias de Nueva Acr\u00f3polis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/news.acropolis.org\/es\/2013\/2400-anos-de-la-fundacion-de-la-academia-de-platon-santos-brasil\/","twitter_card":"summary_large_image","twitter_title":"2400 a\u00f1os de la fundaci\u00f3n de la Academia de Plat\u00f3n (Santos, Brasil) - Noticias de Nueva Acr\u00f3polis","twitter_description":"Nueva Acr\u00f3polis en Brasil promueve varios actos para conmemorar los 2400 a\u00f1os de la fundaci\u00f3n de la Academia de Plat\u00f3n. Conferencias, grupos de lectura de los mitos plat\u00f3nicos y debates [&hellip;]","twitter_image":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2013\/11\/Plat\u00e3o01.jpg","twitter_misc":{"Escrito por":"Brasil","Tiempo de lectura":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/news.acropolis.org\/es\/2013\/2400-anos-de-la-fundacion-de-la-academia-de-platon-santos-brasil\/#article","isPartOf":{"@id":"https:\/\/news.acropolis.org\/es\/2013\/2400-anos-de-la-fundacion-de-la-academia-de-platon-santos-brasil\/"},"author":{"name":"Brazil","@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/7ebe516505cf9031162552b6f779c7b1"},"headline":"2400 a\u00f1os de la fundaci\u00f3n de la Academia de Plat\u00f3n (Santos, Brasil)","datePublished":"2013-11-27T18:19:31+00:00","dateModified":"2014-01-04T08:32:08+00:00","mainEntityOfPage":{"@id":"https:\/\/news.acropolis.org\/es\/2013\/2400-anos-de-la-fundacion-de-la-academia-de-platon-santos-brasil\/"},"wordCount":175,"commentCount":0,"image":{"@id":"https:\/\/news.acropolis.org\/es\/2013\/2400-anos-de-la-fundacion-de-la-academia-de-platon-santos-brasil\/#primaryimage"},"thumbnailUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2013\/11\/Plat\u00e3o01.jpg","articleSection":["Promoci\u00f3n de la Filosof\u00eda"],"inLanguage":"es-ES","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/news.acropolis.org\/es\/2013\/2400-anos-de-la-fundacion-de-la-academia-de-platon-santos-brasil\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/news.acropolis.org\/es\/2013\/2400-anos-de-la-fundacion-de-la-academia-de-platon-santos-brasil\/","url":"https:\/\/news.acropolis.org\/es\/2013\/2400-anos-de-la-fundacion-de-la-academia-de-platon-santos-brasil\/","name":"2400 a\u00f1os de la fundaci\u00f3n de la Academia de Plat\u00f3n (Santos, Brasil) - Noticias de Nueva Acr\u00f3polis","isPartOf":{"@id":"https:\/\/news.acropolis.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/news.acropolis.org\/es\/2013\/2400-anos-de-la-fundacion-de-la-academia-de-platon-santos-brasil\/#primaryimage"},"image":{"@id":"https:\/\/news.acropolis.org\/es\/2013\/2400-anos-de-la-fundacion-de-la-academia-de-platon-santos-brasil\/#primaryimage"},"thumbnailUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2013\/11\/Plat\u00e3o01.jpg","datePublished":"2013-11-27T18:19:31+00:00","dateModified":"2014-01-04T08:32:08+00:00","author":{"@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/7ebe516505cf9031162552b6f779c7b1"},"breadcrumb":{"@id":"https:\/\/news.acropolis.org\/es\/2013\/2400-anos-de-la-fundacion-de-la-academia-de-platon-santos-brasil\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/news.acropolis.org\/es\/2013\/2400-anos-de-la-fundacion-de-la-academia-de-platon-santos-brasil\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/news.acropolis.org\/es\/2013\/2400-anos-de-la-fundacion-de-la-academia-de-platon-santos-brasil\/#primaryimage","url":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2013\/11\/Plat\u00e3o01.jpg","contentUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2013\/11\/Plat\u00e3o01.jpg","width":1000,"height":546},{"@type":"BreadcrumbList","@id":"https:\/\/news.acropolis.org\/es\/2013\/2400-anos-de-la-fundacion-de-la-academia-de-platon-santos-brasil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/news.acropolis.org\/es\/"},{"@type":"ListItem","position":2,"name":"2400 a\u00f1os de la fundaci\u00f3n de la Academia de Plat\u00f3n (Santos, Brasil)"}]},{"@type":"WebSite","@id":"https:\/\/news.acropolis.org\/es\/#website","url":"https:\/\/news.acropolis.org\/es\/","name":"Noticias de Nueva Acr\u00f3polis","description":"Actividades de la Organizaci\u00f3n Internacional Nueva Acr\u00f3polis","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/news.acropolis.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/7ebe516505cf9031162552b6f779c7b1","name":"Brazil","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/BRA.png","url":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/BRA.png","contentUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/BRA.png","caption":"Brazil"},"url":"https:\/\/news.acropolis.org\/es\/author\/oinab\/"}]}},"_links":{"self":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/6503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/comments?post=6503"}],"version-history":[{"count":5,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/6503\/revisions"}],"predecessor-version":[{"id":6684,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/6503\/revisions\/6684"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/media\/6505"}],"wp:attachment":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/media?parent=6503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/categories?post=6503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/tags?post=6503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}