{"id":78073,"date":"2022-12-18T13:58:01","date_gmt":"2022-12-18T12:58:01","guid":{"rendered":"https:\/\/news.acropolis.org\/2022\/dia-internacional-para-la-eliminacion-de-la-violencia-contra-la-mujer-presentacion-del-libro-violencia-contra-la-mujer-verona-italia\/"},"modified":"2022-12-18T13:58:01","modified_gmt":"2022-12-18T12:58:01","slug":"dia-internacional-para-la-eliminacion-de-la-violencia-contra-la-mujer-presentacion-del-libro-violencia-contra-la-mujer-verona-italia","status":"publish","type":"post","link":"https:\/\/news.acropolis.org\/es\/2022\/dia-internacional-para-la-eliminacion-de-la-violencia-contra-la-mujer-presentacion-del-libro-violencia-contra-la-mujer-verona-italia\/","title":{"rendered":"D\u00eda Internacional para la Eliminaci\u00f3n de la Violencia contra la Mujer: presentaci\u00f3n del libro &#8220;Violencia contra la mujer&#8221; (Verona, Italia)"},"content":{"rendered":"<p>Con motivo del D\u00eda Internacional para la Eliminaci\u00f3n de la Violencia contra la Mujer, Nueva Acr\u00f3polis de Verona organiz\u00f3 una iniciativa titulada &#8220;Lo visible y lo invisible. La importancia de la educaci\u00f3n&#8221;.<\/p>\n<p>El pedagogo, trabajador social y voluntario de Nueva Acr\u00f3polis Domenico Grillo present\u00f3 su nuevo libro &#8220;La violencia contra la mujer. Educar a los hombres para la no violencia contra la mujer. \u00bfEs necesario y posible?&#8221;, acompa\u00f1ado por la profesora y voluntaria Stefania Giusi Italia. El objetivo de la presentaci\u00f3n fue informar, hacer reflexionar y dialogar con el p\u00fablico de mujeres y hombres sobre qu\u00e9 significa la violencia, cu\u00e1les son sus formas y por qu\u00e9 est\u00e1 tan arraigada en nuestra sociedad.<\/p>\n<p>El libro y su autor quieren proponer una soluci\u00f3n para &#8216;prevenir&#8217; en lugar de &#8216;curar&#8217;: la educaci\u00f3n. La educaci\u00f3n como forma de formar hombres y mujeres conscientes que no recurran a la violencia. Hay soluci\u00f3n, y el primer paso para salir de esto es tomar conciencia de sufrir o actuar con violencia. Educar como propuesta para ofrecer la oportunidad de conocerse a uno mismo y al mundo que nos rodea, tal como lo hace la Filosof\u00eda, motor y principio fundacional de Nueva Acr\u00f3polis, invit\u00e1ndonos a luchar contra las faltas y la ignorancia para vivir los m\u00e1s altos valores del ser. humano.<\/p>\n<p>La actividad se realiz\u00f3 en colaboraci\u00f3n con la Asociaci\u00f3n Le Fate Onlus y el Municipio de Verona.<\/p>\n<p><a href=\"https:\/\/news.acropolis.org\/2022\/international-day-for-the-elimination-of-violence-against-women-presentation-of-the-book-violence-against-women-verona-italy\/donne222-min\/\" rel=\"attachment wp-att-77810\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-77810 size-large\" src=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2022\/12\/DONNE222-min-1024x670.jpg\" alt=\"\" width=\"1024\" height=\"670\" srcset=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2022\/12\/DONNE222-min-1024x670.jpg 1024w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2022\/12\/DONNE222-min-300x196.jpg 300w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2022\/12\/DONNE222-min-768x502.jpg 768w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2022\/12\/DONNE222-min-1536x1005.jpg 1536w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2022\/12\/DONNE222-min-2048x1340.jpg 2048w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2022\/12\/DONNE222-min-730x478.jpg 730w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2022\/12\/DONNE222-min-435x285.jpg 435w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2022\/12\/DONNE223-min-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-77813 size-medium\" src=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2022\/12\/DONNE223-min-300x145.jpg\" alt=\"\" width=\"300\" height=\"145\" srcset=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2022\/12\/DONNE223-min-300x145.jpg 300w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2022\/12\/DONNE223-min-1024x494.jpg 1024w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2022\/12\/DONNE223-min-768x371.jpg 768w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2022\/12\/DONNE223-min-1536x741.jpg 1536w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2022\/12\/DONNE223-min-2048x989.jpg 2048w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2022\/12\/DONNE223-min-730x352.jpg 730w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2022\/12\/DONNE223-min-435x210.jpg 435w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2022\/12\/DONNE22-min.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-77816 size-medium\" src=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2022\/12\/DONNE22-min-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2022\/12\/DONNE22-min-300x300.jpg 300w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2022\/12\/DONNE22-min-1024x1024.jpg 1024w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2022\/12\/DONNE22-min-150x150.jpg 150w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2022\/12\/DONNE22-min-768x768.jpg 768w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2022\/12\/DONNE22-min-1536x1536.jpg 1536w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2022\/12\/DONNE22-min-730x730.jpg 730w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2022\/12\/DONNE22-min-435x435.jpg 435w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2022\/12\/DONNE22-min-24x24.jpg 24w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2022\/12\/DONNE22-min-48x48.jpg 48w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2022\/12\/DONNE22-min-96x96.jpg 96w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2022\/12\/DONNE22-min.jpg 1799w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con motivo del D\u00eda Internacional para la Eliminaci\u00f3n de la Violencia contra la Mujer, Nueva Acr\u00f3polis de Verona organiz\u00f3 una iniciativa titulada &#8220;Lo visible y lo invisible. La importancia de [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":77810,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[47],"tags":[],"class_list":["post-78073","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actividades_educativas","clearfix"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00eda Internacional para la Eliminaci\u00f3n de la Violencia contra la Mujer: presentaci\u00f3n del libro &quot;Violencia contra la mujer&quot; (Verona, Italia) - Noticias de Nueva Acr\u00f3polis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/news.acropolis.org\/es\/2022\/dia-internacional-para-la-eliminacion-de-la-violencia-contra-la-mujer-presentacion-del-libro-violencia-contra-la-mujer-verona-italia\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"D\u00eda Internacional para la Eliminaci\u00f3n de la Violencia contra la Mujer: presentaci\u00f3n del libro &quot;Violencia contra la mujer&quot; (Verona, Italia) - Noticias de Nueva Acr\u00f3polis\" \/>\n<meta name=\"twitter:description\" content=\"Con motivo del D\u00eda Internacional para la Eliminaci\u00f3n de la Violencia contra la Mujer, Nueva Acr\u00f3polis de Verona organiz\u00f3 una iniciativa titulada &#8220;Lo visible y lo invisible. La importancia de [&hellip;]\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2022\/12\/DONNE222-min.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Italia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2022\\\/dia-internacional-para-la-eliminacion-de-la-violencia-contra-la-mujer-presentacion-del-libro-violencia-contra-la-mujer-verona-italia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2022\\\/dia-internacional-para-la-eliminacion-de-la-violencia-contra-la-mujer-presentacion-del-libro-violencia-contra-la-mujer-verona-italia\\\/\"},\"author\":{\"name\":\"Italy\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/74bba08497f15fb667c16a1bb79b9711\"},\"headline\":\"D\u00eda Internacional para la Eliminaci\u00f3n de la Violencia contra la Mujer: presentaci\u00f3n del libro &#8220;Violencia contra la mujer&#8221; (Verona, Italia)\",\"datePublished\":\"2022-12-18T12:58:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2022\\\/dia-internacional-para-la-eliminacion-de-la-violencia-contra-la-mujer-presentacion-del-libro-violencia-contra-la-mujer-verona-italia\\\/\"},\"wordCount\":272,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2022\\\/dia-internacional-para-la-eliminacion-de-la-violencia-contra-la-mujer-presentacion-del-libro-violencia-contra-la-mujer-verona-italia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/DONNE222-min.jpg\",\"articleSection\":[\"Actividades Educativas\"],\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2022\\\/dia-internacional-para-la-eliminacion-de-la-violencia-contra-la-mujer-presentacion-del-libro-violencia-contra-la-mujer-verona-italia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2022\\\/dia-internacional-para-la-eliminacion-de-la-violencia-contra-la-mujer-presentacion-del-libro-violencia-contra-la-mujer-verona-italia\\\/\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2022\\\/dia-internacional-para-la-eliminacion-de-la-violencia-contra-la-mujer-presentacion-del-libro-violencia-contra-la-mujer-verona-italia\\\/\",\"name\":\"D\u00eda Internacional para la Eliminaci\u00f3n de la Violencia contra la Mujer: presentaci\u00f3n del libro \\\"Violencia contra la mujer\\\" (Verona, Italia) - Noticias de Nueva Acr\u00f3polis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2022\\\/dia-internacional-para-la-eliminacion-de-la-violencia-contra-la-mujer-presentacion-del-libro-violencia-contra-la-mujer-verona-italia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2022\\\/dia-internacional-para-la-eliminacion-de-la-violencia-contra-la-mujer-presentacion-del-libro-violencia-contra-la-mujer-verona-italia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/DONNE222-min.jpg\",\"datePublished\":\"2022-12-18T12:58:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/74bba08497f15fb667c16a1bb79b9711\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2022\\\/dia-internacional-para-la-eliminacion-de-la-violencia-contra-la-mujer-presentacion-del-libro-violencia-contra-la-mujer-verona-italia\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2022\\\/dia-internacional-para-la-eliminacion-de-la-violencia-contra-la-mujer-presentacion-del-libro-violencia-contra-la-mujer-verona-italia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2022\\\/dia-internacional-para-la-eliminacion-de-la-violencia-contra-la-mujer-presentacion-del-libro-violencia-contra-la-mujer-verona-italia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/DONNE222-min.jpg\",\"contentUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/DONNE222-min.jpg\",\"width\":2531,\"height\":1656},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2022\\\/dia-internacional-para-la-eliminacion-de-la-violencia-contra-la-mujer-presentacion-del-libro-violencia-contra-la-mujer-verona-italia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00eda Internacional para la Eliminaci\u00f3n de la Violencia contra la Mujer: presentaci\u00f3n del libro &#8220;Violencia contra la mujer&#8221; (Verona, Italia)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/\",\"name\":\"Noticias de Nueva Acr\u00f3polis\",\"description\":\"Actividades de la Organizaci\u00f3n Internacional Nueva Acr\u00f3polis\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/74bba08497f15fb667c16a1bb79b9711\",\"name\":\"Italy\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/ITA.png\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/ITA.png\",\"contentUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/ITA.png\",\"caption\":\"Italy\"},\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/author\\\/oinai\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00eda Internacional para la Eliminaci\u00f3n de la Violencia contra la Mujer: presentaci\u00f3n del libro \"Violencia contra la mujer\" (Verona, Italia) - Noticias de Nueva Acr\u00f3polis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/news.acropolis.org\/es\/2022\/dia-internacional-para-la-eliminacion-de-la-violencia-contra-la-mujer-presentacion-del-libro-violencia-contra-la-mujer-verona-italia\/","twitter_card":"summary_large_image","twitter_title":"D\u00eda Internacional para la Eliminaci\u00f3n de la Violencia contra la Mujer: presentaci\u00f3n del libro \"Violencia contra la mujer\" (Verona, Italia) - Noticias de Nueva Acr\u00f3polis","twitter_description":"Con motivo del D\u00eda Internacional para la Eliminaci\u00f3n de la Violencia contra la Mujer, Nueva Acr\u00f3polis de Verona organiz\u00f3 una iniciativa titulada &#8220;Lo visible y lo invisible. La importancia de [&hellip;]","twitter_image":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2022\/12\/DONNE222-min.jpg","twitter_misc":{"Escrito por":"Italia","Tiempo de lectura":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/news.acropolis.org\/es\/2022\/dia-internacional-para-la-eliminacion-de-la-violencia-contra-la-mujer-presentacion-del-libro-violencia-contra-la-mujer-verona-italia\/#article","isPartOf":{"@id":"https:\/\/news.acropolis.org\/es\/2022\/dia-internacional-para-la-eliminacion-de-la-violencia-contra-la-mujer-presentacion-del-libro-violencia-contra-la-mujer-verona-italia\/"},"author":{"name":"Italy","@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/74bba08497f15fb667c16a1bb79b9711"},"headline":"D\u00eda Internacional para la Eliminaci\u00f3n de la Violencia contra la Mujer: presentaci\u00f3n del libro &#8220;Violencia contra la mujer&#8221; (Verona, Italia)","datePublished":"2022-12-18T12:58:01+00:00","mainEntityOfPage":{"@id":"https:\/\/news.acropolis.org\/es\/2022\/dia-internacional-para-la-eliminacion-de-la-violencia-contra-la-mujer-presentacion-del-libro-violencia-contra-la-mujer-verona-italia\/"},"wordCount":272,"commentCount":0,"image":{"@id":"https:\/\/news.acropolis.org\/es\/2022\/dia-internacional-para-la-eliminacion-de-la-violencia-contra-la-mujer-presentacion-del-libro-violencia-contra-la-mujer-verona-italia\/#primaryimage"},"thumbnailUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2022\/12\/DONNE222-min.jpg","articleSection":["Actividades Educativas"],"inLanguage":"es-ES","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/news.acropolis.org\/es\/2022\/dia-internacional-para-la-eliminacion-de-la-violencia-contra-la-mujer-presentacion-del-libro-violencia-contra-la-mujer-verona-italia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/news.acropolis.org\/es\/2022\/dia-internacional-para-la-eliminacion-de-la-violencia-contra-la-mujer-presentacion-del-libro-violencia-contra-la-mujer-verona-italia\/","url":"https:\/\/news.acropolis.org\/es\/2022\/dia-internacional-para-la-eliminacion-de-la-violencia-contra-la-mujer-presentacion-del-libro-violencia-contra-la-mujer-verona-italia\/","name":"D\u00eda Internacional para la Eliminaci\u00f3n de la Violencia contra la Mujer: presentaci\u00f3n del libro \"Violencia contra la mujer\" (Verona, Italia) - Noticias de Nueva Acr\u00f3polis","isPartOf":{"@id":"https:\/\/news.acropolis.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/news.acropolis.org\/es\/2022\/dia-internacional-para-la-eliminacion-de-la-violencia-contra-la-mujer-presentacion-del-libro-violencia-contra-la-mujer-verona-italia\/#primaryimage"},"image":{"@id":"https:\/\/news.acropolis.org\/es\/2022\/dia-internacional-para-la-eliminacion-de-la-violencia-contra-la-mujer-presentacion-del-libro-violencia-contra-la-mujer-verona-italia\/#primaryimage"},"thumbnailUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2022\/12\/DONNE222-min.jpg","datePublished":"2022-12-18T12:58:01+00:00","author":{"@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/74bba08497f15fb667c16a1bb79b9711"},"breadcrumb":{"@id":"https:\/\/news.acropolis.org\/es\/2022\/dia-internacional-para-la-eliminacion-de-la-violencia-contra-la-mujer-presentacion-del-libro-violencia-contra-la-mujer-verona-italia\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/news.acropolis.org\/es\/2022\/dia-internacional-para-la-eliminacion-de-la-violencia-contra-la-mujer-presentacion-del-libro-violencia-contra-la-mujer-verona-italia\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/news.acropolis.org\/es\/2022\/dia-internacional-para-la-eliminacion-de-la-violencia-contra-la-mujer-presentacion-del-libro-violencia-contra-la-mujer-verona-italia\/#primaryimage","url":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2022\/12\/DONNE222-min.jpg","contentUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2022\/12\/DONNE222-min.jpg","width":2531,"height":1656},{"@type":"BreadcrumbList","@id":"https:\/\/news.acropolis.org\/es\/2022\/dia-internacional-para-la-eliminacion-de-la-violencia-contra-la-mujer-presentacion-del-libro-violencia-contra-la-mujer-verona-italia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/news.acropolis.org\/es\/"},{"@type":"ListItem","position":2,"name":"D\u00eda Internacional para la Eliminaci\u00f3n de la Violencia contra la Mujer: presentaci\u00f3n del libro &#8220;Violencia contra la mujer&#8221; (Verona, Italia)"}]},{"@type":"WebSite","@id":"https:\/\/news.acropolis.org\/es\/#website","url":"https:\/\/news.acropolis.org\/es\/","name":"Noticias de Nueva Acr\u00f3polis","description":"Actividades de la Organizaci\u00f3n Internacional Nueva Acr\u00f3polis","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/news.acropolis.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/74bba08497f15fb667c16a1bb79b9711","name":"Italy","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/ITA.png","url":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/ITA.png","contentUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/ITA.png","caption":"Italy"},"url":"https:\/\/news.acropolis.org\/es\/author\/oinai\/"}]}},"_links":{"self":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/78073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/comments?post=78073"}],"version-history":[{"count":0,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/78073\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/media\/77810"}],"wp:attachment":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/media?parent=78073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/categories?post=78073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/tags?post=78073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}