{"id":82976,"date":"2023-05-04T18:05:24","date_gmt":"2023-05-04T16:05:24","guid":{"rendered":"https:\/\/news.acropolis.org\/2023\/taller-de-arqueologia-praga-republica-checa\/"},"modified":"2023-05-04T18:05:24","modified_gmt":"2023-05-04T16:05:24","slug":"taller-de-arqueologia-praga-republica-checa","status":"publish","type":"post","link":"https:\/\/news.acropolis.org\/es\/2023\/taller-de-arqueologia-praga-republica-checa\/","title":{"rendered":"Taller de arqueolog\u00eda (Praga, Rep\u00fablica Checa)"},"content":{"rendered":"<p>Nueva Acr\u00f3polis Praga organiz\u00f3 un taller centrado en la creaci\u00f3n de reproducciones de famosos artefactos arqueol\u00f3gicos y murales.<\/p>\n<p><a href=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/04\/praha_kurz_malovani_reprodukci_1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-82652\" src=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/04\/praha_kurz_malovani_reprodukci_1-288x300.jpg\" alt=\"\" width=\"288\" height=\"300\" srcset=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/04\/praha_kurz_malovani_reprodukci_1-288x300.jpg 288w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/04\/praha_kurz_malovani_reprodukci_1-435x453.jpg 435w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/04\/praha_kurz_malovani_reprodukci_1-24x24.jpg 24w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/04\/praha_kurz_malovani_reprodukci_1.jpg 468w\" sizes=\"auto, (max-width: 288px) 100vw, 288px\" \/><\/a> <a href=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/04\/praha_kurz_malovani_reprodukci_2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-82655 alignright\" src=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/04\/praha_kurz_malovani_reprodukci_2-300x266.jpg\" alt=\"\" width=\"300\" height=\"266\" srcset=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/04\/praha_kurz_malovani_reprodukci_2-300x266.jpg 300w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/04\/praha_kurz_malovani_reprodukci_2-435x385.jpg 435w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/04\/praha_kurz_malovani_reprodukci_2.jpg 550w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nueva Acr\u00f3polis Praga organiz\u00f3 un taller centrado en la creaci\u00f3n de reproducciones de famosos artefactos arqueol\u00f3gicos y murales.<\/p>\n","protected":false},"author":7,"featured_media":82652,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[47],"tags":[],"class_list":["post-82976","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actividades_educativas","clearfix"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Taller de arqueolog\u00eda (Praga, Rep\u00fablica Checa) - Noticias de Nueva Acr\u00f3polis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/news.acropolis.org\/es\/2023\/taller-de-arqueologia-praga-republica-checa\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Taller de arqueolog\u00eda (Praga, Rep\u00fablica Checa) - Noticias de Nueva Acr\u00f3polis\" \/>\n<meta name=\"twitter:description\" content=\"Nueva Acr\u00f3polis Praga organiz\u00f3 un taller centrado en la creaci\u00f3n de reproducciones de famosos artefactos arqueol\u00f3gicos y murales.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/04\/praha_kurz_malovani_reprodukci_1.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rep\u00fablica Checa\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/taller-de-arqueologia-praga-republica-checa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/taller-de-arqueologia-praga-republica-checa\\\/\"},\"author\":{\"name\":\"Czech Republic\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/707297d714ad77479e9463b255f5e3d9\"},\"headline\":\"Taller de arqueolog\u00eda (Praga, Rep\u00fablica Checa)\",\"datePublished\":\"2023-05-04T16:05:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/taller-de-arqueologia-praga-republica-checa\\\/\"},\"wordCount\":29,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/taller-de-arqueologia-praga-republica-checa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/praha_kurz_malovani_reprodukci_1.jpg\",\"articleSection\":[\"Actividades Educativas\"],\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/taller-de-arqueologia-praga-republica-checa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/taller-de-arqueologia-praga-republica-checa\\\/\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/taller-de-arqueologia-praga-republica-checa\\\/\",\"name\":\"Taller de arqueolog\u00eda (Praga, Rep\u00fablica Checa) - Noticias de Nueva Acr\u00f3polis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/taller-de-arqueologia-praga-republica-checa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/taller-de-arqueologia-praga-republica-checa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/praha_kurz_malovani_reprodukci_1.jpg\",\"datePublished\":\"2023-05-04T16:05:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/707297d714ad77479e9463b255f5e3d9\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/taller-de-arqueologia-praga-republica-checa\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/taller-de-arqueologia-praga-republica-checa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/taller-de-arqueologia-praga-republica-checa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/praha_kurz_malovani_reprodukci_1.jpg\",\"contentUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/praha_kurz_malovani_reprodukci_1.jpg\",\"width\":468,\"height\":487},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/taller-de-arqueologia-praga-republica-checa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Taller de arqueolog\u00eda (Praga, Rep\u00fablica Checa)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/\",\"name\":\"Noticias de Nueva Acr\u00f3polis\",\"description\":\"Actividades de la Organizaci\u00f3n Internacional Nueva Acr\u00f3polis\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/707297d714ad77479e9463b255f5e3d9\",\"name\":\"Czech Republic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/CZE.png\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/CZE.png\",\"contentUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/CZE.png\",\"caption\":\"Czech Republic\"},\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/author\\\/oinaches\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Taller de arqueolog\u00eda (Praga, Rep\u00fablica Checa) - Noticias de Nueva Acr\u00f3polis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/news.acropolis.org\/es\/2023\/taller-de-arqueologia-praga-republica-checa\/","twitter_card":"summary_large_image","twitter_title":"Taller de arqueolog\u00eda (Praga, Rep\u00fablica Checa) - Noticias de Nueva Acr\u00f3polis","twitter_description":"Nueva Acr\u00f3polis Praga organiz\u00f3 un taller centrado en la creaci\u00f3n de reproducciones de famosos artefactos arqueol\u00f3gicos y murales.","twitter_image":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/04\/praha_kurz_malovani_reprodukci_1.jpg","twitter_misc":{"Escrito por":"Rep\u00fablica Checa"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/news.acropolis.org\/es\/2023\/taller-de-arqueologia-praga-republica-checa\/#article","isPartOf":{"@id":"https:\/\/news.acropolis.org\/es\/2023\/taller-de-arqueologia-praga-republica-checa\/"},"author":{"name":"Czech Republic","@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/707297d714ad77479e9463b255f5e3d9"},"headline":"Taller de arqueolog\u00eda (Praga, Rep\u00fablica Checa)","datePublished":"2023-05-04T16:05:24+00:00","mainEntityOfPage":{"@id":"https:\/\/news.acropolis.org\/es\/2023\/taller-de-arqueologia-praga-republica-checa\/"},"wordCount":29,"commentCount":0,"image":{"@id":"https:\/\/news.acropolis.org\/es\/2023\/taller-de-arqueologia-praga-republica-checa\/#primaryimage"},"thumbnailUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/04\/praha_kurz_malovani_reprodukci_1.jpg","articleSection":["Actividades Educativas"],"inLanguage":"es-ES","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/news.acropolis.org\/es\/2023\/taller-de-arqueologia-praga-republica-checa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/news.acropolis.org\/es\/2023\/taller-de-arqueologia-praga-republica-checa\/","url":"https:\/\/news.acropolis.org\/es\/2023\/taller-de-arqueologia-praga-republica-checa\/","name":"Taller de arqueolog\u00eda (Praga, Rep\u00fablica Checa) - Noticias de Nueva Acr\u00f3polis","isPartOf":{"@id":"https:\/\/news.acropolis.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/news.acropolis.org\/es\/2023\/taller-de-arqueologia-praga-republica-checa\/#primaryimage"},"image":{"@id":"https:\/\/news.acropolis.org\/es\/2023\/taller-de-arqueologia-praga-republica-checa\/#primaryimage"},"thumbnailUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/04\/praha_kurz_malovani_reprodukci_1.jpg","datePublished":"2023-05-04T16:05:24+00:00","author":{"@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/707297d714ad77479e9463b255f5e3d9"},"breadcrumb":{"@id":"https:\/\/news.acropolis.org\/es\/2023\/taller-de-arqueologia-praga-republica-checa\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/news.acropolis.org\/es\/2023\/taller-de-arqueologia-praga-republica-checa\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/news.acropolis.org\/es\/2023\/taller-de-arqueologia-praga-republica-checa\/#primaryimage","url":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/04\/praha_kurz_malovani_reprodukci_1.jpg","contentUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/04\/praha_kurz_malovani_reprodukci_1.jpg","width":468,"height":487},{"@type":"BreadcrumbList","@id":"https:\/\/news.acropolis.org\/es\/2023\/taller-de-arqueologia-praga-republica-checa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/news.acropolis.org\/es\/"},{"@type":"ListItem","position":2,"name":"Taller de arqueolog\u00eda (Praga, Rep\u00fablica Checa)"}]},{"@type":"WebSite","@id":"https:\/\/news.acropolis.org\/es\/#website","url":"https:\/\/news.acropolis.org\/es\/","name":"Noticias de Nueva Acr\u00f3polis","description":"Actividades de la Organizaci\u00f3n Internacional Nueva Acr\u00f3polis","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/news.acropolis.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/707297d714ad77479e9463b255f5e3d9","name":"Czech Republic","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/CZE.png","url":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/CZE.png","contentUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/CZE.png","caption":"Czech Republic"},"url":"https:\/\/news.acropolis.org\/es\/author\/oinaches\/"}]}},"_links":{"self":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/82976","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/comments?post=82976"}],"version-history":[{"count":0,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/82976\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/media\/82652"}],"wp:attachment":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/media?parent=82976"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/categories?post=82976"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/tags?post=82976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}