{"id":88901,"date":"2023-11-12T14:01:22","date_gmt":"2023-11-12T13:01:22","guid":{"rendered":"https:\/\/news.acropolis.org\/?p=88901"},"modified":"2023-11-12T14:02:12","modified_gmt":"2023-11-12T13:02:12","slug":"teatro-para-celebrar-el-dia-mundial-de-la-filosofia-pune-india","status":"publish","type":"post","link":"https:\/\/news.acropolis.org\/es\/2023\/teatro-para-celebrar-el-dia-mundial-de-la-filosofia-pune-india\/","title":{"rendered":"Teatro para celebrar el D\u00eda Mundial de la Filosof\u00eda (Pune, India)"},"content":{"rendered":"<p>La sede de Nueva Acr\u00f3polis en Pune celebr\u00f3 el D\u00eda Mundial de la Filosof\u00eda con la llegada del Diwali, a trav\u00e9s de una presentaci\u00f3n teatral titulada \u201cVictoria de la luz sobre la oscuridad\u201d en \u201cThe Base\u201d, un teatro en Erandwane, Pune.<\/p>\n<p>La presentaci\u00f3n teatral fue seguida por una conferencia de Shraddha Shetty, director de la sede de Nueva Acr\u00f3polis Pune, que abord\u00f3 ideas de filosof\u00eda, teatro y Diwali. Los participantes participaron en algunos ejercicios filos\u00f3ficos sencillos, como escribir un peque\u00f1o poema sobre su inspiraci\u00f3n, leerlo m\u00e1s tarde y elegir diferentes emociones mientras los recitaban. Con la asistencia de m\u00e1s de 150 personas, fue una velada que explor\u00f3 el tema principal de &#8220;Filosof\u00eda en Acci\u00f3n&#8221;, organizada por los j\u00f3venes miembros de Nueva Acr\u00f3polis Pune.<\/p>\n<p><a href=\"https:\/\/news.acropolis.org\/2023\/theatre-celebrating-victory-of-light-over-darkness-towards-world-philosophy-day-pune-india\/wpd_puneuntitled2\/\" rel=\"attachment wp-att-88826\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-88826\" src=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/wpd_puneUntitled2-300x208.jpg\" alt=\"\" width=\"300\" height=\"208\" srcset=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/wpd_puneUntitled2-300x208.jpg 300w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/wpd_puneUntitled2-1024x711.jpg 1024w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/wpd_puneUntitled2-768x533.jpg 768w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/wpd_puneUntitled2-730x507.jpg 730w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/wpd_puneUntitled2-435x302.jpg 435w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/wpd_puneUntitled2.jpg 1210w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/news.acropolis.org\/2023\/theatre-celebrating-victory-of-light-over-darkness-towards-world-philosophy-day-pune-india\/c38a986d-ff54-43c7-af22-31217c84234d\/\" rel=\"attachment wp-att-88811\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-88811\" src=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/C38A986D-FF54-43C7-AF22-31217C84234D-300x217.jpg\" alt=\"\" width=\"300\" height=\"217\" srcset=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/C38A986D-FF54-43C7-AF22-31217C84234D-300x217.jpg 300w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/C38A986D-FF54-43C7-AF22-31217C84234D-1024x742.jpg 1024w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/C38A986D-FF54-43C7-AF22-31217C84234D-768x557.jpg 768w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/C38A986D-FF54-43C7-AF22-31217C84234D-730x529.jpg 730w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/C38A986D-FF54-43C7-AF22-31217C84234D-435x315.jpg 435w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/C38A986D-FF54-43C7-AF22-31217C84234D.jpg 1043w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/news.acropolis.org\/2023\/theatre-celebrating-victory-of-light-over-darkness-towards-world-philosophy-day-pune-india\/wpd_puneuntitled\/\" rel=\"attachment wp-att-88823\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-88823\" src=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/wpd_puneUntitled-300x213.jpg\" alt=\"\" width=\"300\" height=\"213\" srcset=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/wpd_puneUntitled-300x213.jpg 300w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/wpd_puneUntitled-768x546.jpg 768w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/wpd_puneUntitled-730x519.jpg 730w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/wpd_puneUntitled-435x309.jpg 435w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/wpd_puneUntitled.jpg 804w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/news.acropolis.org\/2023\/theatre-celebrating-victory-of-light-over-darkness-towards-world-philosophy-day-pune-india\/679a6350-fe01-4813-8b36-5d827486b1ef\/\" rel=\"attachment wp-att-88814\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-88814\" src=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/679A6350-FE01-4813-8B36-5D827486B1EF-300x218.jpg\" alt=\"\" width=\"300\" height=\"218\" srcset=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/679A6350-FE01-4813-8B36-5D827486B1EF-300x218.jpg 300w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/679A6350-FE01-4813-8B36-5D827486B1EF-1024x742.jpg 1024w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/679A6350-FE01-4813-8B36-5D827486B1EF-768x557.jpg 768w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/679A6350-FE01-4813-8B36-5D827486B1EF-730x529.jpg 730w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/679A6350-FE01-4813-8B36-5D827486B1EF-435x315.jpg 435w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/679A6350-FE01-4813-8B36-5D827486B1EF.jpg 1440w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/news.acropolis.org\/2023\/theatre-celebrating-victory-of-light-over-darkness-towards-world-philosophy-day-pune-india\/9df5a9df-7b3e-4e1f-82f1-384743d2b51c\/\" rel=\"attachment wp-att-88817\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-88817\" src=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/9DF5A9DF-7B3E-4E1F-82F1-384743D2B51C-300x218.jpg\" alt=\"\" width=\"300\" height=\"218\" srcset=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/9DF5A9DF-7B3E-4E1F-82F1-384743D2B51C-300x218.jpg 300w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/9DF5A9DF-7B3E-4E1F-82F1-384743D2B51C-1024x742.jpg 1024w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/9DF5A9DF-7B3E-4E1F-82F1-384743D2B51C-768x557.jpg 768w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/9DF5A9DF-7B3E-4E1F-82F1-384743D2B51C-730x529.jpg 730w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/9DF5A9DF-7B3E-4E1F-82F1-384743D2B51C-435x315.jpg 435w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/9DF5A9DF-7B3E-4E1F-82F1-384743D2B51C.jpg 1440w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/news.acropolis.org\/2023\/theatre-celebrating-victory-of-light-over-darkness-towards-world-philosophy-day-pune-india\/c4514c6d-d0df-4580-af59-3c059a07abba\/\" rel=\"attachment wp-att-88820\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-88820\" src=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/C4514C6D-D0DF-4580-AF59-3C059A07ABBA-300x218.jpg\" alt=\"\" width=\"300\" height=\"218\" srcset=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/C4514C6D-D0DF-4580-AF59-3C059A07ABBA-300x218.jpg 300w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/C4514C6D-D0DF-4580-AF59-3C059A07ABBA-1024x742.jpg 1024w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/C4514C6D-D0DF-4580-AF59-3C059A07ABBA-768x557.jpg 768w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/C4514C6D-D0DF-4580-AF59-3C059A07ABBA-730x529.jpg 730w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/C4514C6D-D0DF-4580-AF59-3C059A07ABBA-435x315.jpg 435w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/C4514C6D-D0DF-4580-AF59-3C059A07ABBA.jpg 1440w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La sede de Nueva Acr\u00f3polis en Pune celebr\u00f3 el D\u00eda Mundial de la Filosof\u00eda con la llegada del Diwali, a trav\u00e9s de una presentaci\u00f3n teatral titulada \u201cVictoria de la luz [&hellip;]<\/p>\n","protected":false},"author":28,"featured_media":88828,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[50],"tags":[],"class_list":["post-88901","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dia_filosofia","clearfix"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Teatro para celebrar el D\u00eda Mundial de la Filosof\u00eda (Pune, India) - Noticias de Nueva Acr\u00f3polis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/news.acropolis.org\/es\/2023\/teatro-para-celebrar-el-dia-mundial-de-la-filosofia-pune-india\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Teatro para celebrar el D\u00eda Mundial de la Filosof\u00eda (Pune, India) - Noticias de Nueva Acr\u00f3polis\" \/>\n<meta name=\"twitter:description\" content=\"La sede de Nueva Acr\u00f3polis en Pune celebr\u00f3 el D\u00eda Mundial de la Filosof\u00eda con la llegada del Diwali, a trav\u00e9s de una presentaci\u00f3n teatral titulada \u201cVictoria de la luz [&hellip;]\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/wpd_puneUntitled2.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"India\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/teatro-para-celebrar-el-dia-mundial-de-la-filosofia-pune-india\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/teatro-para-celebrar-el-dia-mundial-de-la-filosofia-pune-india\\\/\"},\"author\":{\"name\":\"India\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/5206b1386085a9d7de22a1d23c51281e\"},\"headline\":\"Teatro para celebrar el D\u00eda Mundial de la Filosof\u00eda (Pune, India)\",\"datePublished\":\"2023-11-12T13:01:22+00:00\",\"dateModified\":\"2023-11-12T13:02:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/teatro-para-celebrar-el-dia-mundial-de-la-filosofia-pune-india\\\/\"},\"wordCount\":152,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/teatro-para-celebrar-el-dia-mundial-de-la-filosofia-pune-india\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/wpd_puneUntitled2.jpg\",\"articleSection\":[\"D\u00eda Mundial de la Filosof\u00eda\"],\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/teatro-para-celebrar-el-dia-mundial-de-la-filosofia-pune-india\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/teatro-para-celebrar-el-dia-mundial-de-la-filosofia-pune-india\\\/\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/teatro-para-celebrar-el-dia-mundial-de-la-filosofia-pune-india\\\/\",\"name\":\"Teatro para celebrar el D\u00eda Mundial de la Filosof\u00eda (Pune, India) - Noticias de Nueva Acr\u00f3polis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/teatro-para-celebrar-el-dia-mundial-de-la-filosofia-pune-india\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/teatro-para-celebrar-el-dia-mundial-de-la-filosofia-pune-india\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/wpd_puneUntitled2.jpg\",\"datePublished\":\"2023-11-12T13:01:22+00:00\",\"dateModified\":\"2023-11-12T13:02:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/5206b1386085a9d7de22a1d23c51281e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/teatro-para-celebrar-el-dia-mundial-de-la-filosofia-pune-india\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/teatro-para-celebrar-el-dia-mundial-de-la-filosofia-pune-india\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/teatro-para-celebrar-el-dia-mundial-de-la-filosofia-pune-india\\\/#primaryimage\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/wpd_puneUntitled2.jpg\",\"contentUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/wpd_puneUntitled2.jpg\",\"width\":1210,\"height\":840},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/teatro-para-celebrar-el-dia-mundial-de-la-filosofia-pune-india\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Teatro para celebrar el D\u00eda Mundial de la Filosof\u00eda (Pune, India)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/\",\"name\":\"Noticias de Nueva Acr\u00f3polis\",\"description\":\"Actividades de la Organizaci\u00f3n Internacional Nueva Acr\u00f3polis\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/5206b1386085a9d7de22a1d23c51281e\",\"name\":\"India\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/IND.png\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/IND.png\",\"contentUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/IND.png\",\"caption\":\"India\"},\"sameAs\":[\"http:\\\/\\\/www.acropolis.org.in\"],\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/author\\\/oinaind\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Teatro para celebrar el D\u00eda Mundial de la Filosof\u00eda (Pune, India) - Noticias de Nueva Acr\u00f3polis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/news.acropolis.org\/es\/2023\/teatro-para-celebrar-el-dia-mundial-de-la-filosofia-pune-india\/","twitter_card":"summary_large_image","twitter_title":"Teatro para celebrar el D\u00eda Mundial de la Filosof\u00eda (Pune, India) - Noticias de Nueva Acr\u00f3polis","twitter_description":"La sede de Nueva Acr\u00f3polis en Pune celebr\u00f3 el D\u00eda Mundial de la Filosof\u00eda con la llegada del Diwali, a trav\u00e9s de una presentaci\u00f3n teatral titulada \u201cVictoria de la luz [&hellip;]","twitter_image":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/wpd_puneUntitled2.jpg","twitter_misc":{"Escrito por":"India","Tiempo de lectura":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/news.acropolis.org\/es\/2023\/teatro-para-celebrar-el-dia-mundial-de-la-filosofia-pune-india\/#article","isPartOf":{"@id":"https:\/\/news.acropolis.org\/es\/2023\/teatro-para-celebrar-el-dia-mundial-de-la-filosofia-pune-india\/"},"author":{"name":"India","@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/5206b1386085a9d7de22a1d23c51281e"},"headline":"Teatro para celebrar el D\u00eda Mundial de la Filosof\u00eda (Pune, India)","datePublished":"2023-11-12T13:01:22+00:00","dateModified":"2023-11-12T13:02:12+00:00","mainEntityOfPage":{"@id":"https:\/\/news.acropolis.org\/es\/2023\/teatro-para-celebrar-el-dia-mundial-de-la-filosofia-pune-india\/"},"wordCount":152,"commentCount":0,"image":{"@id":"https:\/\/news.acropolis.org\/es\/2023\/teatro-para-celebrar-el-dia-mundial-de-la-filosofia-pune-india\/#primaryimage"},"thumbnailUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/wpd_puneUntitled2.jpg","articleSection":["D\u00eda Mundial de la Filosof\u00eda"],"inLanguage":"es-ES","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/news.acropolis.org\/es\/2023\/teatro-para-celebrar-el-dia-mundial-de-la-filosofia-pune-india\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/news.acropolis.org\/es\/2023\/teatro-para-celebrar-el-dia-mundial-de-la-filosofia-pune-india\/","url":"https:\/\/news.acropolis.org\/es\/2023\/teatro-para-celebrar-el-dia-mundial-de-la-filosofia-pune-india\/","name":"Teatro para celebrar el D\u00eda Mundial de la Filosof\u00eda (Pune, India) - Noticias de Nueva Acr\u00f3polis","isPartOf":{"@id":"https:\/\/news.acropolis.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/news.acropolis.org\/es\/2023\/teatro-para-celebrar-el-dia-mundial-de-la-filosofia-pune-india\/#primaryimage"},"image":{"@id":"https:\/\/news.acropolis.org\/es\/2023\/teatro-para-celebrar-el-dia-mundial-de-la-filosofia-pune-india\/#primaryimage"},"thumbnailUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/wpd_puneUntitled2.jpg","datePublished":"2023-11-12T13:01:22+00:00","dateModified":"2023-11-12T13:02:12+00:00","author":{"@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/5206b1386085a9d7de22a1d23c51281e"},"breadcrumb":{"@id":"https:\/\/news.acropolis.org\/es\/2023\/teatro-para-celebrar-el-dia-mundial-de-la-filosofia-pune-india\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/news.acropolis.org\/es\/2023\/teatro-para-celebrar-el-dia-mundial-de-la-filosofia-pune-india\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/news.acropolis.org\/es\/2023\/teatro-para-celebrar-el-dia-mundial-de-la-filosofia-pune-india\/#primaryimage","url":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/wpd_puneUntitled2.jpg","contentUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/wpd_puneUntitled2.jpg","width":1210,"height":840},{"@type":"BreadcrumbList","@id":"https:\/\/news.acropolis.org\/es\/2023\/teatro-para-celebrar-el-dia-mundial-de-la-filosofia-pune-india\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/news.acropolis.org\/es\/"},{"@type":"ListItem","position":2,"name":"Teatro para celebrar el D\u00eda Mundial de la Filosof\u00eda (Pune, India)"}]},{"@type":"WebSite","@id":"https:\/\/news.acropolis.org\/es\/#website","url":"https:\/\/news.acropolis.org\/es\/","name":"Noticias de Nueva Acr\u00f3polis","description":"Actividades de la Organizaci\u00f3n Internacional Nueva Acr\u00f3polis","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/news.acropolis.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/5206b1386085a9d7de22a1d23c51281e","name":"India","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/IND.png","url":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/IND.png","contentUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/IND.png","caption":"India"},"sameAs":["http:\/\/www.acropolis.org.in"],"url":"https:\/\/news.acropolis.org\/es\/author\/oinaind\/"}]}},"_links":{"self":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/88901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/comments?post=88901"}],"version-history":[{"count":1,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/88901\/revisions"}],"predecessor-version":[{"id":88902,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/88901\/revisions\/88902"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/media\/88828"}],"wp:attachment":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/media?parent=88901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/categories?post=88901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/tags?post=88901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}