{"id":88979,"date":"2023-11-19T12:15:22","date_gmt":"2023-11-19T11:15:22","guid":{"rendered":"https:\/\/news.acropolis.org\/?p=88979"},"modified":"2024-01-19T09:38:52","modified_gmt":"2024-01-19T08:38:52","slug":"dia-mundial-de-la-limpieza-2023-montpellier-francia","status":"publish","type":"post","link":"https:\/\/news.acropolis.org\/es\/2023\/dia-mundial-de-la-limpieza-2023-montpellier-francia\/","title":{"rendered":"D\u00eda Mundial de la Limpieza 2023 (Montpellier, Francia)"},"content":{"rendered":"<p><a href=\"https:\/\/news.acropolis.org\/es\/2023\/dia-mundial-de-la-limpieza-2023-montpellier-francia\/photo-world-clean-up-day-mop-sept-2023-2\/\" rel=\"attachment wp-att-88974\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-88974 size-full\" src=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/photo-World-Clean-up-day-MOP-sept-2023.jpg\" alt=\"\" width=\"500\" height=\"282\" srcset=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/photo-World-Clean-up-day-MOP-sept-2023.jpg 500w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/photo-World-Clean-up-day-MOP-sept-2023-300x169.jpg 300w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/photo-World-Clean-up-day-MOP-sept-2023-435x245.jpg 435w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a>Con motivo del D\u00eda Mundial de la Limpieza, un grupo de voluntarios desafiamos sin miedo la tormenta prevista.<\/p>\n<p>Incluso antes de entrar en acci\u00f3n, al salir a pesar del tiempo desfavorable, pudimos sentir realmente lo que es un fil\u00f3sofo.\u00a0Un fil\u00f3sofo, pase lo que pase en el exterior, har\u00e1 todo lo que est\u00e9 en su mano para vivir de acuerdo con sus valores.<\/p>\n<p>Y eso que no llovi\u00f3 cuando nos enfrentamos a todas las colillas y c\u00e1psulas del Paseo del Peyrou.<\/p>\n<p>\u00a1Qu\u00e9 alegr\u00eda unirse al servicio de la Tierra y devolverle todo su esplendor!<\/p>\n<p>Enhorabuena a todos los participantes:<\/p>\n<p>2000 colillas recogidas<\/p>\n<p>30 litros de materiales reciclables<\/p>\n<p>20 litros de residuos generales<\/p>\n<p>&nbsp;<\/p>\n<p>Hoy en d\u00eda, cuando vemos la magnitud del da\u00f1o que se est\u00e1 haciendo al planeta, podemos preguntarnos leg\u00edtimamente si realmente merece la pena actuar.<\/p>\n<p>Durante la recogida, nos fijamos en una frase de Confucio que podr\u00eda ayudarnos a responder a esta pregunta.<\/p>\n<p>&#8220;<i>Cuando sea obvio que tu objetivo es inalcanzable, no cambies tu objetivo, cambia la forma de alcanzarlo<\/i>&#8220;.<\/p>\n<p>Confucio<\/p>\n<p>\u00bfY t\u00fa qu\u00e9 opinas?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con motivo del D\u00eda Mundial de la Limpieza, un grupo de voluntarios desafiamos sin miedo la tormenta prevista. Incluso antes de entrar en acci\u00f3n, al salir a pesar del tiempo [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":88974,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[57],"tags":[2377,1494,4573,4487,5192],"class_list":["post-88979","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-voluntariado_ecologico","tag-accion-ecologica","tag-limpieza","tag-nouvelle-acropole-france-es","tag-nueva-acropolis-francia","tag-volunatariado","clearfix"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00eda Mundial de la Limpieza 2023 (Montpellier, Francia) - Noticias de Nueva Acr\u00f3polis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/news.acropolis.org\/es\/2023\/dia-mundial-de-la-limpieza-2023-montpellier-francia\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"D\u00eda Mundial de la Limpieza 2023 (Montpellier, Francia) - Noticias de Nueva Acr\u00f3polis\" \/>\n<meta name=\"twitter:description\" content=\"Con motivo del D\u00eda Mundial de la Limpieza, un grupo de voluntarios desafiamos sin miedo la tormenta prevista. Incluso antes de entrar en acci\u00f3n, al salir a pesar del tiempo [&hellip;]\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/photo-World-Clean-up-day-MOP-sept-2023.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/dia-mundial-de-la-limpieza-2023-montpellier-francia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/dia-mundial-de-la-limpieza-2023-montpellier-francia\\\/\"},\"author\":{\"name\":\"France\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/c835cfdc299fe61027b215fef932cd3c\"},\"headline\":\"D\u00eda Mundial de la Limpieza 2023 (Montpellier, Francia)\",\"datePublished\":\"2023-11-19T11:15:22+00:00\",\"dateModified\":\"2024-01-19T08:38:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/dia-mundial-de-la-limpieza-2023-montpellier-francia\\\/\"},\"wordCount\":192,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/dia-mundial-de-la-limpieza-2023-montpellier-francia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/photo-World-Clean-up-day-MOP-sept-2023.jpg\",\"keywords\":[\"acci\u00f3n ecol\u00f3gica\",\"limpieza\",\"Nouvelle Acropole France\",\"Nueva Acr\u00f3polis Francia\",\"volunatariado\"],\"articleSection\":[\"Voluntariado Ecol\u00f3gico\"],\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/dia-mundial-de-la-limpieza-2023-montpellier-francia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/dia-mundial-de-la-limpieza-2023-montpellier-francia\\\/\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/dia-mundial-de-la-limpieza-2023-montpellier-francia\\\/\",\"name\":\"D\u00eda Mundial de la Limpieza 2023 (Montpellier, Francia) - Noticias de Nueva Acr\u00f3polis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/dia-mundial-de-la-limpieza-2023-montpellier-francia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/dia-mundial-de-la-limpieza-2023-montpellier-francia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/photo-World-Clean-up-day-MOP-sept-2023.jpg\",\"datePublished\":\"2023-11-19T11:15:22+00:00\",\"dateModified\":\"2024-01-19T08:38:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/c835cfdc299fe61027b215fef932cd3c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/dia-mundial-de-la-limpieza-2023-montpellier-francia\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/dia-mundial-de-la-limpieza-2023-montpellier-francia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/dia-mundial-de-la-limpieza-2023-montpellier-francia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/photo-World-Clean-up-day-MOP-sept-2023.jpg\",\"contentUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/photo-World-Clean-up-day-MOP-sept-2023.jpg\",\"width\":500,\"height\":282},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/dia-mundial-de-la-limpieza-2023-montpellier-francia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00eda Mundial de la Limpieza 2023 (Montpellier, Francia)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/\",\"name\":\"Noticias de Nueva Acr\u00f3polis\",\"description\":\"Actividades de la Organizaci\u00f3n Internacional Nueva Acr\u00f3polis\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/c835cfdc299fe61027b215fef932cd3c\",\"name\":\"France\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/FRA.png\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/FRA.png\",\"contentUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/FRA.png\",\"caption\":\"France\"},\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/author\\\/oinaf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00eda Mundial de la Limpieza 2023 (Montpellier, Francia) - Noticias de Nueva Acr\u00f3polis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/news.acropolis.org\/es\/2023\/dia-mundial-de-la-limpieza-2023-montpellier-francia\/","twitter_card":"summary_large_image","twitter_title":"D\u00eda Mundial de la Limpieza 2023 (Montpellier, Francia) - Noticias de Nueva Acr\u00f3polis","twitter_description":"Con motivo del D\u00eda Mundial de la Limpieza, un grupo de voluntarios desafiamos sin miedo la tormenta prevista. Incluso antes de entrar en acci\u00f3n, al salir a pesar del tiempo [&hellip;]","twitter_image":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/photo-World-Clean-up-day-MOP-sept-2023.jpg","twitter_misc":{"Escrito por":"Francia","Tiempo de lectura":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/news.acropolis.org\/es\/2023\/dia-mundial-de-la-limpieza-2023-montpellier-francia\/#article","isPartOf":{"@id":"https:\/\/news.acropolis.org\/es\/2023\/dia-mundial-de-la-limpieza-2023-montpellier-francia\/"},"author":{"name":"France","@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/c835cfdc299fe61027b215fef932cd3c"},"headline":"D\u00eda Mundial de la Limpieza 2023 (Montpellier, Francia)","datePublished":"2023-11-19T11:15:22+00:00","dateModified":"2024-01-19T08:38:52+00:00","mainEntityOfPage":{"@id":"https:\/\/news.acropolis.org\/es\/2023\/dia-mundial-de-la-limpieza-2023-montpellier-francia\/"},"wordCount":192,"commentCount":0,"image":{"@id":"https:\/\/news.acropolis.org\/es\/2023\/dia-mundial-de-la-limpieza-2023-montpellier-francia\/#primaryimage"},"thumbnailUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/photo-World-Clean-up-day-MOP-sept-2023.jpg","keywords":["acci\u00f3n ecol\u00f3gica","limpieza","Nouvelle Acropole France","Nueva Acr\u00f3polis Francia","volunatariado"],"articleSection":["Voluntariado Ecol\u00f3gico"],"inLanguage":"es-ES","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/news.acropolis.org\/es\/2023\/dia-mundial-de-la-limpieza-2023-montpellier-francia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/news.acropolis.org\/es\/2023\/dia-mundial-de-la-limpieza-2023-montpellier-francia\/","url":"https:\/\/news.acropolis.org\/es\/2023\/dia-mundial-de-la-limpieza-2023-montpellier-francia\/","name":"D\u00eda Mundial de la Limpieza 2023 (Montpellier, Francia) - Noticias de Nueva Acr\u00f3polis","isPartOf":{"@id":"https:\/\/news.acropolis.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/news.acropolis.org\/es\/2023\/dia-mundial-de-la-limpieza-2023-montpellier-francia\/#primaryimage"},"image":{"@id":"https:\/\/news.acropolis.org\/es\/2023\/dia-mundial-de-la-limpieza-2023-montpellier-francia\/#primaryimage"},"thumbnailUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/photo-World-Clean-up-day-MOP-sept-2023.jpg","datePublished":"2023-11-19T11:15:22+00:00","dateModified":"2024-01-19T08:38:52+00:00","author":{"@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/c835cfdc299fe61027b215fef932cd3c"},"breadcrumb":{"@id":"https:\/\/news.acropolis.org\/es\/2023\/dia-mundial-de-la-limpieza-2023-montpellier-francia\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/news.acropolis.org\/es\/2023\/dia-mundial-de-la-limpieza-2023-montpellier-francia\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/news.acropolis.org\/es\/2023\/dia-mundial-de-la-limpieza-2023-montpellier-francia\/#primaryimage","url":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/photo-World-Clean-up-day-MOP-sept-2023.jpg","contentUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/photo-World-Clean-up-day-MOP-sept-2023.jpg","width":500,"height":282},{"@type":"BreadcrumbList","@id":"https:\/\/news.acropolis.org\/es\/2023\/dia-mundial-de-la-limpieza-2023-montpellier-francia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/news.acropolis.org\/es\/"},{"@type":"ListItem","position":2,"name":"D\u00eda Mundial de la Limpieza 2023 (Montpellier, Francia)"}]},{"@type":"WebSite","@id":"https:\/\/news.acropolis.org\/es\/#website","url":"https:\/\/news.acropolis.org\/es\/","name":"Noticias de Nueva Acr\u00f3polis","description":"Actividades de la Organizaci\u00f3n Internacional Nueva Acr\u00f3polis","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/news.acropolis.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/c835cfdc299fe61027b215fef932cd3c","name":"France","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/FRA.png","url":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/FRA.png","contentUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/FRA.png","caption":"France"},"url":"https:\/\/news.acropolis.org\/es\/author\/oinaf\/"}]}},"_links":{"self":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/88979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/comments?post=88979"}],"version-history":[{"count":5,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/88979\/revisions"}],"predecessor-version":[{"id":91486,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/88979\/revisions\/91486"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/media\/88974"}],"wp:attachment":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/media?parent=88979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/categories?post=88979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/tags?post=88979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}