{"id":89209,"date":"2023-11-26T14:01:34","date_gmt":"2023-11-26T13:01:34","guid":{"rendered":"https:\/\/news.acropolis.org\/?p=89209"},"modified":"2023-11-26T14:02:01","modified_gmt":"2023-11-26T13:02:01","slug":"semana-de-la-filosofia-belgica","status":"publish","type":"post","link":"https:\/\/news.acropolis.org\/es\/2023\/semana-de-la-filosofia-belgica\/","title":{"rendered":"Semana de la filosof\u00eda (B\u00e9lgica)"},"content":{"rendered":"<p><a href=\"https:\/\/news.acropolis.org\/es\/2023\/semana-de-la-filosofia-belgica\/philo-week-2\/\" rel=\"attachment wp-att-89213\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-89213 size-large\" src=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/philo-week-2-1024x766.jpg\" alt=\"\" width=\"1024\" height=\"766\" srcset=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/philo-week-2-1024x766.jpg 1024w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/philo-week-2-300x224.jpg 300w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/philo-week-2-768x574.jpg 768w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/philo-week-2-1536x1149.jpg 1536w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/philo-week-2-2048x1532.jpg 2048w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/philo-week-2-730x546.jpg 730w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/philo-week-2-435x325.jpg 435w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/philo-week-2-80x60.jpg 80w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p>Ciclo de conferencias sobre filosof\u00eda pr\u00e1ctica durante toda una semana para celebrar El D\u00eda Mundial de la Filosof\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ciclo de conferencias sobre filosof\u00eda pr\u00e1ctica durante toda una semana para celebrar El D\u00eda Mundial de la Filosof\u00eda.<\/p>\n","protected":false},"author":32,"featured_media":89210,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[50],"tags":[],"class_list":["post-89209","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dia_filosofia","clearfix"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Semana de la filosof\u00eda (B\u00e9lgica) - Noticias de Nueva Acr\u00f3polis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/news.acropolis.org\/es\/2023\/semana-de-la-filosofia-belgica\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Semana de la filosof\u00eda (B\u00e9lgica) - Noticias de Nueva Acr\u00f3polis\" \/>\n<meta name=\"twitter:description\" content=\"Ciclo de conferencias sobre filosof\u00eda pr\u00e1ctica durante toda una semana para celebrar El D\u00eda Mundial de la Filosof\u00eda.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/philoweek-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"B\u00e9lgica\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/semana-de-la-filosofia-belgica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/semana-de-la-filosofia-belgica\\\/\"},\"author\":{\"name\":\"Belgium\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/db01097c808f416d0708ce55e2c1d45a\"},\"headline\":\"Semana de la filosof\u00eda (B\u00e9lgica)\",\"datePublished\":\"2023-11-26T13:01:34+00:00\",\"dateModified\":\"2023-11-26T13:02:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/semana-de-la-filosofia-belgica\\\/\"},\"wordCount\":29,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/semana-de-la-filosofia-belgica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/philoweek-scaled.jpg\",\"articleSection\":[\"D\u00eda Mundial de la Filosof\u00eda\"],\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/semana-de-la-filosofia-belgica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/semana-de-la-filosofia-belgica\\\/\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/semana-de-la-filosofia-belgica\\\/\",\"name\":\"Semana de la filosof\u00eda (B\u00e9lgica) - Noticias de Nueva Acr\u00f3polis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/semana-de-la-filosofia-belgica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/semana-de-la-filosofia-belgica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/philoweek-scaled.jpg\",\"datePublished\":\"2023-11-26T13:01:34+00:00\",\"dateModified\":\"2023-11-26T13:02:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/db01097c808f416d0708ce55e2c1d45a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/semana-de-la-filosofia-belgica\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/semana-de-la-filosofia-belgica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/semana-de-la-filosofia-belgica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/philoweek-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/philoweek-scaled.jpg\",\"width\":2560,\"height\":1915},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2023\\\/semana-de-la-filosofia-belgica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Semana de la filosof\u00eda (B\u00e9lgica)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/\",\"name\":\"Noticias de Nueva Acr\u00f3polis\",\"description\":\"Actividades de la Organizaci\u00f3n Internacional Nueva Acr\u00f3polis\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/db01097c808f416d0708ce55e2c1d45a\",\"name\":\"Belgium\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/BEL.png\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/BEL.png\",\"contentUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/BEL.png\",\"caption\":\"Belgium\"},\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/author\\\/oinabel\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Semana de la filosof\u00eda (B\u00e9lgica) - Noticias de Nueva Acr\u00f3polis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/news.acropolis.org\/es\/2023\/semana-de-la-filosofia-belgica\/","twitter_card":"summary_large_image","twitter_title":"Semana de la filosof\u00eda (B\u00e9lgica) - Noticias de Nueva Acr\u00f3polis","twitter_description":"Ciclo de conferencias sobre filosof\u00eda pr\u00e1ctica durante toda una semana para celebrar El D\u00eda Mundial de la Filosof\u00eda.","twitter_image":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/philoweek-scaled.jpg","twitter_misc":{"Escrito por":"B\u00e9lgica","Tiempo de lectura":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/news.acropolis.org\/es\/2023\/semana-de-la-filosofia-belgica\/#article","isPartOf":{"@id":"https:\/\/news.acropolis.org\/es\/2023\/semana-de-la-filosofia-belgica\/"},"author":{"name":"Belgium","@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/db01097c808f416d0708ce55e2c1d45a"},"headline":"Semana de la filosof\u00eda (B\u00e9lgica)","datePublished":"2023-11-26T13:01:34+00:00","dateModified":"2023-11-26T13:02:01+00:00","mainEntityOfPage":{"@id":"https:\/\/news.acropolis.org\/es\/2023\/semana-de-la-filosofia-belgica\/"},"wordCount":29,"commentCount":0,"image":{"@id":"https:\/\/news.acropolis.org\/es\/2023\/semana-de-la-filosofia-belgica\/#primaryimage"},"thumbnailUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/philoweek-scaled.jpg","articleSection":["D\u00eda Mundial de la Filosof\u00eda"],"inLanguage":"es-ES","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/news.acropolis.org\/es\/2023\/semana-de-la-filosofia-belgica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/news.acropolis.org\/es\/2023\/semana-de-la-filosofia-belgica\/","url":"https:\/\/news.acropolis.org\/es\/2023\/semana-de-la-filosofia-belgica\/","name":"Semana de la filosof\u00eda (B\u00e9lgica) - Noticias de Nueva Acr\u00f3polis","isPartOf":{"@id":"https:\/\/news.acropolis.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/news.acropolis.org\/es\/2023\/semana-de-la-filosofia-belgica\/#primaryimage"},"image":{"@id":"https:\/\/news.acropolis.org\/es\/2023\/semana-de-la-filosofia-belgica\/#primaryimage"},"thumbnailUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/philoweek-scaled.jpg","datePublished":"2023-11-26T13:01:34+00:00","dateModified":"2023-11-26T13:02:01+00:00","author":{"@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/db01097c808f416d0708ce55e2c1d45a"},"breadcrumb":{"@id":"https:\/\/news.acropolis.org\/es\/2023\/semana-de-la-filosofia-belgica\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/news.acropolis.org\/es\/2023\/semana-de-la-filosofia-belgica\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/news.acropolis.org\/es\/2023\/semana-de-la-filosofia-belgica\/#primaryimage","url":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/philoweek-scaled.jpg","contentUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2023\/11\/philoweek-scaled.jpg","width":2560,"height":1915},{"@type":"BreadcrumbList","@id":"https:\/\/news.acropolis.org\/es\/2023\/semana-de-la-filosofia-belgica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/news.acropolis.org\/es\/"},{"@type":"ListItem","position":2,"name":"Semana de la filosof\u00eda (B\u00e9lgica)"}]},{"@type":"WebSite","@id":"https:\/\/news.acropolis.org\/es\/#website","url":"https:\/\/news.acropolis.org\/es\/","name":"Noticias de Nueva Acr\u00f3polis","description":"Actividades de la Organizaci\u00f3n Internacional Nueva Acr\u00f3polis","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/news.acropolis.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/db01097c808f416d0708ce55e2c1d45a","name":"Belgium","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/BEL.png","url":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/BEL.png","contentUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/BEL.png","caption":"Belgium"},"url":"https:\/\/news.acropolis.org\/es\/author\/oinabel\/"}]}},"_links":{"self":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/89209","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/comments?post=89209"}],"version-history":[{"count":5,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/89209\/revisions"}],"predecessor-version":[{"id":89450,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/89209\/revisions\/89450"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/media\/89210"}],"wp:attachment":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/media?parent=89209"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/categories?post=89209"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/tags?post=89209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}