{"id":91561,"date":"2024-01-21T12:40:27","date_gmt":"2024-01-21T11:40:27","guid":{"rendered":"https:\/\/news.acropolis.org\/?p=91561"},"modified":"2024-01-21T12:40:27","modified_gmt":"2024-01-21T11:40:27","slug":"talleres-en-el-dia-mundial-de-la-filosofia-eslovenia","status":"publish","type":"post","link":"https:\/\/news.acropolis.org\/es\/2024\/talleres-en-el-dia-mundial-de-la-filosofia-eslovenia\/","title":{"rendered":"Talleres en el D\u00eda Mundial de la Filosof\u00eda (Eslovenia)"},"content":{"rendered":"<p><span data-contrast=\"none\"><a href=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/01\/cloveskevrednote.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-91414 alignright\" src=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/01\/cloveskevrednote.jpg\" alt=\"\" width=\"335\" height=\"251\" srcset=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/01\/cloveskevrednote.jpg 800w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/01\/cloveskevrednote-300x225.jpg 300w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/01\/cloveskevrednote-768x576.jpg 768w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/01\/cloveskevrednote-730x548.jpg 730w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/01\/cloveskevrednote-435x326.jpg 435w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/01\/cloveskevrednote-80x60.jpg 80w\" sizes=\"auto, (max-width: 335px) 100vw, 335px\" \/><\/a><\/span><\/p>\n<p>Cada a\u00f1o, en el D\u00eda Mundial de la Filosof\u00eda, recordamos lo importante que es buscar la sabidur\u00eda para vivir mejor.<\/p>\n<p>Este a\u00f1o, los miembros de Nueva Acr\u00f3polis Eslovenia tambi\u00e9n contribuyeron a la causa organizando un par de talleres p\u00fablicos.<\/p>\n<p>El primero abord\u00f3 nuestros valores humanos, sobre los cuales tomamos decisiones cotidianas para lograr ciertos objetivos. Pero al hacerlo, \u00bfrealmente nos planteamos si nuestras intenciones son realmente buenas o qu\u00e9 influencia tendr\u00e1 en la vida que nos rodea? Al final de la conferencia se invit\u00f3 a la audiencia a compartir y discutir puntos de vista comunes.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-91417 alignleft\" style=\"color: #0000ee;\" src=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/01\/imamo-razum.jpg\" alt=\"\" width=\"337\" height=\"253\" srcset=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/01\/imamo-razum.jpg 900w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/01\/imamo-razum-300x225.jpg 300w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/01\/imamo-razum-768x576.jpg 768w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/01\/imamo-razum-730x548.jpg 730w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/01\/imamo-razum-435x326.jpg 435w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/01\/imamo-razum-80x60.jpg 80w\" sizes=\"auto, (max-width: 337px) 100vw, 337px\" \/>El segundo, titulado: &#8220;Somos due\u00f1os de la raz\u00f3n. \u00bfQu\u00e9 debemos hacer con \u00e9l?&#8221;,\u00a0 impuls\u00f3 a los asistentes a explorar numerosos procesos de pensamiento que ocurren continuamente en el fondo de nuestra mente y gu\u00edan (o desv\u00edan) nuestro comportamiento. Las civilizaciones florecientes del pasado ya ve\u00edan el intelecto humano como una herramienta poderosa y la necesidad de utilizarlo responsablemente, por lo que nos familiarizamos con varios m\u00e9todos que diferentes escuelas filos\u00f3ficas desarrollaron para domesticarlo.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cada a\u00f1o, en el D\u00eda Mundial de la Filosof\u00eda, recordamos lo importante que es buscar la sabidur\u00eda para vivir mejor. Este a\u00f1o, los miembros de Nueva Acr\u00f3polis Eslovenia tambi\u00e9n contribuyeron [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":91416,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[50],"tags":[],"class_list":["post-91561","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dia_filosofia","clearfix"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Talleres en el D\u00eda Mundial de la Filosof\u00eda (Eslovenia) - Noticias de Nueva Acr\u00f3polis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/news.acropolis.org\/es\/2024\/talleres-en-el-dia-mundial-de-la-filosofia-eslovenia\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Talleres en el D\u00eda Mundial de la Filosof\u00eda (Eslovenia) - Noticias de Nueva Acr\u00f3polis\" \/>\n<meta name=\"twitter:description\" content=\"Cada a\u00f1o, en el D\u00eda Mundial de la Filosof\u00eda, recordamos lo importante que es buscar la sabidur\u00eda para vivir mejor. Este a\u00f1o, los miembros de Nueva Acr\u00f3polis Eslovenia tambi\u00e9n contribuyeron [&hellip;]\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/01\/cloveskevrednote.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eslovenia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/talleres-en-el-dia-mundial-de-la-filosofia-eslovenia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/talleres-en-el-dia-mundial-de-la-filosofia-eslovenia\\\/\"},\"author\":{\"name\":\"Slovenia\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/833ec9d55fbdbe9ed80d0d68e19a658d\"},\"headline\":\"Talleres en el D\u00eda Mundial de la Filosof\u00eda (Eslovenia)\",\"datePublished\":\"2024-01-21T11:40:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/talleres-en-el-dia-mundial-de-la-filosofia-eslovenia\\\/\"},\"wordCount\":197,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/talleres-en-el-dia-mundial-de-la-filosofia-eslovenia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cloveskevrednote.jpg\",\"articleSection\":[\"D\u00eda Mundial de la Filosof\u00eda\"],\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/talleres-en-el-dia-mundial-de-la-filosofia-eslovenia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/talleres-en-el-dia-mundial-de-la-filosofia-eslovenia\\\/\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/talleres-en-el-dia-mundial-de-la-filosofia-eslovenia\\\/\",\"name\":\"Talleres en el D\u00eda Mundial de la Filosof\u00eda (Eslovenia) - Noticias de Nueva Acr\u00f3polis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/talleres-en-el-dia-mundial-de-la-filosofia-eslovenia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/talleres-en-el-dia-mundial-de-la-filosofia-eslovenia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cloveskevrednote.jpg\",\"datePublished\":\"2024-01-21T11:40:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/833ec9d55fbdbe9ed80d0d68e19a658d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/talleres-en-el-dia-mundial-de-la-filosofia-eslovenia\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/talleres-en-el-dia-mundial-de-la-filosofia-eslovenia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/talleres-en-el-dia-mundial-de-la-filosofia-eslovenia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cloveskevrednote.jpg\",\"contentUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cloveskevrednote.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/talleres-en-el-dia-mundial-de-la-filosofia-eslovenia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Talleres en el D\u00eda Mundial de la Filosof\u00eda (Eslovenia)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/\",\"name\":\"Noticias de Nueva Acr\u00f3polis\",\"description\":\"Actividades de la Organizaci\u00f3n Internacional Nueva Acr\u00f3polis\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/833ec9d55fbdbe9ed80d0d68e19a658d\",\"name\":\"Slovenia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/SVN.png\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/SVN.png\",\"contentUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/SVN.png\",\"caption\":\"Slovenia\"},\"sameAs\":[\"http:\\\/\\\/www.akropola.org\"],\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/author\\\/oinaeslo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Talleres en el D\u00eda Mundial de la Filosof\u00eda (Eslovenia) - Noticias de Nueva Acr\u00f3polis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/news.acropolis.org\/es\/2024\/talleres-en-el-dia-mundial-de-la-filosofia-eslovenia\/","twitter_card":"summary_large_image","twitter_title":"Talleres en el D\u00eda Mundial de la Filosof\u00eda (Eslovenia) - Noticias de Nueva Acr\u00f3polis","twitter_description":"Cada a\u00f1o, en el D\u00eda Mundial de la Filosof\u00eda, recordamos lo importante que es buscar la sabidur\u00eda para vivir mejor. Este a\u00f1o, los miembros de Nueva Acr\u00f3polis Eslovenia tambi\u00e9n contribuyeron [&hellip;]","twitter_image":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/01\/cloveskevrednote.jpg","twitter_misc":{"Escrito por":"Eslovenia","Tiempo de lectura":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/news.acropolis.org\/es\/2024\/talleres-en-el-dia-mundial-de-la-filosofia-eslovenia\/#article","isPartOf":{"@id":"https:\/\/news.acropolis.org\/es\/2024\/talleres-en-el-dia-mundial-de-la-filosofia-eslovenia\/"},"author":{"name":"Slovenia","@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/833ec9d55fbdbe9ed80d0d68e19a658d"},"headline":"Talleres en el D\u00eda Mundial de la Filosof\u00eda (Eslovenia)","datePublished":"2024-01-21T11:40:27+00:00","mainEntityOfPage":{"@id":"https:\/\/news.acropolis.org\/es\/2024\/talleres-en-el-dia-mundial-de-la-filosofia-eslovenia\/"},"wordCount":197,"commentCount":0,"image":{"@id":"https:\/\/news.acropolis.org\/es\/2024\/talleres-en-el-dia-mundial-de-la-filosofia-eslovenia\/#primaryimage"},"thumbnailUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/01\/cloveskevrednote.jpg","articleSection":["D\u00eda Mundial de la Filosof\u00eda"],"inLanguage":"es-ES","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/news.acropolis.org\/es\/2024\/talleres-en-el-dia-mundial-de-la-filosofia-eslovenia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/news.acropolis.org\/es\/2024\/talleres-en-el-dia-mundial-de-la-filosofia-eslovenia\/","url":"https:\/\/news.acropolis.org\/es\/2024\/talleres-en-el-dia-mundial-de-la-filosofia-eslovenia\/","name":"Talleres en el D\u00eda Mundial de la Filosof\u00eda (Eslovenia) - Noticias de Nueva Acr\u00f3polis","isPartOf":{"@id":"https:\/\/news.acropolis.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/news.acropolis.org\/es\/2024\/talleres-en-el-dia-mundial-de-la-filosofia-eslovenia\/#primaryimage"},"image":{"@id":"https:\/\/news.acropolis.org\/es\/2024\/talleres-en-el-dia-mundial-de-la-filosofia-eslovenia\/#primaryimage"},"thumbnailUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/01\/cloveskevrednote.jpg","datePublished":"2024-01-21T11:40:27+00:00","author":{"@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/833ec9d55fbdbe9ed80d0d68e19a658d"},"breadcrumb":{"@id":"https:\/\/news.acropolis.org\/es\/2024\/talleres-en-el-dia-mundial-de-la-filosofia-eslovenia\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/news.acropolis.org\/es\/2024\/talleres-en-el-dia-mundial-de-la-filosofia-eslovenia\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/news.acropolis.org\/es\/2024\/talleres-en-el-dia-mundial-de-la-filosofia-eslovenia\/#primaryimage","url":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/01\/cloveskevrednote.jpg","contentUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/01\/cloveskevrednote.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/news.acropolis.org\/es\/2024\/talleres-en-el-dia-mundial-de-la-filosofia-eslovenia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/news.acropolis.org\/es\/"},{"@type":"ListItem","position":2,"name":"Talleres en el D\u00eda Mundial de la Filosof\u00eda (Eslovenia)"}]},{"@type":"WebSite","@id":"https:\/\/news.acropolis.org\/es\/#website","url":"https:\/\/news.acropolis.org\/es\/","name":"Noticias de Nueva Acr\u00f3polis","description":"Actividades de la Organizaci\u00f3n Internacional Nueva Acr\u00f3polis","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/news.acropolis.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/833ec9d55fbdbe9ed80d0d68e19a658d","name":"Slovenia","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/SVN.png","url":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/SVN.png","contentUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/SVN.png","caption":"Slovenia"},"sameAs":["http:\/\/www.akropola.org"],"url":"https:\/\/news.acropolis.org\/es\/author\/oinaeslo\/"}]}},"_links":{"self":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/91561","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/comments?post=91561"}],"version-history":[{"count":1,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/91561\/revisions"}],"predecessor-version":[{"id":91562,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/91561\/revisions\/91562"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/media\/91416"}],"wp:attachment":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/media?parent=91561"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/categories?post=91561"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/tags?post=91561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}