{"id":91935,"date":"2024-02-04T14:00:29","date_gmt":"2024-02-04T13:00:29","guid":{"rendered":"https:\/\/news.acropolis.org\/?p=91935"},"modified":"2024-02-04T14:00:29","modified_gmt":"2024-02-04T13:00:29","slug":"dia-mundial-de-la-filosofia-a-lo-largo-del-pais-ucrania","status":"publish","type":"post","link":"https:\/\/news.acropolis.org\/es\/2024\/dia-mundial-de-la-filosofia-a-lo-largo-del-pais-ucrania\/","title":{"rendered":"D\u00eda Mundial de la Filosof\u00eda a lo largo del pa\u00eds (Ucrania)"},"content":{"rendered":"<p class=\"p1\"><a href=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.06.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-91860\" src=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.06-300x200.jpeg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.06-300x200.jpeg 300w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.06-1024x682.jpeg 1024w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.06-768x512.jpeg 768w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.06-730x486.jpeg 730w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.06-435x290.jpeg 435w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.06.jpeg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Para celebrar el D\u00eda Mundial de la Filosof\u00eda, Nueva Acr\u00f3polis de Ucrania organiz\u00f3 diferentes eventos en siete de sus ciudades.<\/p>\n<p>En V\u00ednnytsia se present\u00f3 una nueva edici\u00f3n del di\u00e1logo &#8220;Men\u00f3n&#8221; de Plat\u00f3n. El libro fue traducido al idioma ucraniano y publicado por la Editorial Nueva Acr\u00f3polis en 2023.<\/p>\n<p>&#8220;Sobrevivir y crecer entre las arenas del tiempo&#8221;, obra representada en Lviv basada en el mito de Osiris.<\/p>\n<p>En Ivano-Frankivsk se llev\u00f3 a cabo una representaci\u00f3n basada en el ensayo de J. A. Livraga &#8220;El buzo&#8221;.<\/p>\n<p>En Zaporizhzhia se ofreci\u00f3 la conferencia interactiva &#8220;Tres pasos hacia la felicidad en Skovoroda&#8221;.<\/p>\n<p><a href=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.13.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-91854 alignright\" src=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.13-225x300.jpeg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.13-225x300.jpeg 225w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.13-768x1024.jpeg 768w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.13-730x973.jpeg 730w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.13-435x580.jpeg 435w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.13.jpeg 960w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><a href=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.24.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-91845\" src=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.24-300x169.jpeg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.24-300x169.jpeg 300w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.24-1024x576.jpeg 1024w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.24-768x432.jpeg 768w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.24-730x411.jpeg 730w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.24-435x245.jpeg 435w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.24.jpeg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>En Dnipro se celebr\u00f3 el taller sobre la comprensi\u00f3n filos\u00f3fica del tiempo y la conferencia &#8220;Filosof\u00eda de la libertad. Skovoroda <em>versus<\/em> Kant&#8221;.<\/p>\n<p>Nueva Acr\u00f3polis en Kiev organiz\u00f3 un taller sobre estoicismo.<\/p>\n<p>En Poltava tuvo lugar una conferencia sobre el fil\u00f3sofo y m\u00fasico ucraniano Hryhorii Skovoroda.<\/p>\n<p class=\"p1\">\n<p><a href=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.21.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-91848\" src=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.21-300x225.jpeg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.21-300x225.jpeg 300w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.21-1024x768.jpeg 1024w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.21-768x576.jpeg 768w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.21-730x548.jpeg 730w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.21-435x326.jpeg 435w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.21-80x60.jpeg 80w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.21.jpeg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.35.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-91836\" src=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.35-300x225.jpeg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.35-300x225.jpeg 300w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.35-1024x768.jpeg 1024w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.35-768x576.jpeg 768w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.35-730x548.jpeg 730w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.35-435x326.jpeg 435w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.35-80x60.jpeg 80w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.35.jpeg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.10.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-91857\" src=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.10-300x243.jpeg\" alt=\"\" width=\"300\" height=\"243\" srcset=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.10-300x243.jpeg 300w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.10-1024x828.jpeg 1024w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.10-768x621.jpeg 768w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.10-730x590.jpeg 730w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.10-435x352.jpeg 435w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.10.jpeg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.17.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-91851\" src=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.17-300x200.jpeg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.17-300x200.jpeg 300w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.17-1024x682.jpeg 1024w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.17-768x512.jpeg 768w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.17-730x486.jpeg 730w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.17-435x290.jpeg 435w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.17.jpeg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para celebrar el D\u00eda Mundial de la Filosof\u00eda, Nueva Acr\u00f3polis de Ucrania organiz\u00f3 diferentes eventos en siete de sus ciudades. En V\u00ednnytsia se present\u00f3 una nueva edici\u00f3n del di\u00e1logo &#8220;Men\u00f3n&#8221; [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":91853,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[50],"tags":[5382,171,5615,1196,1054],"class_list":["post-91935","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dia_filosofia","tag-new-acropolis-ukraine-es","tag-platon-es","tag-skovoroda-es","tag-ukraine-es","tag-world-philosophy-day-es","clearfix"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00eda Mundial de la Filosof\u00eda a lo largo del pa\u00eds (Ucrania) - Noticias de Nueva Acr\u00f3polis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/news.acropolis.org\/es\/2024\/dia-mundial-de-la-filosofia-a-lo-largo-del-pais-ucrania\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"D\u00eda Mundial de la Filosof\u00eda a lo largo del pa\u00eds (Ucrania) - Noticias de Nueva Acr\u00f3polis\" \/>\n<meta name=\"twitter:description\" content=\"Para celebrar el D\u00eda Mundial de la Filosof\u00eda, Nueva Acr\u00f3polis de Ucrania organiz\u00f3 diferentes eventos en siete de sus ciudades. En V\u00ednnytsia se present\u00f3 una nueva edici\u00f3n del di\u00e1logo &#8220;Men\u00f3n&#8221; [&hellip;]\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.17.jpeg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ucrania\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/dia-mundial-de-la-filosofia-a-lo-largo-del-pais-ucrania\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/dia-mundial-de-la-filosofia-a-lo-largo-del-pais-ucrania\\\/\"},\"author\":{\"name\":\"Ukraine\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/8e061c15dff50f06de8551e5506051b1\"},\"headline\":\"D\u00eda Mundial de la Filosof\u00eda a lo largo del pa\u00eds (Ucrania)\",\"datePublished\":\"2024-02-04T13:00:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/dia-mundial-de-la-filosofia-a-lo-largo-del-pais-ucrania\\\/\"},\"wordCount\":172,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/dia-mundial-de-la-filosofia-a-lo-largo-del-pais-ucrania\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/photo_2024-02-03-12.58.17.jpeg\",\"keywords\":[\"New Acropolis Ukraine\",\"Plat\u00f3n\",\"Skovoroda\",\"Ukraine\",\"World Philosophy Day\"],\"articleSection\":[\"D\u00eda Mundial de la Filosof\u00eda\"],\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/dia-mundial-de-la-filosofia-a-lo-largo-del-pais-ucrania\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/dia-mundial-de-la-filosofia-a-lo-largo-del-pais-ucrania\\\/\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/dia-mundial-de-la-filosofia-a-lo-largo-del-pais-ucrania\\\/\",\"name\":\"D\u00eda Mundial de la Filosof\u00eda a lo largo del pa\u00eds (Ucrania) - Noticias de Nueva Acr\u00f3polis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/dia-mundial-de-la-filosofia-a-lo-largo-del-pais-ucrania\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/dia-mundial-de-la-filosofia-a-lo-largo-del-pais-ucrania\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/photo_2024-02-03-12.58.17.jpeg\",\"datePublished\":\"2024-02-04T13:00:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/8e061c15dff50f06de8551e5506051b1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/dia-mundial-de-la-filosofia-a-lo-largo-del-pais-ucrania\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/dia-mundial-de-la-filosofia-a-lo-largo-del-pais-ucrania\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/dia-mundial-de-la-filosofia-a-lo-largo-del-pais-ucrania\\\/#primaryimage\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/photo_2024-02-03-12.58.17.jpeg\",\"contentUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/photo_2024-02-03-12.58.17.jpeg\",\"width\":1280,\"height\":853},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/dia-mundial-de-la-filosofia-a-lo-largo-del-pais-ucrania\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00eda Mundial de la Filosof\u00eda a lo largo del pa\u00eds (Ucrania)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/\",\"name\":\"Noticias de Nueva Acr\u00f3polis\",\"description\":\"Actividades de la Organizaci\u00f3n Internacional Nueva Acr\u00f3polis\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/8e061c15dff50f06de8551e5506051b1\",\"name\":\"Ukraine\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/UKR.png\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/UKR.png\",\"contentUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/UKR.png\",\"caption\":\"Ukraine\"},\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/author\\\/oinauc\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00eda Mundial de la Filosof\u00eda a lo largo del pa\u00eds (Ucrania) - Noticias de Nueva Acr\u00f3polis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/news.acropolis.org\/es\/2024\/dia-mundial-de-la-filosofia-a-lo-largo-del-pais-ucrania\/","twitter_card":"summary_large_image","twitter_title":"D\u00eda Mundial de la Filosof\u00eda a lo largo del pa\u00eds (Ucrania) - Noticias de Nueva Acr\u00f3polis","twitter_description":"Para celebrar el D\u00eda Mundial de la Filosof\u00eda, Nueva Acr\u00f3polis de Ucrania organiz\u00f3 diferentes eventos en siete de sus ciudades. En V\u00ednnytsia se present\u00f3 una nueva edici\u00f3n del di\u00e1logo &#8220;Men\u00f3n&#8221; [&hellip;]","twitter_image":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.17.jpeg","twitter_misc":{"Escrito por":"Ucrania","Tiempo de lectura":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/news.acropolis.org\/es\/2024\/dia-mundial-de-la-filosofia-a-lo-largo-del-pais-ucrania\/#article","isPartOf":{"@id":"https:\/\/news.acropolis.org\/es\/2024\/dia-mundial-de-la-filosofia-a-lo-largo-del-pais-ucrania\/"},"author":{"name":"Ukraine","@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/8e061c15dff50f06de8551e5506051b1"},"headline":"D\u00eda Mundial de la Filosof\u00eda a lo largo del pa\u00eds (Ucrania)","datePublished":"2024-02-04T13:00:29+00:00","mainEntityOfPage":{"@id":"https:\/\/news.acropolis.org\/es\/2024\/dia-mundial-de-la-filosofia-a-lo-largo-del-pais-ucrania\/"},"wordCount":172,"commentCount":0,"image":{"@id":"https:\/\/news.acropolis.org\/es\/2024\/dia-mundial-de-la-filosofia-a-lo-largo-del-pais-ucrania\/#primaryimage"},"thumbnailUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.17.jpeg","keywords":["New Acropolis Ukraine","Plat\u00f3n","Skovoroda","Ukraine","World Philosophy Day"],"articleSection":["D\u00eda Mundial de la Filosof\u00eda"],"inLanguage":"es-ES","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/news.acropolis.org\/es\/2024\/dia-mundial-de-la-filosofia-a-lo-largo-del-pais-ucrania\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/news.acropolis.org\/es\/2024\/dia-mundial-de-la-filosofia-a-lo-largo-del-pais-ucrania\/","url":"https:\/\/news.acropolis.org\/es\/2024\/dia-mundial-de-la-filosofia-a-lo-largo-del-pais-ucrania\/","name":"D\u00eda Mundial de la Filosof\u00eda a lo largo del pa\u00eds (Ucrania) - Noticias de Nueva Acr\u00f3polis","isPartOf":{"@id":"https:\/\/news.acropolis.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/news.acropolis.org\/es\/2024\/dia-mundial-de-la-filosofia-a-lo-largo-del-pais-ucrania\/#primaryimage"},"image":{"@id":"https:\/\/news.acropolis.org\/es\/2024\/dia-mundial-de-la-filosofia-a-lo-largo-del-pais-ucrania\/#primaryimage"},"thumbnailUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.17.jpeg","datePublished":"2024-02-04T13:00:29+00:00","author":{"@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/8e061c15dff50f06de8551e5506051b1"},"breadcrumb":{"@id":"https:\/\/news.acropolis.org\/es\/2024\/dia-mundial-de-la-filosofia-a-lo-largo-del-pais-ucrania\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/news.acropolis.org\/es\/2024\/dia-mundial-de-la-filosofia-a-lo-largo-del-pais-ucrania\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/news.acropolis.org\/es\/2024\/dia-mundial-de-la-filosofia-a-lo-largo-del-pais-ucrania\/#primaryimage","url":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.17.jpeg","contentUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/photo_2024-02-03-12.58.17.jpeg","width":1280,"height":853},{"@type":"BreadcrumbList","@id":"https:\/\/news.acropolis.org\/es\/2024\/dia-mundial-de-la-filosofia-a-lo-largo-del-pais-ucrania\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/news.acropolis.org\/es\/"},{"@type":"ListItem","position":2,"name":"D\u00eda Mundial de la Filosof\u00eda a lo largo del pa\u00eds (Ucrania)"}]},{"@type":"WebSite","@id":"https:\/\/news.acropolis.org\/es\/#website","url":"https:\/\/news.acropolis.org\/es\/","name":"Noticias de Nueva Acr\u00f3polis","description":"Actividades de la Organizaci\u00f3n Internacional Nueva Acr\u00f3polis","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/news.acropolis.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/8e061c15dff50f06de8551e5506051b1","name":"Ukraine","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/UKR.png","url":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/UKR.png","contentUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/UKR.png","caption":"Ukraine"},"url":"https:\/\/news.acropolis.org\/es\/author\/oinauc\/"}]}},"_links":{"self":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/91935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/comments?post=91935"}],"version-history":[{"count":2,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/91935\/revisions"}],"predecessor-version":[{"id":91937,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/91935\/revisions\/91937"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/media\/91853"}],"wp:attachment":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/media?parent=91935"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/categories?post=91935"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/tags?post=91935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}