{"id":92600,"date":"2024-03-03T12:03:59","date_gmt":"2024-03-03T11:03:59","guid":{"rendered":"https:\/\/news.acropolis.org\/?p=92600"},"modified":"2024-03-03T12:03:59","modified_gmt":"2024-03-03T11:03:59","slug":"el-hombre-y-su-sombra-bratislava-eslovaquia","status":"publish","type":"post","link":"https:\/\/news.acropolis.org\/es\/2024\/el-hombre-y-su-sombra-bratislava-eslovaquia\/","title":{"rendered":"El hombre y su sombra (Bratislava, Eslovaquia)"},"content":{"rendered":"<p>Seminario de fin de semana titulado &#8220;La Sombra&#8221;, uno de los arquetipos descritos por el psiquiatra suizo C. G. Jung. \u00c9l y otros expertos que han tratado este tema nos ofrecen muchas posibilidades para revelar y procesar gradualmente las Sombras en nuestro mundo ps\u00edquico. La conferencia se complet\u00f3 con una escena teatral del grupo de teatro Mythos basada en el cuento de hadas de H. Ch. La &#8220;Sombra&#8221; de Andersen.<\/p>\n<p><a href=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/20240127_Clovek_Tien_4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-92426\" src=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/20240127_Clovek_Tien_4.jpg\" alt=\"\" width=\"953\" height=\"538\" srcset=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/20240127_Clovek_Tien_4.jpg 953w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/20240127_Clovek_Tien_4-300x169.jpg 300w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/20240127_Clovek_Tien_4-768x434.jpg 768w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/20240127_Clovek_Tien_4-730x412.jpg 730w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/20240127_Clovek_Tien_4-435x246.jpg 435w\" sizes=\"auto, (max-width: 953px) 100vw, 953px\" \/><\/a> <a href=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/20240127_Clovek_Tien_1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-92429\" src=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/20240127_Clovek_Tien_1.jpg\" alt=\"\" width=\"960\" height=\"720\" srcset=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/20240127_Clovek_Tien_1.jpg 960w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/20240127_Clovek_Tien_1-300x225.jpg 300w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/20240127_Clovek_Tien_1-768x576.jpg 768w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/20240127_Clovek_Tien_1-730x548.jpg 730w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/20240127_Clovek_Tien_1-435x326.jpg 435w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/20240127_Clovek_Tien_1-80x60.jpg 80w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seminario de fin de semana titulado &#8220;La Sombra&#8221;, uno de los arquetipos descritos por el psiquiatra suizo C. G. Jung. \u00c9l y otros expertos que han tratado este tema nos [&hellip;]<\/p>\n","protected":false},"author":36,"featured_media":92431,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[],"class_list":["post-92600","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actividades_culturales","clearfix"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El hombre y su sombra (Bratislava, Eslovaquia) - Noticias de Nueva Acr\u00f3polis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/news.acropolis.org\/es\/2024\/el-hombre-y-su-sombra-bratislava-eslovaquia\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"El hombre y su sombra (Bratislava, Eslovaquia) - Noticias de Nueva Acr\u00f3polis\" \/>\n<meta name=\"twitter:description\" content=\"Seminario de fin de semana titulado &#8220;La Sombra&#8221;, uno de los arquetipos descritos por el psiquiatra suizo C. G. Jung. \u00c9l y otros expertos que han tratado este tema nos [&hellip;]\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/20240127_Clovek_Tien_1.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eslovaquia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/el-hombre-y-su-sombra-bratislava-eslovaquia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/el-hombre-y-su-sombra-bratislava-eslovaquia\\\/\"},\"author\":{\"name\":\"Slovakia\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/1a1f5a206a7bb7a0c85e469ae9463b6d\"},\"headline\":\"El hombre y su sombra (Bratislava, Eslovaquia)\",\"datePublished\":\"2024-03-03T11:03:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/el-hombre-y-su-sombra-bratislava-eslovaquia\\\/\"},\"wordCount\":78,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/el-hombre-y-su-sombra-bratislava-eslovaquia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/20240127_Clovek_Tien_1.jpg\",\"articleSection\":[\"Actividades Culturales\"],\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/el-hombre-y-su-sombra-bratislava-eslovaquia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/el-hombre-y-su-sombra-bratislava-eslovaquia\\\/\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/el-hombre-y-su-sombra-bratislava-eslovaquia\\\/\",\"name\":\"El hombre y su sombra (Bratislava, Eslovaquia) - Noticias de Nueva Acr\u00f3polis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/el-hombre-y-su-sombra-bratislava-eslovaquia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/el-hombre-y-su-sombra-bratislava-eslovaquia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/20240127_Clovek_Tien_1.jpg\",\"datePublished\":\"2024-03-03T11:03:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/1a1f5a206a7bb7a0c85e469ae9463b6d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/el-hombre-y-su-sombra-bratislava-eslovaquia\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/el-hombre-y-su-sombra-bratislava-eslovaquia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/el-hombre-y-su-sombra-bratislava-eslovaquia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/20240127_Clovek_Tien_1.jpg\",\"contentUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/20240127_Clovek_Tien_1.jpg\",\"width\":960,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2024\\\/el-hombre-y-su-sombra-bratislava-eslovaquia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El hombre y su sombra (Bratislava, Eslovaquia)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/\",\"name\":\"Noticias de Nueva Acr\u00f3polis\",\"description\":\"Actividades de la Organizaci\u00f3n Internacional Nueva Acr\u00f3polis\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/1a1f5a206a7bb7a0c85e469ae9463b6d\",\"name\":\"Slovakia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/SVK.png\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/SVK.png\",\"contentUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/SVK.png\",\"caption\":\"Slovakia\"},\"sameAs\":[\"http:\\\/\\\/www.akropolis.sk\"],\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/author\\\/oinaesk\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El hombre y su sombra (Bratislava, Eslovaquia) - Noticias de Nueva Acr\u00f3polis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/news.acropolis.org\/es\/2024\/el-hombre-y-su-sombra-bratislava-eslovaquia\/","twitter_card":"summary_large_image","twitter_title":"El hombre y su sombra (Bratislava, Eslovaquia) - Noticias de Nueva Acr\u00f3polis","twitter_description":"Seminario de fin de semana titulado &#8220;La Sombra&#8221;, uno de los arquetipos descritos por el psiquiatra suizo C. G. Jung. \u00c9l y otros expertos que han tratado este tema nos [&hellip;]","twitter_image":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/20240127_Clovek_Tien_1.jpg","twitter_misc":{"Escrito por":"Eslovaquia","Tiempo de lectura":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/news.acropolis.org\/es\/2024\/el-hombre-y-su-sombra-bratislava-eslovaquia\/#article","isPartOf":{"@id":"https:\/\/news.acropolis.org\/es\/2024\/el-hombre-y-su-sombra-bratislava-eslovaquia\/"},"author":{"name":"Slovakia","@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/1a1f5a206a7bb7a0c85e469ae9463b6d"},"headline":"El hombre y su sombra (Bratislava, Eslovaquia)","datePublished":"2024-03-03T11:03:59+00:00","mainEntityOfPage":{"@id":"https:\/\/news.acropolis.org\/es\/2024\/el-hombre-y-su-sombra-bratislava-eslovaquia\/"},"wordCount":78,"commentCount":0,"image":{"@id":"https:\/\/news.acropolis.org\/es\/2024\/el-hombre-y-su-sombra-bratislava-eslovaquia\/#primaryimage"},"thumbnailUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/20240127_Clovek_Tien_1.jpg","articleSection":["Actividades Culturales"],"inLanguage":"es-ES","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/news.acropolis.org\/es\/2024\/el-hombre-y-su-sombra-bratislava-eslovaquia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/news.acropolis.org\/es\/2024\/el-hombre-y-su-sombra-bratislava-eslovaquia\/","url":"https:\/\/news.acropolis.org\/es\/2024\/el-hombre-y-su-sombra-bratislava-eslovaquia\/","name":"El hombre y su sombra (Bratislava, Eslovaquia) - Noticias de Nueva Acr\u00f3polis","isPartOf":{"@id":"https:\/\/news.acropolis.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/news.acropolis.org\/es\/2024\/el-hombre-y-su-sombra-bratislava-eslovaquia\/#primaryimage"},"image":{"@id":"https:\/\/news.acropolis.org\/es\/2024\/el-hombre-y-su-sombra-bratislava-eslovaquia\/#primaryimage"},"thumbnailUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/20240127_Clovek_Tien_1.jpg","datePublished":"2024-03-03T11:03:59+00:00","author":{"@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/1a1f5a206a7bb7a0c85e469ae9463b6d"},"breadcrumb":{"@id":"https:\/\/news.acropolis.org\/es\/2024\/el-hombre-y-su-sombra-bratislava-eslovaquia\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/news.acropolis.org\/es\/2024\/el-hombre-y-su-sombra-bratislava-eslovaquia\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/news.acropolis.org\/es\/2024\/el-hombre-y-su-sombra-bratislava-eslovaquia\/#primaryimage","url":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/20240127_Clovek_Tien_1.jpg","contentUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2024\/02\/20240127_Clovek_Tien_1.jpg","width":960,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/news.acropolis.org\/es\/2024\/el-hombre-y-su-sombra-bratislava-eslovaquia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/news.acropolis.org\/es\/"},{"@type":"ListItem","position":2,"name":"El hombre y su sombra (Bratislava, Eslovaquia)"}]},{"@type":"WebSite","@id":"https:\/\/news.acropolis.org\/es\/#website","url":"https:\/\/news.acropolis.org\/es\/","name":"Noticias de Nueva Acr\u00f3polis","description":"Actividades de la Organizaci\u00f3n Internacional Nueva Acr\u00f3polis","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/news.acropolis.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/1a1f5a206a7bb7a0c85e469ae9463b6d","name":"Slovakia","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/SVK.png","url":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/SVK.png","contentUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/SVK.png","caption":"Slovakia"},"sameAs":["http:\/\/www.akropolis.sk"],"url":"https:\/\/news.acropolis.org\/es\/author\/oinaesk\/"}]}},"_links":{"self":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/92600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/comments?post=92600"}],"version-history":[{"count":1,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/92600\/revisions"}],"predecessor-version":[{"id":92601,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/92600\/revisions\/92601"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/media\/92431"}],"wp:attachment":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/media?parent=92600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/categories?post=92600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/tags?post=92600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}