{"id":9555,"date":"2014-07-06T20:00:54","date_gmt":"2014-07-06T18:00:54","guid":{"rendered":"https:\/\/news.acropolis.org\/?p=9555"},"modified":"2014-07-06T20:36:15","modified_gmt":"2014-07-06T18:36:15","slug":"conferencias-para-los-estudiantes-de-la-universidad-de-brno-brno-republica-checa","status":"publish","type":"post","link":"https:\/\/news.acropolis.org\/es\/2014\/conferencias-para-los-estudiantes-de-la-universidad-de-brno-brno-republica-checa\/","title":{"rendered":"Conferencias para los estudiantes de la Universidad de Brno (Brno, Rep\u00fablica Checa)"},"content":{"rendered":"<p><a href=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2014\/06\/800_brno_duben_propravniky.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-9556\" src=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2014\/06\/800_brno_duben_propravniky-300x231.jpg\" alt=\"800_brno_duben_propravniky\" width=\"300\" height=\"231\" srcset=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2014\/06\/800_brno_duben_propravniky-300x231.jpg 300w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2014\/06\/800_brno_duben_propravniky-200x154.jpg 200w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2014\/06\/800_brno_duben_propravniky-600x462.jpg 600w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2014\/06\/800_brno_duben_propravniky.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\u00a0Nueva Acr\u00f3polis en Brno ofreci\u00f3 una serie de conferencias\u00a0sobre la capacidad de comunicaci\u00f3n y de organizaci\u00f3n del tiempo\u00a0a los\u00a0estudiantes de la Facultad de Derecho\u00a0de la ciudad<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0Nueva Acr\u00f3polis en Brno ofreci\u00f3 una serie de conferencias\u00a0sobre la capacidad de comunicaci\u00f3n y de organizaci\u00f3n del tiempo\u00a0a los\u00a0estudiantes de la Facultad de Derecho\u00a0de la ciudad<\/p>\n","protected":false},"author":7,"featured_media":9556,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[47],"tags":[],"class_list":["post-9555","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actividades_educativas","clearfix"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conferencias para los estudiantes de la Universidad de Brno (Brno, Rep\u00fablica Checa) - Noticias de Nueva Acr\u00f3polis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/news.acropolis.org\/es\/2014\/conferencias-para-los-estudiantes-de-la-universidad-de-brno-brno-republica-checa\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Conferencias para los estudiantes de la Universidad de Brno (Brno, Rep\u00fablica Checa) - Noticias de Nueva Acr\u00f3polis\" \/>\n<meta name=\"twitter:description\" content=\"\u00a0Nueva Acr\u00f3polis en Brno ofreci\u00f3 una serie de conferencias\u00a0sobre la capacidad de comunicaci\u00f3n y de organizaci\u00f3n del tiempo\u00a0a los\u00a0estudiantes de la Facultad de Derecho\u00a0de la ciudad\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2014\/06\/800_brno_duben_propravniky.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rep\u00fablica Checa\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2014\\\/conferencias-para-los-estudiantes-de-la-universidad-de-brno-brno-republica-checa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2014\\\/conferencias-para-los-estudiantes-de-la-universidad-de-brno-brno-republica-checa\\\/\"},\"author\":{\"name\":\"Czech Republic\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/707297d714ad77479e9463b255f5e3d9\"},\"headline\":\"Conferencias para los estudiantes de la Universidad de Brno (Brno, Rep\u00fablica Checa)\",\"datePublished\":\"2014-07-06T18:00:54+00:00\",\"dateModified\":\"2014-07-06T18:36:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2014\\\/conferencias-para-los-estudiantes-de-la-universidad-de-brno-brno-republica-checa\\\/\"},\"wordCount\":46,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2014\\\/conferencias-para-los-estudiantes-de-la-universidad-de-brno-brno-republica-checa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/800_brno_duben_propravniky.jpg\",\"articleSection\":[\"Actividades Educativas\"],\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2014\\\/conferencias-para-los-estudiantes-de-la-universidad-de-brno-brno-republica-checa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2014\\\/conferencias-para-los-estudiantes-de-la-universidad-de-brno-brno-republica-checa\\\/\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2014\\\/conferencias-para-los-estudiantes-de-la-universidad-de-brno-brno-republica-checa\\\/\",\"name\":\"Conferencias para los estudiantes de la Universidad de Brno (Brno, Rep\u00fablica Checa) - Noticias de Nueva Acr\u00f3polis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2014\\\/conferencias-para-los-estudiantes-de-la-universidad-de-brno-brno-republica-checa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2014\\\/conferencias-para-los-estudiantes-de-la-universidad-de-brno-brno-republica-checa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/800_brno_duben_propravniky.jpg\",\"datePublished\":\"2014-07-06T18:00:54+00:00\",\"dateModified\":\"2014-07-06T18:36:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/707297d714ad77479e9463b255f5e3d9\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2014\\\/conferencias-para-los-estudiantes-de-la-universidad-de-brno-brno-republica-checa\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2014\\\/conferencias-para-los-estudiantes-de-la-universidad-de-brno-brno-republica-checa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2014\\\/conferencias-para-los-estudiantes-de-la-universidad-de-brno-brno-republica-checa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/800_brno_duben_propravniky.jpg\",\"contentUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/800_brno_duben_propravniky.jpg\",\"width\":800,\"height\":616},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2014\\\/conferencias-para-los-estudiantes-de-la-universidad-de-brno-brno-republica-checa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conferencias para los estudiantes de la Universidad de Brno (Brno, Rep\u00fablica Checa)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/\",\"name\":\"Noticias de Nueva Acr\u00f3polis\",\"description\":\"Actividades de la Organizaci\u00f3n Internacional Nueva Acr\u00f3polis\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/707297d714ad77479e9463b255f5e3d9\",\"name\":\"Czech Republic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/CZE.png\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/CZE.png\",\"contentUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/CZE.png\",\"caption\":\"Czech Republic\"},\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/author\\\/oinaches\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conferencias para los estudiantes de la Universidad de Brno (Brno, Rep\u00fablica Checa) - Noticias de Nueva Acr\u00f3polis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/news.acropolis.org\/es\/2014\/conferencias-para-los-estudiantes-de-la-universidad-de-brno-brno-republica-checa\/","twitter_card":"summary_large_image","twitter_title":"Conferencias para los estudiantes de la Universidad de Brno (Brno, Rep\u00fablica Checa) - Noticias de Nueva Acr\u00f3polis","twitter_description":"\u00a0Nueva Acr\u00f3polis en Brno ofreci\u00f3 una serie de conferencias\u00a0sobre la capacidad de comunicaci\u00f3n y de organizaci\u00f3n del tiempo\u00a0a los\u00a0estudiantes de la Facultad de Derecho\u00a0de la ciudad","twitter_image":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2014\/06\/800_brno_duben_propravniky.jpg","twitter_misc":{"Escrito por":"Rep\u00fablica Checa"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/news.acropolis.org\/es\/2014\/conferencias-para-los-estudiantes-de-la-universidad-de-brno-brno-republica-checa\/#article","isPartOf":{"@id":"https:\/\/news.acropolis.org\/es\/2014\/conferencias-para-los-estudiantes-de-la-universidad-de-brno-brno-republica-checa\/"},"author":{"name":"Czech Republic","@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/707297d714ad77479e9463b255f5e3d9"},"headline":"Conferencias para los estudiantes de la Universidad de Brno (Brno, Rep\u00fablica Checa)","datePublished":"2014-07-06T18:00:54+00:00","dateModified":"2014-07-06T18:36:15+00:00","mainEntityOfPage":{"@id":"https:\/\/news.acropolis.org\/es\/2014\/conferencias-para-los-estudiantes-de-la-universidad-de-brno-brno-republica-checa\/"},"wordCount":46,"commentCount":0,"image":{"@id":"https:\/\/news.acropolis.org\/es\/2014\/conferencias-para-los-estudiantes-de-la-universidad-de-brno-brno-republica-checa\/#primaryimage"},"thumbnailUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2014\/06\/800_brno_duben_propravniky.jpg","articleSection":["Actividades Educativas"],"inLanguage":"es-ES","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/news.acropolis.org\/es\/2014\/conferencias-para-los-estudiantes-de-la-universidad-de-brno-brno-republica-checa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/news.acropolis.org\/es\/2014\/conferencias-para-los-estudiantes-de-la-universidad-de-brno-brno-republica-checa\/","url":"https:\/\/news.acropolis.org\/es\/2014\/conferencias-para-los-estudiantes-de-la-universidad-de-brno-brno-republica-checa\/","name":"Conferencias para los estudiantes de la Universidad de Brno (Brno, Rep\u00fablica Checa) - Noticias de Nueva Acr\u00f3polis","isPartOf":{"@id":"https:\/\/news.acropolis.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/news.acropolis.org\/es\/2014\/conferencias-para-los-estudiantes-de-la-universidad-de-brno-brno-republica-checa\/#primaryimage"},"image":{"@id":"https:\/\/news.acropolis.org\/es\/2014\/conferencias-para-los-estudiantes-de-la-universidad-de-brno-brno-republica-checa\/#primaryimage"},"thumbnailUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2014\/06\/800_brno_duben_propravniky.jpg","datePublished":"2014-07-06T18:00:54+00:00","dateModified":"2014-07-06T18:36:15+00:00","author":{"@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/707297d714ad77479e9463b255f5e3d9"},"breadcrumb":{"@id":"https:\/\/news.acropolis.org\/es\/2014\/conferencias-para-los-estudiantes-de-la-universidad-de-brno-brno-republica-checa\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/news.acropolis.org\/es\/2014\/conferencias-para-los-estudiantes-de-la-universidad-de-brno-brno-republica-checa\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/news.acropolis.org\/es\/2014\/conferencias-para-los-estudiantes-de-la-universidad-de-brno-brno-republica-checa\/#primaryimage","url":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2014\/06\/800_brno_duben_propravniky.jpg","contentUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2014\/06\/800_brno_duben_propravniky.jpg","width":800,"height":616},{"@type":"BreadcrumbList","@id":"https:\/\/news.acropolis.org\/es\/2014\/conferencias-para-los-estudiantes-de-la-universidad-de-brno-brno-republica-checa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/news.acropolis.org\/es\/"},{"@type":"ListItem","position":2,"name":"Conferencias para los estudiantes de la Universidad de Brno (Brno, Rep\u00fablica Checa)"}]},{"@type":"WebSite","@id":"https:\/\/news.acropolis.org\/es\/#website","url":"https:\/\/news.acropolis.org\/es\/","name":"Noticias de Nueva Acr\u00f3polis","description":"Actividades de la Organizaci\u00f3n Internacional Nueva Acr\u00f3polis","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/news.acropolis.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/707297d714ad77479e9463b255f5e3d9","name":"Czech Republic","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/CZE.png","url":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/CZE.png","contentUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/CZE.png","caption":"Czech Republic"},"url":"https:\/\/news.acropolis.org\/es\/author\/oinaches\/"}]}},"_links":{"self":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/9555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/comments?post=9555"}],"version-history":[{"count":5,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/9555\/revisions"}],"predecessor-version":[{"id":9948,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/9555\/revisions\/9948"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/media\/9556"}],"wp:attachment":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/media?parent=9555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/categories?post=9555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/tags?post=9555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}