{"id":9742,"date":"2014-06-25T21:09:34","date_gmt":"2014-06-25T19:09:34","guid":{"rendered":"https:\/\/news.acropolis.org\/?p=9742"},"modified":"2014-06-25T21:09:34","modified_gmt":"2014-06-25T19:09:34","slug":"representacion-teatral-la-muerte-de-socrates-malaga-espana","status":"publish","type":"post","link":"https:\/\/news.acropolis.org\/es\/2014\/representacion-teatral-la-muerte-de-socrates-malaga-espana\/","title":{"rendered":"Representaci\u00f3n teatral &#8220;La muerte de S\u00f3crates&#8221; (M\u00e1laga, Espa\u00f1a)"},"content":{"rendered":"<p>Nueva Acr\u00f3polis M\u00e1laga particip\u00f3<img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-7596\" src=\"https:\/\/noticias.nueva-acropolis.es\/wp-content\/uploads\/2014\/06\/DSCN7276-300x140.jpg\" alt=\"DSCN7276\" width=\"300\" height=\"140\" \/>\u00a0en la Semana Cultural que organiza la Asociaci\u00f3n de Vecinos de la Roca de esta ciudad con el grupo Teatro de las Ideas que puso en escena la\u00a0obra titulada \u00a0\u201cLa muerte de S\u00f3crates\u201d.<\/p>\n<p><a href=\"https:\/\/noticias.nueva-acropolis.es\/wp-content\/uploads\/2014\/06\/DSCN7319.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-7598 alignright\" src=\"https:\/\/noticias.nueva-acropolis.es\/wp-content\/uploads\/2014\/06\/DSCN7319-300x114.jpg\" alt=\"DSCN7319\" width=\"300\" height=\"114\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/noticias.nueva-acropolis.es\/wp-content\/uploads\/2014\/06\/DSCN7306.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-7597 size-medium\" src=\"https:\/\/noticias.nueva-acropolis.es\/wp-content\/uploads\/2014\/06\/DSCN7306-300x80.jpg\" alt=\"DSCN7306\" width=\"300\" height=\"80\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nueva Acr\u00f3polis M\u00e1laga particip\u00f3\u00a0en la Semana Cultural que organiza la Asociaci\u00f3n de Vecinos de la Roca de esta ciudad con el grupo Teatro de las Ideas que puso en escena [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":7596,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[],"class_list":["post-9742","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actividades_culturales","clearfix"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Representaci\u00f3n teatral &quot;La muerte de S\u00f3crates&quot; (M\u00e1laga, Espa\u00f1a) - Noticias de Nueva Acr\u00f3polis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/news.acropolis.org\/es\/2014\/representacion-teatral-la-muerte-de-socrates-malaga-espana\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Representaci\u00f3n teatral &quot;La muerte de S\u00f3crates&quot; (M\u00e1laga, Espa\u00f1a) - Noticias de Nueva Acr\u00f3polis\" \/>\n<meta name=\"twitter:description\" content=\"Nueva Acr\u00f3polis M\u00e1laga particip\u00f3\u00a0en la Semana Cultural que organiza la Asociaci\u00f3n de Vecinos de la Roca de esta ciudad con el grupo Teatro de las Ideas que puso en escena [&hellip;]\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Espa\u00f1a\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2014\\\/representacion-teatral-la-muerte-de-socrates-malaga-espana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2014\\\/representacion-teatral-la-muerte-de-socrates-malaga-espana\\\/\"},\"author\":{\"name\":\"Spain\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/ced850172dfe4e556569b56610e2183e\"},\"headline\":\"Representaci\u00f3n teatral &#8220;La muerte de S\u00f3crates&#8221; (M\u00e1laga, Espa\u00f1a)\",\"datePublished\":\"2014-06-25T19:09:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2014\\\/representacion-teatral-la-muerte-de-socrates-malaga-espana\\\/\"},\"wordCount\":55,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2014\\\/representacion-teatral-la-muerte-de-socrates-malaga-espana\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Actividades Culturales\"],\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2014\\\/representacion-teatral-la-muerte-de-socrates-malaga-espana\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2014\\\/representacion-teatral-la-muerte-de-socrates-malaga-espana\\\/\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2014\\\/representacion-teatral-la-muerte-de-socrates-malaga-espana\\\/\",\"name\":\"Representaci\u00f3n teatral \\\"La muerte de S\u00f3crates\\\" (M\u00e1laga, Espa\u00f1a) - Noticias de Nueva Acr\u00f3polis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2014\\\/representacion-teatral-la-muerte-de-socrates-malaga-espana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2014\\\/representacion-teatral-la-muerte-de-socrates-malaga-espana\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2014-06-25T19:09:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/ced850172dfe4e556569b56610e2183e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2014\\\/representacion-teatral-la-muerte-de-socrates-malaga-espana\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2014\\\/representacion-teatral-la-muerte-de-socrates-malaga-espana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2014\\\/representacion-teatral-la-muerte-de-socrates-malaga-espana\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/2014\\\/representacion-teatral-la-muerte-de-socrates-malaga-espana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Representaci\u00f3n teatral &#8220;La muerte de S\u00f3crates&#8221; (M\u00e1laga, Espa\u00f1a)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/\",\"name\":\"Noticias de Nueva Acr\u00f3polis\",\"description\":\"Actividades de la Organizaci\u00f3n Internacional Nueva Acr\u00f3polis\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/#\\\/schema\\\/person\\\/ced850172dfe4e556569b56610e2183e\",\"name\":\"Spain\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/ESP.png\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/ESP.png\",\"contentUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/ESP.png\",\"caption\":\"Spain\"},\"url\":\"https:\\\/\\\/news.acropolis.org\\\/es\\\/author\\\/oinaes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Representaci\u00f3n teatral \"La muerte de S\u00f3crates\" (M\u00e1laga, Espa\u00f1a) - Noticias de Nueva Acr\u00f3polis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/news.acropolis.org\/es\/2014\/representacion-teatral-la-muerte-de-socrates-malaga-espana\/","twitter_card":"summary_large_image","twitter_title":"Representaci\u00f3n teatral \"La muerte de S\u00f3crates\" (M\u00e1laga, Espa\u00f1a) - Noticias de Nueva Acr\u00f3polis","twitter_description":"Nueva Acr\u00f3polis M\u00e1laga particip\u00f3\u00a0en la Semana Cultural que organiza la Asociaci\u00f3n de Vecinos de la Roca de esta ciudad con el grupo Teatro de las Ideas que puso en escena [&hellip;]","twitter_misc":{"Escrito por":"Espa\u00f1a"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/news.acropolis.org\/es\/2014\/representacion-teatral-la-muerte-de-socrates-malaga-espana\/#article","isPartOf":{"@id":"https:\/\/news.acropolis.org\/es\/2014\/representacion-teatral-la-muerte-de-socrates-malaga-espana\/"},"author":{"name":"Spain","@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/ced850172dfe4e556569b56610e2183e"},"headline":"Representaci\u00f3n teatral &#8220;La muerte de S\u00f3crates&#8221; (M\u00e1laga, Espa\u00f1a)","datePublished":"2014-06-25T19:09:34+00:00","mainEntityOfPage":{"@id":"https:\/\/news.acropolis.org\/es\/2014\/representacion-teatral-la-muerte-de-socrates-malaga-espana\/"},"wordCount":55,"commentCount":0,"image":{"@id":"https:\/\/news.acropolis.org\/es\/2014\/representacion-teatral-la-muerte-de-socrates-malaga-espana\/#primaryimage"},"thumbnailUrl":"","articleSection":["Actividades Culturales"],"inLanguage":"es-ES","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/news.acropolis.org\/es\/2014\/representacion-teatral-la-muerte-de-socrates-malaga-espana\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/news.acropolis.org\/es\/2014\/representacion-teatral-la-muerte-de-socrates-malaga-espana\/","url":"https:\/\/news.acropolis.org\/es\/2014\/representacion-teatral-la-muerte-de-socrates-malaga-espana\/","name":"Representaci\u00f3n teatral \"La muerte de S\u00f3crates\" (M\u00e1laga, Espa\u00f1a) - Noticias de Nueva Acr\u00f3polis","isPartOf":{"@id":"https:\/\/news.acropolis.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/news.acropolis.org\/es\/2014\/representacion-teatral-la-muerte-de-socrates-malaga-espana\/#primaryimage"},"image":{"@id":"https:\/\/news.acropolis.org\/es\/2014\/representacion-teatral-la-muerte-de-socrates-malaga-espana\/#primaryimage"},"thumbnailUrl":"","datePublished":"2014-06-25T19:09:34+00:00","author":{"@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/ced850172dfe4e556569b56610e2183e"},"breadcrumb":{"@id":"https:\/\/news.acropolis.org\/es\/2014\/representacion-teatral-la-muerte-de-socrates-malaga-espana\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/news.acropolis.org\/es\/2014\/representacion-teatral-la-muerte-de-socrates-malaga-espana\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/news.acropolis.org\/es\/2014\/representacion-teatral-la-muerte-de-socrates-malaga-espana\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/news.acropolis.org\/es\/2014\/representacion-teatral-la-muerte-de-socrates-malaga-espana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/news.acropolis.org\/es\/"},{"@type":"ListItem","position":2,"name":"Representaci\u00f3n teatral &#8220;La muerte de S\u00f3crates&#8221; (M\u00e1laga, Espa\u00f1a)"}]},{"@type":"WebSite","@id":"https:\/\/news.acropolis.org\/es\/#website","url":"https:\/\/news.acropolis.org\/es\/","name":"Noticias de Nueva Acr\u00f3polis","description":"Actividades de la Organizaci\u00f3n Internacional Nueva Acr\u00f3polis","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/news.acropolis.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/news.acropolis.org\/es\/#\/schema\/person\/ced850172dfe4e556569b56610e2183e","name":"Spain","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/ESP.png","url":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/ESP.png","contentUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/ESP.png","caption":"Spain"},"url":"https:\/\/news.acropolis.org\/es\/author\/oinaes\/"}]}},"_links":{"self":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/9742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/comments?post=9742"}],"version-history":[{"count":1,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/9742\/revisions"}],"predecessor-version":[{"id":9743,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/9742\/revisions\/9743"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/posts\/7596"}],"wp:attachment":[{"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/media?parent=9742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/categories?post=9742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/news.acropolis.org\/es\/wp-json\/wp\/v2\/tags?post=9742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}