{"id":54346,"date":"2020-11-21T07:05:57","date_gmt":"2020-11-21T06:05:57","guid":{"rendered":"https:\/\/news.acropolis.org\/?p=54346"},"modified":"2020-11-29T07:06:17","modified_gmt":"2020-11-29T06:06:17","slug":"les-journees-europeennes-du-patrimoine-a-la-cour-petral-france","status":"publish","type":"post","link":"https:\/\/news.acropolis.org\/fr\/2020\/les-journees-europeennes-du-patrimoine-a-la-cour-petral-france\/","title":{"rendered":"Les Journ\u00e9es europ\u00e9ennes du Patrimoine \u00e0 la Cour P\u00e9tral (France)"},"content":{"rendered":"<p><a href=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2020\/10\/2020-09-Journee-du-Patrimoine-Cour-Petral-v2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-54347 aligncenter\" src=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2020\/10\/2020-09-Journee-du-Patrimoine-Cour-Petral-v2-300x269.jpg\" alt=\"\" width=\"300\" height=\"269\" srcset=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2020\/10\/2020-09-Journee-du-Patrimoine-Cour-Petral-v2-300x269.jpg 300w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2020\/10\/2020-09-Journee-du-Patrimoine-Cour-Petral-v2-1024x918.jpg 1024w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2020\/10\/2020-09-Journee-du-Patrimoine-Cour-Petral-v2-768x688.jpg 768w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2020\/10\/2020-09-Journee-du-Patrimoine-Cour-Petral-v2-730x654.jpg 730w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2020\/10\/2020-09-Journee-du-Patrimoine-Cour-Petral-v2-435x390.jpg 435w, https:\/\/news.acropolis.org\/wp-content\/uploads\/2020\/10\/2020-09-Journee-du-Patrimoine-Cour-Petral-v2.jpg 1275w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Les Journ\u00e9es Europ\u00e9ennes du Patrimoine (J.E.P) ont \u00e9t\u00e9 organis\u00e9es, comme chaque ann\u00e9e, par le Minist\u00e8re de la Culture en France. Et l\u2019Ancienne Abbaye de la Cour P\u00e9tral a ouvert ses portes \u00e0 cette occasion. Cette ann\u00e9e, les JEP \u00e9taient sous le signe de \u00ab l\u2019\u00e9ducation et l\u2019apprentissage pour la vie \u00bb.<\/p>\n<p>Les nombreux visiteurs (pr\u00e8s de 200 cette ann\u00e9e) sont venus admirer la beaut\u00e9 de ses b\u00e2timents et de son cadre bucolique.<br \/>\nDes visites guid\u00e9es par des conf\u00e9renciers permettent de d\u00e9couvrir l\u2019histoire du lieu et de conna\u00eetre les projets en cours. Et une halte plus longue est propos\u00e9e \u00e0 la cit\u00e9 artisanale o\u00f9 le public est invit\u00e9 \u00e0 d\u00e9couvrir le savoir-faire artisanal et \u00e0 participer de ses mains. C\u2019est le moment favori de cette rencontre. Au d\u00e9but, tout le monde para\u00eet intimid\u00e9 par le travail de la mati\u00e8re et avec ses mains. Puis, progressivement, les mains acceptent l\u2019outil qu\u2019il sera finalement difficile de l\u00e2cher par la suite. Il se joue l\u00e0 quelque chose d\u2019ancestral entre l\u2019homme et la mati\u00e8re. Allez savoir pourquoi, en travaillant de leurs mains, grands et petits ont leurs yeux qui brillent !<\/p>\n<div class=\"wp-block-image\">\n<p>Le projet des JEP rejoint celui de Nouvelle Acropole, organisatrice de ces journ\u00e9es, par la m\u00eame conception de l\u2019\u00e9ducation et de l\u2019apprentissage \u00e0 vie, comme voie de r\u00e9g\u00e9n\u00e9ration humaine.<br \/>\n\u00ab L\u2019\u00e9ducation est un \u00e9l\u00e9ment essentiel des JEP depuis le lancement de cette initiative et elle est intimement li\u00e9e \u00e0 tout ce que nous entreprenons, que nous nous adressions \u00e0 des enfants, ou \u00e0 des adultes. Notre objectif est le m\u00eame : laisser une trace qui illustre tout le potentiel que rec\u00e8le le patrimoine en tant qu\u2019outil d\u2019apprentissage et source d\u2019inspiration pour l\u2019avenir. L\u2019ambition est de nous reconnecter aux connaissances, aux traditions, aux savoir-faire qui d\u00e9finissaient jadis notre lieu de vie, et, ce faisant, de r\u00e9inventer ce que signifie l\u2019\u00e9ducation pour le XXI\u00e8me si\u00e8cle.\u00bb<\/p>\n<p>Pour voir le reportage vid\u00e9o sur le th\u00e8me \u00ab\u00a0Patrimoine et \u00e9ducation : apprendre pour la vie\u00a0\u00bb, avec le concours des associations \u00ab\u00a0Les amis de la Cour P\u00e9tral\u00a0\u00bb, \u00ab\u00a0Nouvelle Acropole \u00ab\u00a0et \u00ab\u00a0Les ateliers d\u2019H\u00e9pha\u00efstos : https:\/\/youtu.be\/YwzebJB2rTQ<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Les Journ\u00e9es Europ\u00e9ennes du Patrimoine (J.E.P) ont \u00e9t\u00e9 organis\u00e9es, comme chaque ann\u00e9e, par le Minist\u00e8re de la Culture en France. Et l\u2019Ancienne Abbaye de la Cour P\u00e9tral a ouvert ses [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":54347,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31,28,29],"tags":[2598,2601,698,2887,4402],"class_list":["post-54346","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artistiques_artisanales","category-activites_culturelles","category-activites_educatives","tag-artisanat","tag-cour-petral","tag-culture-fr","tag-france","tag-journees-europeennes-du-patrimoine","clearfix"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les Journ\u00e9es europ\u00e9ennes du Patrimoine \u00e0 la Cour P\u00e9tral (France) - Nouvelles des Activit\u00e9s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/news.acropolis.org\/fr\/2020\/les-journees-europeennes-du-patrimoine-a-la-cour-petral-france\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Les Journ\u00e9es europ\u00e9ennes du Patrimoine \u00e0 la Cour P\u00e9tral (France) - Nouvelles des Activit\u00e9s\" \/>\n<meta name=\"twitter:description\" content=\"Les Journ\u00e9es Europ\u00e9ennes du Patrimoine (J.E.P) ont \u00e9t\u00e9 organis\u00e9es, comme chaque ann\u00e9e, par le Minist\u00e8re de la Culture en France. Et l\u2019Ancienne Abbaye de la Cour P\u00e9tral a ouvert ses [&hellip;]\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/news.acropolis.org\/wp-content\/uploads\/2020\/10\/2020-09-Journee-du-Patrimoine-Cour-Petral-v2.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"France\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/fr\\\/2020\\\/les-journees-europeennes-du-patrimoine-a-la-cour-petral-france\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/fr\\\/2020\\\/les-journees-europeennes-du-patrimoine-a-la-cour-petral-france\\\/\"},\"author\":{\"name\":\"France\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/fr\\\/#\\\/schema\\\/person\\\/c835cfdc299fe61027b215fef932cd3c\"},\"headline\":\"Les Journ\u00e9es europ\u00e9ennes du Patrimoine \u00e0 la Cour P\u00e9tral (France)\",\"datePublished\":\"2020-11-21T06:05:57+00:00\",\"dateModified\":\"2020-11-29T06:06:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/fr\\\/2020\\\/les-journees-europeennes-du-patrimoine-a-la-cour-petral-france\\\/\"},\"wordCount\":404,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/fr\\\/2020\\\/les-journees-europeennes-du-patrimoine-a-la-cour-petral-france\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/2020-09-Journee-du-Patrimoine-Cour-Petral-v2.jpg\",\"keywords\":[\"Artisanat\",\"Cour P\u00e9tral\",\"culture\",\"France\",\"Journ\u00e9es europ\u00e9ennes du patrimoine\"],\"articleSection\":[\"Activit\u00e9s Artistiques et Artisanales\",\"Activit\u00e9s Culturelles\",\"Activit\u00e9s \u00c9ducatives\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/news.acropolis.org\\\/fr\\\/2020\\\/les-journees-europeennes-du-patrimoine-a-la-cour-petral-france\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/fr\\\/2020\\\/les-journees-europeennes-du-patrimoine-a-la-cour-petral-france\\\/\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/fr\\\/2020\\\/les-journees-europeennes-du-patrimoine-a-la-cour-petral-france\\\/\",\"name\":\"Les Journ\u00e9es europ\u00e9ennes du Patrimoine \u00e0 la Cour P\u00e9tral (France) - Nouvelles des Activit\u00e9s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/fr\\\/2020\\\/les-journees-europeennes-du-patrimoine-a-la-cour-petral-france\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/fr\\\/2020\\\/les-journees-europeennes-du-patrimoine-a-la-cour-petral-france\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/2020-09-Journee-du-Patrimoine-Cour-Petral-v2.jpg\",\"datePublished\":\"2020-11-21T06:05:57+00:00\",\"dateModified\":\"2020-11-29T06:06:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/fr\\\/#\\\/schema\\\/person\\\/c835cfdc299fe61027b215fef932cd3c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/fr\\\/2020\\\/les-journees-europeennes-du-patrimoine-a-la-cour-petral-france\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/news.acropolis.org\\\/fr\\\/2020\\\/les-journees-europeennes-du-patrimoine-a-la-cour-petral-france\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/fr\\\/2020\\\/les-journees-europeennes-du-patrimoine-a-la-cour-petral-france\\\/#primaryimage\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/2020-09-Journee-du-Patrimoine-Cour-Petral-v2.jpg\",\"contentUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/2020-09-Journee-du-Patrimoine-Cour-Petral-v2.jpg\",\"width\":1275,\"height\":1143},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/fr\\\/2020\\\/les-journees-europeennes-du-patrimoine-a-la-cour-petral-france\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/news.acropolis.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les Journ\u00e9es europ\u00e9ennes du Patrimoine \u00e0 la Cour P\u00e9tral (France)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/fr\\\/\",\"name\":\"Nouvelles des Activit\u00e9s\",\"description\":\"de l&#039;Organisation Internationale Nouvelle Acropole\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/news.acropolis.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/fr\\\/#\\\/schema\\\/person\\\/c835cfdc299fe61027b215fef932cd3c\",\"name\":\"France\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/FRA.png\",\"url\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/FRA.png\",\"contentUrl\":\"https:\\\/\\\/news.acropolis.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/FRA.png\",\"caption\":\"France\"},\"url\":\"https:\\\/\\\/news.acropolis.org\\\/fr\\\/author\\\/oinaf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les Journ\u00e9es europ\u00e9ennes du Patrimoine \u00e0 la Cour P\u00e9tral (France) - Nouvelles des Activit\u00e9s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/news.acropolis.org\/fr\/2020\/les-journees-europeennes-du-patrimoine-a-la-cour-petral-france\/","twitter_card":"summary_large_image","twitter_title":"Les Journ\u00e9es europ\u00e9ennes du Patrimoine \u00e0 la Cour P\u00e9tral (France) - Nouvelles des Activit\u00e9s","twitter_description":"Les Journ\u00e9es Europ\u00e9ennes du Patrimoine (J.E.P) ont \u00e9t\u00e9 organis\u00e9es, comme chaque ann\u00e9e, par le Minist\u00e8re de la Culture en France. Et l\u2019Ancienne Abbaye de la Cour P\u00e9tral a ouvert ses [&hellip;]","twitter_image":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2020\/10\/2020-09-Journee-du-Patrimoine-Cour-Petral-v2.jpg","twitter_misc":{"\u00c9crit par":"France","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/news.acropolis.org\/fr\/2020\/les-journees-europeennes-du-patrimoine-a-la-cour-petral-france\/#article","isPartOf":{"@id":"https:\/\/news.acropolis.org\/fr\/2020\/les-journees-europeennes-du-patrimoine-a-la-cour-petral-france\/"},"author":{"name":"France","@id":"https:\/\/news.acropolis.org\/fr\/#\/schema\/person\/c835cfdc299fe61027b215fef932cd3c"},"headline":"Les Journ\u00e9es europ\u00e9ennes du Patrimoine \u00e0 la Cour P\u00e9tral (France)","datePublished":"2020-11-21T06:05:57+00:00","dateModified":"2020-11-29T06:06:17+00:00","mainEntityOfPage":{"@id":"https:\/\/news.acropolis.org\/fr\/2020\/les-journees-europeennes-du-patrimoine-a-la-cour-petral-france\/"},"wordCount":404,"commentCount":0,"image":{"@id":"https:\/\/news.acropolis.org\/fr\/2020\/les-journees-europeennes-du-patrimoine-a-la-cour-petral-france\/#primaryimage"},"thumbnailUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2020\/10\/2020-09-Journee-du-Patrimoine-Cour-Petral-v2.jpg","keywords":["Artisanat","Cour P\u00e9tral","culture","France","Journ\u00e9es europ\u00e9ennes du patrimoine"],"articleSection":["Activit\u00e9s Artistiques et Artisanales","Activit\u00e9s Culturelles","Activit\u00e9s \u00c9ducatives"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/news.acropolis.org\/fr\/2020\/les-journees-europeennes-du-patrimoine-a-la-cour-petral-france\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/news.acropolis.org\/fr\/2020\/les-journees-europeennes-du-patrimoine-a-la-cour-petral-france\/","url":"https:\/\/news.acropolis.org\/fr\/2020\/les-journees-europeennes-du-patrimoine-a-la-cour-petral-france\/","name":"Les Journ\u00e9es europ\u00e9ennes du Patrimoine \u00e0 la Cour P\u00e9tral (France) - Nouvelles des Activit\u00e9s","isPartOf":{"@id":"https:\/\/news.acropolis.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/news.acropolis.org\/fr\/2020\/les-journees-europeennes-du-patrimoine-a-la-cour-petral-france\/#primaryimage"},"image":{"@id":"https:\/\/news.acropolis.org\/fr\/2020\/les-journees-europeennes-du-patrimoine-a-la-cour-petral-france\/#primaryimage"},"thumbnailUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2020\/10\/2020-09-Journee-du-Patrimoine-Cour-Petral-v2.jpg","datePublished":"2020-11-21T06:05:57+00:00","dateModified":"2020-11-29T06:06:17+00:00","author":{"@id":"https:\/\/news.acropolis.org\/fr\/#\/schema\/person\/c835cfdc299fe61027b215fef932cd3c"},"breadcrumb":{"@id":"https:\/\/news.acropolis.org\/fr\/2020\/les-journees-europeennes-du-patrimoine-a-la-cour-petral-france\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/news.acropolis.org\/fr\/2020\/les-journees-europeennes-du-patrimoine-a-la-cour-petral-france\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/news.acropolis.org\/fr\/2020\/les-journees-europeennes-du-patrimoine-a-la-cour-petral-france\/#primaryimage","url":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2020\/10\/2020-09-Journee-du-Patrimoine-Cour-Petral-v2.jpg","contentUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2020\/10\/2020-09-Journee-du-Patrimoine-Cour-Petral-v2.jpg","width":1275,"height":1143},{"@type":"BreadcrumbList","@id":"https:\/\/news.acropolis.org\/fr\/2020\/les-journees-europeennes-du-patrimoine-a-la-cour-petral-france\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/news.acropolis.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Les Journ\u00e9es europ\u00e9ennes du Patrimoine \u00e0 la Cour P\u00e9tral (France)"}]},{"@type":"WebSite","@id":"https:\/\/news.acropolis.org\/fr\/#website","url":"https:\/\/news.acropolis.org\/fr\/","name":"Nouvelles des Activit\u00e9s","description":"de l&#039;Organisation Internationale Nouvelle Acropole","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/news.acropolis.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/news.acropolis.org\/fr\/#\/schema\/person\/c835cfdc299fe61027b215fef932cd3c","name":"France","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/FRA.png","url":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/FRA.png","contentUrl":"https:\/\/news.acropolis.org\/wp-content\/uploads\/2017\/05\/FRA.png","caption":"France"},"url":"https:\/\/news.acropolis.org\/fr\/author\/oinaf\/"}]}},"_links":{"self":[{"href":"https:\/\/news.acropolis.org\/fr\/wp-json\/wp\/v2\/posts\/54346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/news.acropolis.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/news.acropolis.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/fr\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/fr\/wp-json\/wp\/v2\/comments?post=54346"}],"version-history":[{"count":2,"href":"https:\/\/news.acropolis.org\/fr\/wp-json\/wp\/v2\/posts\/54346\/revisions"}],"predecessor-version":[{"id":54351,"href":"https:\/\/news.acropolis.org\/fr\/wp-json\/wp\/v2\/posts\/54346\/revisions\/54351"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/news.acropolis.org\/fr\/wp-json\/wp\/v2\/media\/54347"}],"wp:attachment":[{"href":"https:\/\/news.acropolis.org\/fr\/wp-json\/wp\/v2\/media?parent=54346"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/news.acropolis.org\/fr\/wp-json\/wp\/v2\/categories?post=54346"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/news.acropolis.org\/fr\/wp-json\/wp\/v2\/tags?post=54346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}